{"id":190574,"date":"2026-01-01T14:06:27","date_gmt":"2026-01-01T17:06:27","guid":{"rendered":"https:\/\/www.hoymercedes.com.ar\/principal\/?page_id=190574"},"modified":"2026-05-12T15:35:22","modified_gmt":"2026-05-12T18:35:22","slug":"funebres-2026","status":"publish","type":"page","link":"https:\/\/www.hoymercedes.com.ar\/principal\/funebres-2026\/","title":{"rendered":"F\u00fanebres 2026"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">MONICA EDITH CAMUSONI DE TESSORE <\/h2>\n\n\n\n<p>Falleci\u00f3 el 12 de mayo de 2026 Su esposo Oscar Alberto Tessore, sus hijos: Gisella, Lucas, Marcos y Sof\u00eda Tessore, sus hijos pol\u00edticos: Andrea Fern\u00e1ndez, Silvina Mart\u00edn y Mat\u00edas Lofrano, sus nietos: Matilda, Catalina y Lorenzo, sus hermanos: Patricia y Jorge, sus hermanos pol\u00edticos, sus sobrinos, y dem\u00e1s deudos participan su fallecimiento e invitan a acompa\u00f1ar sus restos hasta el Cementerio Municipal el martes 12 previo responso que se oficiar\u00e1 en Iglesia San Patricio a las 17.00 hs<br>Casa velatoria: 19 y 20<br>Casa de duelo: 21 Nro 281<br>73 a\u00f1os , docente jubilada<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">ANALIA ROSANA CHIRINO <\/h2>\n\n\n\n<p>Falleci\u00f3 el 12 de mayo de 2026 Su esposo: Esteban Ra\u00fal P\u00e9rez, sus hijas Geraldine, Valentina y Emilia P\u00e9rez, sus padres: Roberto Oscar Chirino y Mar\u00eda Hayde\u00e9 Gianaschi, sus hermanos: Marcelo, Micaela, Pamela y Milagros Chirino, sus hermanos pol\u00edticos, sus sobrinos y dem\u00e1s deudos participan su fallecimiento e invitan al sepelio de sus restos que ser\u00e1n inhumados en el Cementerio Municipal el martes 12 previo responso que se oficiar\u00e1 en Iglesia San Jos\u00e9 a las 12.30 hs<br>Casa velatoria: 20 y 19 ( desde 12\/5 a las 08 hs)<br>Casa de duelo: 56 bis y 101<br>42 a\u00f1os, empleada Servicio Penitenciario<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">OSCAR MARIO VERA <\/h2>\n\n\n\n<p>Falleci\u00f3 el 9 de mayo de 2026. Sus hijas: Lidia Beatriz, Zulma Y Gladys Vera; su hijo pol\u00edtico: Efren, sus nietos y dem\u00e1s familiares participan a sus relaciones su fallecimiento y que sus restos ser\u00e1n inhumados en el Cementerio Municipal previo responso que se oficiar\u00e1 el domingo 10\/05 a las  11,30 hs en la Iglesia San Luis. Casa Velatoria: 20 y 19 (09\/05 a partir de 19,30 hs) Casa de Duelo: 3 N\u00b0 647. 90 a\u00f1os \u2013 Retirado de Gendarmeria.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">ANTONELLA LUCILA MAURIN LOPEZ <\/h2>\n\n\n\n<p>Falleci\u00f3 el dia 8 de mayo de 2026 Su hijo: Benjam\u00edn, sus padres: Rub\u00e9n Maurin Lopez y Mar\u00eda Gabriela Gradin, sus hermanos: Magal\u00ed, Valent\u00edn y Mar\u00eda Romina, su hermano pol\u00edtico: Patricio, sus sobrinos: Ezio, Emilio, Tob\u00edas, Lorenzo y Martina, sus t\u00edos, sus primos y dem\u00e1s deudos participan su fallecimiento y que sus restos ser\u00e1n inhumados en el Cementerio Parque de Mercedes el s\u00e1bado 9 de mayo de 2026 a las 10 horas previo responso oficiado en la Iglesia San Luis. Punto de encuentro Iglesia San Luis 10 hs. Casa de duelo 21 nro 728. 24 a\u00f1os&#8212; Estudiante&#8212;-nacida en Mercedes.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">GUILLERMO JOS\u00c9 FERN\u00c1NDEZ<\/h2>\n\n\n\n<p>Falleci\u00f3 el 8 de mayo de 2026 a los 53 a\u00f1os de edad. Se desempe\u00f1aba como empleado municipal. Su esposa, Karina Ortega; sus hijos, Alex, Jerem\u00edas, Naiara, Isabella y Federico; su mam\u00e1, sus hermanos y dem\u00e1s deudos participan con profundo dolor de su fallecimiento. El velatorio se llevar\u00e1 a cabo el d\u00eda 8 de mayo, de 13:00 a 16:45 horas, en la Casa Velatoria Municipal ubicada en las calles 10 entre 55 y 57. Sus restos ser\u00e1n inhumados en el cementerio local a las 17:00 horas. La casa de duelo se encuentra en la calle 25 N\u00b0 3333.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">CARLOS LUIS JOSE ASENZO <\/h2>\n\n\n\n<p>Falleci\u00f3 el 7 de mayo de 2026. Su Madre del Coraz\u00f3n: Iris Sonia Acosta y dem\u00e1s familiares participan a sus relaciones su fallecimiento y que sus restos fueron inhumados en el Cementerio Municipal previo responso que se oficiar\u00e1 a las 10,00 hs en la Iglesia San Vicente. Casa de Duelo: 101 N\u00b0 483. 60 a\u00f1os. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">MIRTA NORA RAMOS ROJAS <\/h2>\n\n\n\n<p>Falleci\u00f3 el 7 de mayo de 2026. Su pareja: Oscar Nievas, sus hijos: Nora Anahi Florido, Mar\u00eda Jos\u00e9 Florido y Alfredo Wiser; sus hijos politicos: Facundo Cardoso y   Ariel Caro; sus nietos: Bel\u00e9n, Ayrton, Mirko, Uziel y Mauricio; sus bisnietos; sus hermanos: Miguel y   Anahi Rojas y dem\u00e1s familiares participan a sus relaciones su fallecimiento y que sus restos ser\u00e1n trasladados al Crematorio del Cementerio Parque previo Responso que se oficiara a las 12,00 hs en la Iglesia San Luis. Casa Velatoria: 19 y 20. Casa de Duelo: 30 N\u00b0 3131. 68 a\u00f1os \u2013 Jubilada.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">MARIA ROSA COLOMBO de FRIAS <\/h2>\n\n\n\n<p>Falleci\u00f3 el 7 de mayo de 2026. Su esposo: Juan Jos\u00e9 Frias; sus hijos: Enzo Nahuel, Nicol\u00e1s Hernan y Mar\u00eda Soledad Frias; su madre: Irma Luisa Fusco; sus nietos: Francisco Frias y Julia Acu\u00f1a y dem\u00e1s familiares   participan a sus relaciones su fallecimiento y que sus   restos ser\u00e1n inhumados en el Cementerio Municipal previo responso que se oficiara a las 14,00 hs en la Iglesia San Luis. Casa Velatoria: 20 y 19 (a partir de las 10,00 hs) Casa de Duelo: 19 N\u00b0 881. 66 a\u00f1os \u2013 Empleada Poder Judicial.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">MIRIAM NOEMI BAL de GRASSI <\/h2>\n\n\n\n<p>Falleci\u00f3 el 5 de mayo de 2026. Su esposo: Jorge Grassi, sus hijos: Marianela, Juan Pablo y Gonzalo; sus hijos pol\u00edticos; sus nietos: Andr\u00e9s, Francisco, Justina   y Felipe; sus hermanos pol\u00edticos, sus sobrinos, primos y dem\u00e1s familiares participan a sus relaciones su   fallecimiento y que sus restos ser\u00e1n trasladados al   Crematorio del Cementerio Parque previo Responso que se oficiara a las 16,00 hs en la Iglesia San Jos\u00e9. Casa de Duelo: 29 N\u00b0 1290. 68 a\u00f1os \u2013 Jubilada. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">ROSINA MARAIA vda de ANGELUCCI<\/h2>\n\n\n\n<p>Fallecio el dia 3 de mayo de 2026 Sus hijos Antonio y Gustavo Angelucci, su hija pol\u00edtica Adriana, sus nietos Aldana, Marcos, Guadalupe, Pilar y Milagros, sus bisnietos catalina, Lupe y Salvador, sus nietos pol\u00edticos, su hermano Antonio Maraio y dem\u00e1s deudos participan su fallecimiento y que sus restos ser\u00e1n inhumados en el Cementerio de Mercedes el lunes 4 de mayo de 2026 a las 11 horas previo responso oficiado en la Iglesia San Luis.<br>Punto de encuentro Iglesia San Luis 11 hs<br>Casa de duelo 7 nro 494<br>94 a\u00f1os&#8212; jubilada&#8212;-nacida en Italia<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">RICARDO HECTOR OLIVA <\/h2>\n\n\n\n<p>Falleci\u00f3 el 2 de mayo de 2026 Su esposa Nilda Romano, sus hijos Daniela y Gabriel Oliva, su hijo politicos Pablo Galle, sus nietos Abel, Christian y Juan Pablo Galle, sus sobrinos y demas deudos participan su fallecimiento y que sus restos seran cremados en el Crematorio Cementerio Parque de Mercedes el dia Sabado 02 de Mayo de 2026  a las 17 horas. Punto de encuentro Cementerio Parque. Casa de duelo 16 nro 778. 86 a\u00f1os&#8212; jubilado&#8212;-nacido en Bs As.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">ANTONIO ALVEZ <\/h2>\n\n\n\n<p>Falleci\u00f3 el dia 30 de abril de 2026. Sus sobrinos Marcela Rodriguez y Anibal Maiorana, sus sobrinas nietas Caro, Lucre, Belu, Ema, Guada y Romi, directivos, personal y residentes del Hogar de ancianos Villa Abrille participan su fallecimiento y que sus restos ser\u00e1n inhumados en el Cementerio de Mercedes el viernes 1 de mayo de 2026 a las 10 horas previo responso oficiado en la Iglesia Catedral .-<br>Punto de encuentro Basilica Catedral 10 hs<br>casa de duelo 25 nro 370<br>81 a\u00f1os&#8212; jubilado&#8212;-nacido en Corrientes.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">LUIS ALFREDO LOPEZ<\/h2>\n\n\n\n<p>Falleci\u00f3 el dia 30 de abril de 2026 Sus hijos Liliana, Luis y Gerardo Lopez, sus hijos pol\u00edticos Hugo Avila, Rosario Gomez y Vanesa Tieso, sus nietos, sus bisnietos, sus nietos politicos, y dem\u00e1s deudos participan su fallecimiento y que sus restos seran cremados en el Crematorio Cementerio Parque de Mercedes el jueves 30 de abril de 2026 a las 16 horas previo responso oficiado en la Iglesia San Luis. <br>Casa velatoria 20 y 19 (a partir 12 hs)<br>Casa de duelo 77 N\u00b0 3266<br>69 a\u00f1os&#8212; jubilado&#8212;-nacido en CABA<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">LUIS ALBERTO SILVESTRE <\/h2>\n\n\n\n<p>Falleci\u00f3 el dia 29 de abril de 2026 Sus hijos Adriana, Javier, Marcela, Pablo, Diego, Debora y Misael Silvestre, sus hijos politicos, sus nietos, sus bisnietos, sus nietos politicos, sus hermanas Beba y Susana, su hermano politico, sus sobrinos y demas deudos participan su fallecimiento y que sus restos seran inhumados en el Cementerio de Mercedes el jueves 30 de abril de 2026  a las 12 horas. -Casa velatoria 19 y 20 a partir 08 hs. Casa de duelo 27 nro 1019. 83 a\u00f1os&#8212; jubilado&#8212;-nacida en Bs As.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">NILDA ISABEL ESPINDOLA vda. de LARA <\/h2>\n\n\n\n<p>Falleci\u00f3 el 27 de abril de 2026 Sus hijos Noemi, Daniel, Ram\u00f3n, Claudia, Pablo y Jos\u00e9 Lara, sus hijos politicos Daniel Torres, Gustavo Pedrazza, Anal\u00eda Far\u00edas, Milagros Villalba, Rosalia Diaz y Manuel Bernaule, sus nietos, sus bisnietos, sus nietos politicos, sus sobrinos y dem\u00e1s deudos participan su fallecimiento y que sus restos ser\u00e1n inhumados en el Cementerio de Mercedes el martes 28 de abril de 2026 a las 11.30 horas previo responso a oficiado en la iglesia San Luis .-<br>casa velatoria 19 y 20 a partir 07 hs<br>casa de duelo 14 e 53 y 55<br>82 a\u00f1os&#8212; jubilada&#8212;-nacida en Corrientes<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">JUAN VICENTE FERRARO <\/h2>\n\n\n\n<p>Falleci\u00f3 el dia 27 de abril de 2026 Su esposa Dora Beatriz Velez, sus hijos Julia, Emiliano y Magdalena Ferraro, su hija politica Maria Cecilia Natalicio, su nieta Regina, su hermana Marta Elena Ferraro, sus hermanos politicos, sus sobrinos y dem\u00e1s deudos participan su fallecimiento y que sus restos ser\u00e1n inhumados en el Cementerio de Mercedes el lunes 27 de abril de 2026 a las 17 horas previo responso a oficiado en la iglesia Catedral .-<br>casa velatoria 19 y 20 a partir 12 hs<br>casa de duelo 45 nro 759<br>82 a\u00f1os&#8212; jubilado&#8212;-nacido en Bs As<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">ESTER ROSA UBOLDI vda de TORRESI <\/h2>\n\n\n\n<p>Falleci\u00f3 el 24 de abril de 2026 Sus hijos: Cristina y Fabio Torresi, sus nietos: Gabriela, Marcelo, Diego, Agust\u00edn y Fiamma, sus bisnietos: Valentino y Abril, sus hermanos, sus sobrinos y dem\u00e1s deudos participan su fallecimiento y que sus restos  ser\u00e1n  inhumados en el Cementerio Municipal el s\u00e1bado 25 a las 11 hs. Casa velatoria: 20 y 19 (desde 25\/4 a las 08 hs) Casa de duelo: 22 bis entre 105 y 107. 78 a\u00f1os, jubilada.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Hermana DORA JOSEFINA PANIZZA <\/h2>\n\n\n\n<p>Falleci\u00f3 el 24 de abril de 2026. La Congregaci\u00f3n de Hermanas de San Antonio de Padua participan su fallecimiento e invitan al sepelio de sus restos que ser\u00e1n inhumados en el Cementerio Municipal previa Misa de cuerpo presente que se oficiar\u00e1 a las 15,30 hs en la Capilla de la Casa de la Sagrada Familia. Casa de Duelo: 15 N\u00b0 625.  87 a\u00f1os \u2013 Religiosa<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">DELIA ISABEL RAMIREZ <\/h2>\n\n\n\n<p>Falleci\u00f3 el 20 de abril de 2026 Sus hijos: Gloria y Patricio Lutteral, su hija pol\u00edtica: Marisa Ram\u00edrez, sus nietos: Maira, Nadia y Leo, sus bisnietos, sus hermanos, sus hermanos pol\u00edticos, sus sobrinos y dem\u00e1s deudos participan su fallecimiento y que sus restos ser\u00e1n trasladados al Crematorio del Cementerio Parque el lunes 20 previo responso que se oficiar\u00e1 en Iglesia San Luis a las 17 hs. Casa de duelo: Divina Providencia. 93 a\u00f1os, jubilada.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">INES MERCEDES ORTOLA<\/h2>\n\n\n\n<p>Falleci\u00f3 el 19 de abril de 2026. Sus hijos: Yanina y Dami\u00e1n; sus hijos pol\u00edticos: Cynthia y Mat\u00edas; sus nietos: Julia, Sof\u00eda y Elena; sus hermanos: Teresa, Hugo y Cristina, sus sobrinos y dem\u00e1s familiares participan a sus relaciones su fallecimiento y que sus restos ser\u00e1n inhumados en el Cementerio Municipal previo responso que se oficiar\u00e1 el lunes 20\/04 a las 12,30 hs en la Iglesia San Luis. Casa Velatoria: 19 y 20. Casa de Duelo: 56 N\u00b0 517. 72 a\u00f1os \u2013  Jubilada.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">ELENA RAQUEL BADANO vda de DEMATEI <\/h2>\n\n\n\n<p>Falleci\u00f3 el 19 de abril de 2026. Sus hijos: Osvaldo Raul y Cristina Elena Dematei; sus hijos pol\u00edticos: Mar\u00eda Cristina Almiron e Ignacio Repetto; sus nietos: Lucrecia Guillermina Dematei, Paula y Mat\u00edas Schelover; sus bisnietos: Tom\u00e1s, Camilo, Benjam\u00edn y Juana y dem\u00e1s familiares participan a sus relaciones su fallecimiento y que sus restos ser\u00e1n trasladados al Crematorio del Cementerio Parque previo responso que se oficiar\u00e1 a las 12,00 hs en la Iglesia San Luis.<br>Casa Velatoria: 20 y 19<br>Casa de Duelo: 3 N\u00b0 327.<br>83 a\u00f1os \u2013 Jubilada.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">CARLA VALERIA BERTOLOTTO <\/h2>\n\n\n\n<p>Falleci\u00f3 el 19 de abril de 2026. Sus hijos: Oriana y Emilio; su hermano: Roberto, sus sobrinos, primos y dem\u00e1s familiares participan a sus relaciones su fallecimiento y que sus restos ser\u00e1n trasladados al Crematorio del Cementerio Parque previo responso que se oficiar\u00e1 el lunes 20\/04 a las 10,00 hs en la Iglesia San Luis. Casa de Duelo: 36 N\u00b0 563. 62 a\u00f1os \u2013 Jubilada Docente.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">RAUL ALFREDO PEREZ <\/h2>\n\n\n\n<p>Falleci\u00f3 el 17 de abril de 2026. Su esposa: Liliana Anchuvidart, sus hijos: Raul, Ezequiel, Ger\u00f3nimo, Leticia y Alexis, sus hijos politicos, sus nietos, sus hermanas y hermanos, sus sobrinos, primos y dem\u00e1s familiares participan a sus relaciones su fallecimiento y que sus restos ser\u00e1n inhumados en el Cementerio Municipal previo Responso que se oficiar\u00e1 a las 16,00 hs en la Iglesia Cristo Rey. Casa Velatoria: 20 y 19. Casa de Duelo: 1 N\u00b0 280. 66 a\u00f1os<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">VICENTE JOSE CESTARI <\/h2>\n\n\n\n<p>Falleci\u00f3 el 17 de abril de 2026 Su esposa Maria Mercedes Sigaut, sus hijos Jorge, Nicolas, Sebastian y Jimena Cestari, sus hijos politicos, sus nietos y dem\u00e1s deudos participan su fallecimiento y que sus restos seran cremados en el Crematorio Cementerio Parque de Mercedes el s\u00e1bado 18 de abril de 2026 a las 10 horas previo responso a oficiado en la iglesia San Luis .-<br>Casa velatoria 22 nro 891<br>Casa de duelo 21 nro 3103<br>77 a\u00f1os&#8212; jubilado&#8212;-nacido en Bs As<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">NELLY ANGELA RAVELLO vda. de LABORDE <\/h2>\n\n\n\n<p>Falleci\u00f3 el 15 de abril de 2026. Sus hijos: Miguel Angel y Silvia Edith Laborde, sus hijos politicos: M\u00f3nica y Ricardo, sus nietos: Soledad, Fernanda y Maximiliano; sus bisnietos: Alma, Clarita, Ulises, Felipe y Sara y dem\u00e1s familiares participan a sus relaciones su fallecimiento y que sus restos fueron inhumados en el Cementerio Municipal previo responso que se oficiar\u00e1 el s\u00e1bado 18 de abril a las 11,30 hs en la Basilica Catedral. Casa de Duelo: 10 N\u00b0 300. 99 a\u00f1os \u2013 Jubilada.<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">MARIO CESAR RAMON NAVARRO<\/h2>\n\n\n\n<p>Falleci\u00f3 el 16 de abril de 2026. Su esposa: Norma Haydee Villa de Navarro; sus hijas: Carina Andrea y Evangelina Viviana Navarro; su hijo pol\u00edtico: Jorge Ceferino Costa; su nieta: Zaya Abigail Costa Navarro; sus hermanas y hermanos pol\u00edticos, sobrinos y dem\u00e1s familiares participan a sus relaciones su fallecimiento   y que sus restos ser\u00e1n  inhumados en el Cementerio Municipal previo Responso que se oficiara a las 15,00 hs en la Iglesia San Luis. Casa de Duelo: 18 N\u00b0 23. 85 a\u00f1os \u2013 Jubilado.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">NELLY ESTHER CALDERON vda de BLANCO<\/h2>\n\n\n\n<p>Falleci\u00f3 el 17 de abril de 2026. Sus hijos: Luis, Osvaldo, Jorge y Silvina Blanco; sus hijos pol\u00edticos: Marcela, Nora y Nancy; sus nietos: Antonella, Magali, Micaela, Magdalena y Lucas Blanco y Franco Reyes, sus bisnietos: Emilia, Anita, Victorio y Faustina; sus nietos politicos, sus hermanos: Carlos e In\u00e9s y dem\u00e1s familiares participan a sus relaciones su fallecimiento y que sus restos ser\u00e1n trasladados al Crematorio del Cementerio Parque previo responso que se oficiara a las 16,00 hs en la Iglesia San Jos\u00e9. Casa Velatoria: 19 y 20. Casa de Duelo: 56 N\u00b0 717. 83 a\u00f1os \u2013 Jubilada. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">RUBEN STEIMBRENNER<\/h2>\n\n\n\n<p>Falleci\u00f3 el d\u00eda 13 de abril de 2026. Sus hermanos: Sara Steinbrenner, Marisa Steinbrenner, Marcelo Steinbrenner, Walter Steinbrenner, Mabel Steinbrenner, Rosa Steinbrenner y dem\u00e1s familias participan su fallecimiento. Sus restos fueron llevados al Cementerio local el d\u00eda 14. 52 a\u00f1os<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">ELIDA MARIA FALABELLA vda. de PANESSI <\/h2>\n\n\n\n<p>Falleci\u00f3 el 15 de abril de 2026 Su hija : Irma Susana Panessi, su hijo pol\u00edtico: Luis Torres, sus nietas: Marisa Beatr\u00edz y Marcelo Luis Torres, sus bisnietos, sus sobrinos, sus ahijadas, y dem\u00e1s deudos participan su fallecimiento e invitan al sepelio de sus restos que ser\u00e1n inhumados en el Cementerio Municipal el jueves 16 previo responso que se oficiar\u00e1 en Iglesia San Luis a las 12 hs<br>Casa velatoria: 19 y 20 (apertura 16\/4 a las 08.30 hs)<br>Casa de duelo: 19 Nro 3044<br>98 a\u00f1os, jubilada<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">HECTOR DANIEL ALFRED  <\/h2>\n\n\n\n<p>Falleci\u00f3 el 14 de abril de 2026. Su esposa: Ana Mar\u00eda G\u00f3mez, sus hijas politicas, sus nietas Joaquin, Eloisa y Lisandro, sus hermanos, sobrinos, primos y dem\u00e1s familiares participan a sus relaciones su fallecimiento y que sus restos ser\u00e1n inhumados en el Cementerio Municipal previo responso que se oficiara a las 15,30 hs en la Iglesia San Luis. Casa de Duelo: 16 N\u00b0 344. 77 a\u00f1os \u2013 Jubilado.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">ANDREA DIANA GIMENEZ de RIVERO  <\/h2>\n\n\n\n<p>Falleci\u00f3 el 15 de abril de 2026. Su esposo: Hugo Alberto Rivero, sus hijos: Luc\u00eda, Juan Facundo y Joaquin, su hija pol\u00edtica: Mar\u00eda Clara, sus nietos: Valentino, Victoria, Carmela y Juan Andres, sus hermanos: Alejandra, Edgar (+) y Daniela, sus hermanos pol\u00edticos: Claudio, Silvina y Cristian, Juan Carlos, Silvia, Dora y Rub\u00e9n, sus sobrinos, primos y dem\u00e1s familiares participan a sus relaciones su fallecimiento y que sus restos ser\u00e1n inhumados en el Cementerio Parque previo responso que se oficiar\u00e1 a las 17,00 hs. en la Iglesia San Luis del 15 de abril. Casa Velatoria: 19 y 20 (a partir de 12,00 hs). Casa de Duelo: 37 N\u00b0 883. 64 a\u00f1os \u2013 Docente.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">ENEVELIA PALMIRA FRANCISCA MARTINET vda de HORN <\/h2>\n\n\n\n<p>Falleci\u00f3 el 12 de abril de 2026 Sus hijos Luis, Mirta, Nino, Marcelo, Maria Luj\u00e1n, Mar\u00eda de los \u00c1ngeles, Fabi\u00e1n, Javier y Mariana Horn, sus hijos pol\u00edticos, sus nietos, sus bisnietos, sus nietos pol\u00edticos, sus sobrinos y demas deudos participan su fallecimiento y que sus restos seran inhumados en el Cementerio de Mercedes el dia lunes 13 de abril de 2026  a las 11.30 horas previo responso a oficiado en la iglesia Catedral. Casa velatoria 19 y 20. Casa de duelo 43 nro 581. 93 a\u00f1os&#8212; jubilada&#8212;-nacida en Bs As<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">JULIO CESAR LIFSICHTZ <\/h2>\n\n\n\n<p>Falleci\u00f3 el 10 de abril de 2026 Su esposa: Patricia Isabel Germen, sus hijos: Federico y Marcos Lifsichtz, su nieta: Uma Lifsichtz Petavs, su hermana : Graciela, sus hermanos pol\u00edticos, sus sobrinos y dem\u00e1s deudos participan su fallecimiento y que sus restos ser\u00e1n trasladados al Crematorio del Cementerio Parque el s\u00e1bado 11 a las 10.00 hs<br>Casa de duelo: 27 Nro 770<br>87 a\u00f1os, jubiilado<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">ELSA IRENE CARDOSO vda  DEANDRES <\/h2>\n\n\n\n<p>Falleci\u00f3 el dia 9 de abril de 2026 Sus hijos Sergio, Juan Ignacio y Gustavo Deandres, sus hijas pol\u00edticas Cecilia Moner, Cecilia Contardi y Laura Sosena, sus nietos Martina, Guido, Benicio, Camila, Lucila, Tomas y Azul, su hermana politica Norma Cardoso y dem\u00e1s deudos participan su fallecimiento y que sus restos seran inhumados en el Cementerio Parque de Mercedes el viernes 10 de abril de 2026  a las 11 horas previo responso a oficiado en la iglesia San Luis. Casa velatoria 19 y 20 a partir 08 hs. Casa de duelo 28 nro 1015. 80 a\u00f1os&#8212; jubilada&#8212;-nacida en Bs As. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">MARIA ELENA ARMENDARIZ vda de PASADORE <\/h2>\n\n\n\n<p>Falleci\u00f3 el dia 8 de abril de 2026 Su nieto Hector Alan Pasadore, su bisnieto Alan Pasadore, su nieta pol\u00edtica Flavia Cane y dem\u00e1s deudos participan su fallecimiento y que sus restos fueron inhumados en el Cementerio de Mercedes jueves 9 de abril de 2026  a las 11 horas previo responso a oficiado en la iglesia San Luis. Casa velatoria 20 y 19 a partir 08 hs. Casa de duelo 55 entre 10 y 12. 90 a\u00f1os&#8212; jubilada&#8212;-nacida en Bs As.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">LILIA ELENA CASTAGNOLA vda. de ARENAS <\/h2>\n\n\n\n<p>Falleci\u00f3 el dia 8 de abril de 2026 Sus hijos Sergio y Gaston Arenas, sus hijas politicas Karina Moavro y Marisa Vignau, sus nietos Manuel, Felipe, Pedro y Camila Arenas, sus sobrinos Y demas deudos participan su fallecimiento y que sus restos seran inhumados en el Cementerio Parque de Mercedes el dia Miercoles 8  de abril de 2026  a las 16 horas previo responso  en la iglesia San Vicente de Paul. Punto de encuentro Iglesia San Vicente de Paul &#8211; 16 hs Casa de duelo 18 nro 810. 84 a\u00f1os&#8212; jubilada&#8212;-nacida en Bs As.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">MARIA LUISA JUANA TOSCAN <\/h2>\n\n\n\n<p>Falleci\u00f3 el dia 7 de abril de 2026 Su hermano Luis Toscan, sus sobrinos Belen, Israel, Lorena y Sergio y dem\u00e1s deudos participan su fallecimiento y que sus restos ser\u00e1n inhumados en el Cementerio de Mercedes el martes 7 de abril de 2026  a las 11.30 horas previo responso en la iglesia San Luis. Casa velatoria 20 y 19 Casa de duelo 8 nro 1365. 87 a\u00f1os&#8212; jubilada&#8212;-nacida en Rio Negro.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">SUSANA CATALINA ROSSELLO <\/h2>\n\n\n\n<p>Falleci\u00f3 el 5 de abril de 2026 Sus hermanas pol\u00edticas, sus sobrinos, sus sobrinos pol\u00edticos, sus sobrinos nietos, sus primos, los directivos, personal e internos  del Hogar de Ancianos Villa Abrille participan su fallecimiento  e invitan  a acompa\u00f1ar sus restos hasta el Crematorio del Cementerio Parque  el lunes 6 previo responso que se oficiar\u00e1 en Iglesia San Luis a las 09.30 hs. Casa de duelo : Hogar Ancianos Villa Abrille. 78 a\u00f1os, jubilada.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">RUBEN ANGEL GELVEZ <\/h2>\n\n\n\n<p>Falleci\u00f3 el 5 de abril de 2026 Sus hermanos: Carmen Edith y Juan Carlos Gelvez, sus hermanos pol\u00edticos: Gustavo Fern\u00e1ndez y Rosa Rodr\u00edguez, sus sobrinos: Anto, Florencia y Franco, sus sobrinas nietas: Martina y Jazm\u00edn, y dem\u00e1s deudos participan su fallecimiento e invitan al sepelio de sus restos que ser\u00e1n inhumados en el Cementerio Municipal el lunes 6 previo responso que se oficiar\u00e1 en Iglesia San Luis a las 11 hs<br>Casa velatoria: 20 y 19 ( desde 06\/4 a las 08 hs )<br>Casa de duelo: Av. Escolta y 42<br>63 a\u00f1os, nacido en Mercedes<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">MARIA DEL CARMEN GONZALEZ<\/h2>\n\n\n\n<p>Falleci\u00f3 el 5 de abril de 2026 Sus hijos: Patricio Lara, Humberto, Antonio, M\u00f3nica y Cesar Perdiguero, sus hijas pol\u00edticas: Norma Torres y Luciana Zuleta, sus nietos, sus bisnietos, sus tataranietos, sus hermanas: Ana y Teresa, sus hermanos pol\u00edticos, sus sobrinos y dem\u00e1s deudos participan su fallecimiento y que sus restos ser\u00e1n inhumados en el Cementerio Municipal el lunes 06 previo responso que se oficiar\u00e1 en Iglesia San Luis a las 12.30 hs<br>Casa velatoria: 22 N\u00b0 891 ( a partir 05\/4 20 hs)<br>Casa de duelo: 6 Nro 1478<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">JORGE ALBERTO LANEGRASSE  <\/h2>\n\n\n\n<p>Falleci\u00f3 el 5 de abril de 2026 Su esposa: Mirta Nancy Fern\u00e1ndez, sus hijos: Claudia, Mauro , Luis Alberto y Brenda Lanegrasse, sus hijos pol\u00edticos: Gustavo Pace y Ezequiel G\u00f3mez, sus nietos , sus bisnietos, sus hermanas: Liliana, Susana, Marcela, Carmen, Estela y Patricia, sus hermanos pol\u00edticos, su t\u00eda: Marta Gonzalez vda de Aranda, y dem\u00e1s deudos participan su fallecimiento y que sus restos ser\u00e1n inhumados en el Cementerio Municipal el domingo 5 previo responso que se oficiar\u00e1 en la Parroquia Cristo Rey a las 12.15 hs. Casa velatoria: 20 y 19. Casa de duelo: Avenida Escolta Nro 966. 69 a\u00f1os, jubilado.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">JORGE OMAR CHAPERON <\/h2>\n\n\n\n<p>Falleci\u00f3 el 4 de abril de 2026 Su esposa: Estela Sonia Castro,Sus hijas: Karen y Eliana y dem\u00e1s deudos participan su fallecimiento y que sus restos ser\u00e1n trasladados al Crematorio del Cementerio Parque el s\u00e1bado 4 previo responso que se oficiar\u00e1  en la Bas\u00edlica Catedral a las 15 hs. Casa velatoria: 37 Nro 320. Casa de duelo: 55  Nro 216. 59 a\u00f1os, cocinero, nacido en Mercedes.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">PASCUAL PARROTTA  <\/h2>\n\n\n\n<p>Falleci\u00f3 el 4 de abril de 2026 Su esposa: Mar\u00eda  Amalia Airoldi, su hijo: Marcelo Eduardo Parrotta, su hija pol\u00edtica: Mariana De Lucca, su nieto: Gennaro Parrotta, su hermano: Eduardo Parrotta, sus hermana pol\u00edticas: Miriam Arzani y Graciela Cunninghan, sus sobrinos y dem\u00e1s deudos participan su fallecimiento e invitan al sepelio de sus restos que ser\u00e1n  inhumados en el Cementerio Municipal el s\u00e1bado 4 previo responso que se oficiar\u00e1 en la parroquia Cristo Rey a las 16.30 hs. Casa velatoria: 22 Nro 891. Casa de duelo: 45 Nro 692. 72 a\u00f1os, jubilado.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">GRACIELA ELISA SPITALE   <\/h2>\n\n\n\n<p>Falleci\u00f3 el 3 de abril de 2026 Su hija Natalia Laurido, su hijo pol\u00edtico: Fernando Ledesma, sus nietos: Brisa Abiga\u00edl, Kiara Ayel\u00e9n y Bianca, su hermano: Miguel Spitale y dem\u00e1s deudos participan su fallecimiento e invitan a acompa\u00f1ar sus restos hasta el Crematorio del Cementerio Parque el s\u00e1bado 4 previo responso que se oficiar\u00e1  en Iglesia San Luis a las 12.30 hs. Casa velatoria: 20 y 19 (desde 08 hs). Casa de duelo: 43 Nro 3080. 68 a\u00f1os , jubilada.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">MARIA FLORENCIA BALSATEGUI vda de RIVERO (Flora)<\/h2>\n\n\n\n<p>Falleci\u00f3 el 3 de abril de 2026 Sus hijas: Alejandra, Karina, Laura, Gabriela y Marita Rivero, sus hijos pol\u00edticos: Ruben Ferreyra, Luis Islas, Alejandro Potes, Cristian D\u00edaz y Nicolas Mauriello, sus nietos, sus bisnietos, y dem\u00e1s deudos participan su fallecimiento e invitan al sepelios de sus restos que ser\u00e1n  inhumados en el Cementerio Municipal el s\u00e1bado 4 previo responso que se oficiar\u00e1 en Iglesia Evang\u00e9lica a las 11 hs. Casa velatoria: 19 y 20 (desde 04\/04 a las 07 hs) Casa de duelo: 17 y 104 Torre 7 1ero A. 81 a\u00f1os, jubilada municipal.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">NARCISO VICTORIO GUTIERREZ  (NACHO) <\/h2>\n\n\n\n<p>Falleci\u00f3 el 3 de abril de 2026 Su esposa: Norma Esther F\u00e1brega, sus hijos: Germ\u00e1n y Leonel Gutierrez F\u00e1brega, sus nietos: Jerem\u00edas, Valent\u00edn,  Micaela y Agustina, su bisnieta: Luna, sus hermanos, sus hermanos pol\u00edticos, sus sobrinos y dem\u00e1s deudos participan su fallecimiento y que sus restos ser\u00e1n trasladados al crematorio crematorio del  Cementerio Parque el viernes 3 previo responso que se oficiar\u00e1  en Iglesia San Luis a las 16 hs. Casa de duelo: 39 Nro 36. 81 a\u00f1os, jubilado.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">MARIA MERCEDES LAGIARD vda de GRASSO  <\/h2>\n\n\n\n<p>Falleci\u00f3 el 2 de abril de 2026  Sus hijos Marcelo y Fernando Grasso, su hija pol\u00edtica: Brenda Garc\u00eda, sus nietos: Candela y Francisco, su hermano Hugo y dem\u00e1s deudos participan su fallecimiento e invitan al sepelio de sus restos que ser\u00e1n inhumados en el Cementerio Municipal el viernes 3 previo responso que se oficiar\u00e1 en Iglesia San Luis a las 10 hs. Casa velatoria: 20 y 19 (desde 03\/4 a las 08 hs) Casa de duelo: 20 Nro 227. 81 a\u00f1os, jubilada.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">HILDA ALICIA CEVA vda de MC LOUGHLIN (Chuchi)<\/h2>\n\n\n\n<p>Falleci\u00f3 el 2 de abril de 2026 Sus hijos: Patricio y Edgardo Mc Loughlin, sus hijas pol\u00edticas, sus nietas y dem\u00e1s deudos participan su fallecimiento e invitan a acompa\u00f1ar sus restos que ser\u00e1 inhumados en el Cementerio Municipal viernes 3 previo responso que se oficiar\u00e1 en Iglesia San Patricio a las 12.30 hs<br>Casa velatoria: 19 y 20 ( desde 03\/abril a las 10.30 hs )<br>Casa de duelo: Los Andes 324 Pablo Nogu\u00e9s,<br>81 a\u00f1os, jubilada<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">SUSANA BEATRIZ MOZZONE DE ROSEO <\/h2>\n\n\n\n<p>Falleci\u00f3 el 2 de abril de 2026 Su esposo: Eduardo Jos\u00e9 Roseo, sus hijos: Javier, Diego, Soledad y Luis Roseo, sus hijos pol\u00edticos: Melina Luna , Alejandra Den\u00edtolis y Germ\u00e1n Kramer, sus nietos: Candela, Agust\u00edn, Julian y Alma Roseo y Fiamma Kramer, sus hermanos, sus hermanos pol\u00edticos, sus sobrinos y dem\u00e1s deudos participan su fallecimiento e invitan al sepelio de sus restos que ser\u00e1n inhumados en el Cementerio Municipal el jueves 2 previo responso oficiado en Iglesia San Luis a las 11.30 hs. <br>Casa velatoria: 20 y 19 (desde 02\/04 a las 08.30 hs)<br>Casa de duelo: 27 Nro 1423<br>69 a\u00f1os, jubilada<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">ELENA PASSADORE vda de CALABRIA <\/h2>\n\n\n\n<p>Falleci\u00f3 el 1 de abril de 2026 Sus hijos Hector y Liliana Calabria, sus hijos pol\u00edticos Mirta Gerardi y Roberto Russo, sus nietos Soledad, Evangelina y Sofia Russo y Luciano, Patricio y Alejandro Calabria, sus bisnietos, sus nietos pol\u00edticos, sus sobrinos y dem\u00e1s deudos participan su fallecimiento y que sus restos ser\u00e1n inhumados en el Cementerio de Mercedes el jueves 2 de abril de 2026 a las 10 horas previo responso a oficiarse en la iglesia San Luis. <br>Casa velatoria 19 y 20 (a partir 8 hs)<br>Casa de duelo 91 y 4<br>94 a\u00f1os&#8212; jubilada&#8212;-nacida en Bs As<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">ANA MARIA MAUHOURAT vda de BUSTOS  <\/h2>\n\n\n\n<p>Falleci\u00f3 31 de marzo de 2026 Sus hijos: Cristhian Oscar y Alejandro Javier Bustos, sus nietos: Jazm\u00edn, Wenci, Candela, Wanda y Ariana, su bisnieto Gianmarco, sus hermanos, sus hermanos pol\u00edticos, sus sobrinos y dem\u00e1s deudos participan su fallecimiento y que sus restos ser\u00e1n trasladados al  Crematorio del Cementerio Parque el mi\u00e9rcoles 1 previo responso que se oficiar\u00e1 en Iglesia San Luis a las 11 hs. Casa de duelo: 32 Nro 325. 76 a\u00f1os, jubilada.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">ANTONIO PEDRO PRIZZI <\/h2>\n\n\n\n<p>Falleci\u00f3 el 31 de marzo de 2026. Sus hijos: Juan Antonio, Graciela Esther, Luis Eduardo y Claudio Gustavo Prizzi; sus hijos pol\u00edticos: Zulma y N\u00e9stor; sus nietos: Gustavo, Fabi\u00e1n y Mat\u00edas Sirio, Juan Ignacio, Mauricio y Lucas Prizzi; sus bisnietos, su hermana: Blanca Maria Prizzi de Boragno, su hermano pol\u00edtico, sus sobrinos, su hijo del coraz\u00f3n: Pablo Sanmartin y dem\u00e1s familiares participan a sus relaciones su fallecimiento y que sus restos ser\u00e1n inhumados en el Cementerio Municipal previo Responso que se oficiara el mi\u00e9rcoles 1 de abril a la 15,00 hs en la Iglesia San Luis. Casa de Duelo: 32 N\u00b0 786. 91 a\u00f1os \u2013 Jubilado.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">CARLOS ALBERTO SARCO <\/h2>\n\n\n\n<p>Falleci\u00f3 el 30 de marzo de 2026. Su esposa: Adriana Esther  Farias; su hija: Sofia Belen Sarco; su hijo   Pol\u00edtico: Hector David  Sotelo; sus nietas:  Alma  y   Roma  Sotelo;  sus hermanos: Patricia, Osvaldo y Oscar Gagliardi; sus sobrinos y dem\u00e1s familiares participan a sus relaciones su fallecimiento y que sus restos ser\u00e1n inhumados en el Cementerio Municipal previo responso que se oficiar\u00e1 a la 17,00 hs en la Iglesia San Luis. Casa Velatoria: 19 y 20 (a partir de 08,00 hs). Casa de Duelo: 134 y 39 N\u00b0 937. 57 a\u00f1os \u2013 Bombero Jubilado. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">ANGELA NELLY DEMATEI (Tita)   <\/h2>\n\n\n\n<p>Falleci\u00f3 el 28 de marzo de 2026. Su hija: Liliana Mabel Gil, su hijo pol\u00edtico: Jos\u00e9 Luis Amena, sus nietos: Lucas y Juli\u00e1n Amena, su bisnieto: Bosco Amena, su nieta pol\u00edtica: Berni Matheu, su hermano: Alberto Dematei, su hermana pol\u00edtica: Dora Balk, su compa\u00f1ero: Ram\u00f3n Forti y dem\u00e1s deudos participan su fallecimiento y que sus restos  fueron trasladados al Crematorio del Cementerio Parque el domingo 29 previo responso  que se oficiar\u00e1 en Iglesia San Jos\u00e9 a las 12 hs. Casa de duelo: 107 Nro 682. 87 a\u00f1os, jubilada.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">ALEJANDRO HECTOR ROMERO <\/h2>\n\n\n\n<p>Falleci\u00f3 el 28 de marzo de 2026. Su hija politica: Patricia Edith Real; sus nietos; sus hermanos, sus sobrinos y dem\u00e1s familiares participan a sus relaciones su fallecimiento y que sus restos ser\u00e1n inhumados en el Cementerio Municipal previo responso que se oficiara a las 16,00 ys en la Iglesia San Jos\u00e9.Casa de Duelo: 27 N\u00b0 57. 97 a\u00f1os \u2013 Jubilado.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">ROBERTO JUAN IBARRA <\/h2>\n\n\n\n<p>Falleci\u00f3 el 28 de marzo de 2026. Su esposa: Rosa Elsa Palacios; su hijo: Roberto Jesus Ibarra, su hija pol\u00edtica: Alicia Regina Barragan; sus nietos: Emilia, Victoria, Teo y Leon; su hijo del coraz\u00f3n: Santiago Asenzo y dem\u00e1s familiares participan a sus relaciones su fallecimiento y que sus restos ser\u00e1n inhumados en el Cementerio Municipal previo responso que se oficiara el domingo 29\/03 a la 09,30 hs en la Iglesia Cristo Rey. Casa de Duelo: 2 y 17 Monoblock B. 75 a\u00f1os \u2013 Jubilado.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Hermana JUANA MARIA GHIGLIONE <\/h2>\n\n\n\n<p>Falleci\u00f3 el 28 de marzo de 2026. La Congregaci\u00f3n de Hermanas de San Antonio de Padua participan su fallecimiento e invitan al sepelio de sus restos que ser\u00e1n inhumados en el Cementerio Municipal previa Misa de cuerpo presente que se oficiara a las 15,30 hs en la Capilla de la Casa de la Sagrada Familia. Casa de Duelo: 15 N\u00b0 625. 86 a\u00f1os \u2013 Religiosa.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">MONICA BEATRIZ LIBARES de MILLA <\/h2>\n\n\n\n<p>Falleci\u00f3 el 27 de marzo de 2026. Su esposo: Miguel Angel Milla; sus hijos: Daniel, Micaela y Eduardo; sus hijos pol\u00edticos: Facundo, Leonardo y Mar\u00eda; sus nietos, su hermano: Jos\u00e9 y dem\u00e1s familiares participan a sus relaciones su fallecimiento y que sus restos ser\u00e1n inhumados en el Cementerio Municipal previo responso que se oficiar\u00e1 el s\u00e1bado 28\/03 a la 10,00 hs en la Iglesia San Luis. Casa Velatoria: 19 y 20 (27\/03 a partir de 21,00 hs) Casa de duelo: 103 N\u00b0 345. 72 a\u00f1os \u2013 Jubilada. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">HECTOR GERONIMO LUCERO  <\/h2>\n\n\n\n<p>Falleci\u00f3 el 26 de marzo de 2026. Su esposa: Olga Ester Torres; sus hijos: Olga Margarita, M\u00f3nica Patricia y H\u00e9ctor Jos\u00e9 Lucero; sus hijos pol\u00edticos: Claudio Alberto Lescano, Juan Arismendi y Mar\u00eda de los Angeles del Campo, sus nietos, bisnietos, sobrinos, primos, y dem\u00e1s familiares participan a sus relaciones su fallecimiento y que sus restos ser\u00e1n trasladados al Crematorio del Cementerio Parque previo responso que se oficiara el viernes 27\/03 a la 14,00 hs en la Bas\u00edlica Catedral. Casa Velatoria: 19 y 20 (27\/03 a partir de 08,00 hs.). Casa de Duelo: 38 N\u00b0 1212. 79 a\u00f1os \u2013 Jubilado.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">ANA MARIA GUTIERREZ vda de DUFOURQUET (Monina) <\/h2>\n\n\n\n<p>Falleci\u00f3 el 26 de marzo de 2026. Sus hijos: Javier, Mariano y Paola; sus hijos pol\u00edticos: Amanda, Marcela y Roberto; sus nietos: Franco, Nicole, Gaspar, Mora, Simon, Tobias, Ciro, Bautista y Vicente;                                su hermana: Mar\u00eda Teresa (Mimiya), sus sobrinos y dem\u00e1s familiares participan a sus relaciones su fallecimiento y que sus restos ser\u00e1n trasladados al Crematorio del Cementerio Parque previo responso que se oficiar\u00e1 a la 17,00 hs en la Iglesia San Patricio. Casa Velatoria: 19 y 20 (a partir de 14,00 hs). Casa de Duelo: 29 N\u00b0 309. 85 a\u00f1os \u2013 Jubilada.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">JOSE LUIS MAGALLAN<\/h2>\n\n\n\n<p>Falleci\u00f3 el 25 de marzo de 2026. Sus uijos: Jos\u00e9 Luis y Elsa Beatriz Gim\u00e9nez de Rossello, sus nietos, bisnietos, sobrinos, primos, y dem\u00e1s familiares participan a sus relaciones su fallecimiento y que sus restos ser\u00e1n inhumados en el Cementerio Municipal previo responso que se oficiar\u00e1 a la 17,00 hs en la Iglesia San Jos\u00e9. Casa Velatoria: 20 y 19. Casa de Duelo: 19 N\u00b0 1355. 85 a\u00f1os \u2013 Jubilado.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">EDUARDO RAFAEL MARTINELLI <\/h2>\n\n\n\n<p>Falleci\u00f3 el 23 de marzo de 2026. Su esposa: Juana Rosa Kesseler; sus hijos: Debora Anabel y Leonardo Ivan Martinelli; sus hijos pol\u00edticos: Mar\u00eda Betania y Ariel Santiago, sus hermanos, hermanos pol\u00edticos; sobrinos, primos, amigos y dem\u00e1s familiares participan a sus relaciones su fallecimiento y que sus restos ser\u00e1n trasladados al Crematorio del Cementerio Parque previa Misa que se oficiara a la 17,00 hs en la Basilica Catedral. Casa de Duelo: 19 N\u00b0 3340. 70 a\u00f1os \u2013 Jubilado.<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">NESTOR AVELINO DOVA <\/h2>\n\n\n\n<p>Falleci\u00f3 el dia 22 de marzo de 2026 Su esposa M\u00f3nica Graciela Merialdo, sus hijos Natalia, Mat\u00edas y Luciano Dova, su hijo pol\u00edtico Miguel M\u00f3naco, su nieto Bruno Priano, sus hermanos Mabel y Luis Dova, sus hermanos pol\u00edticos, sus sobrinos y dem\u00e1s deudos participan su fallecimiento y que sus restos ser\u00e1n inhumados en el Cementerio de Mercedes el lunes 23 de marzo de 2026 a las 12.30 horas previo responso a oficiarse en la iglesia San Luis .-<br>Casa velatoria 19 y 20 a partir 08 hs<br>casa de duelo 1 nro 74<br>73 a\u00f1os&#8212; Periodista Deportivo &#8211; Jubilado&#8212;-nacido en Bs As<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">OFELIA NELIDA DELL ACUA<\/h2>\n\n\n\n<p>Falleci\u00f3 el dia 22 de marzo de 2026 Su hija Mar\u00eda Celina Adano, su hijo pol\u00edtico Sebasti\u00e1n Alberto Ricca, sus nietas Mar\u00eda Valentina, Mar\u00eda Chiara y Mar\u00eda Emilia Ricca, sus hermanas, sus hermanos pol\u00edticos, sus sobrinos, y dem\u00e1s deudos participan su fallecimiento y que sus restos ser\u00e1n inhumados en el Cementerio de Mercedes el dia lunes 23 de marzo de 2026 a las 11 horas previo responso a oficiarse en la iglesia San Patricio .-<br>Punto de encuentro Iglesia San Patricio 11 hs<br>casa de duelo 27 nro 65<br>94 a\u00f1os&#8212; jubilada&#8212;-nacida en Bs As<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">DORA ALICIA QUINTANA (Hermana Patricia) <\/h2>\n\n\n\n<p>Falleci\u00f3 el 22 de marzo de 2026 La Comunidad Religiosa Hermanas de la Divina Providencia participa su fallecimiento y que sus restos fueron inhumados en el Cementerio de Mercedes el domingo 22 de Marzo de 2026 a las 18 horas previa misa a oficiarse en la Capilla de la Divina Providencia. Casa Mortuoria 32 nro 562<br>casa de duelo 32 nro 562<br>88 a\u00f1os&#8212; Religiosa&#8212;-nacida en Entre Rios<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">ANA MARIA QUIROGA vda de SCHENONE <\/h2>\n\n\n\n<p>Falleci\u00f3 el 21 de marzo de 2026 Sus hijas Andrea y Paola Schenone, sus nietos, sus bisnietos, sus nietos pol\u00edticos, sus hermanos, sus hermanos pol\u00edticos, sus sobrinos y dem\u00e1s deudos participan su fallecimiento y que sus restos fueron inhumados en el Cementerio de Mercedes el s\u00e1bado 21 de marzo de 2026 a las 17.30 horas previo responso oficiado en la Iglesia San Luis. Casa de duelo 47 nro 521<br>77 a\u00f1os&#8212; jubilada&#8212;-nacida en Bs As.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">JUAN JOS\u00c9 RODRIGUEZ <\/h2>\n\n\n\n<p>Falleci\u00f3 el dia 20 de marzo de 2026. Directivos, personal y residentes de Hogar de Anciano Villa Abrille participan su fallecimiento y que sus restos fueron inhumados en el Cementerio de Mercedes el s\u00e1bado 21 de marzo de 2026 a las 10.30 horas .-<br>Casa de duelo 25 nro 370<br>84 a\u00f1os&#8212; jubilado&#8212;-nacido en Bs As<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">GLADYS MERCEDES FERRERO vda. de LINCUIZ <\/h2>\n\n\n\n<p>Falleci\u00f3 el dia 18 de marzo de 2026 Sus hijos Zulma y Marcelo Lincuiz, sus hijos pol\u00edticos Juan Antonio Prizzi y Stella Maris Ledesma, sus nietos Juan Ignacio, Mauricio y Lucas Prizzi y Agust\u00edn, Federico y Ludmila Lincuiz, sus bisnietos, sus nietos pol\u00edticos, sus sobrinos y dem\u00e1s deudos participan su fallecimiento y que sus restos ser\u00e1n inhumados en el Cementerio de Mercedes el miercoles 18 de marzo de 2026 a las 16 horas previo responso oficiado en la Iglesia San Luis. <br>Punto de encuentro Iglesia San Luis<br>casa de duelo 37 nro 3341<br>88 a\u00f1os&#8212; jubilada&#8212;-nacido en Santa Fe<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">RAFAEL NICOLAS TABORDA <\/h2>\n\n\n\n<p>Falleci\u00f3 el dia 14 de marzo de 2026 Sus hijos Hern\u00e1n y Anal\u00eda Taborda, sus hijos pol\u00edticos Andrea Iberti y Jos\u00e9 Luis Caceres, sus nietos Helena Taborda y Thiago, Clemente y Amparo Caceres, sus hermanos politicos, sus sobrinos y dem\u00e1s deudos participan su fallecimiento y que sus restos ser\u00e1n inhumados en el Cementerio de Mercedes el martes 17 de marzo de 2026 a las 16 horas previo responso oficiado en la Iglesia San Luis .-<br>Casa velatoria 19 y 20 a partir 11 hs<br>Casa de duelo 16 nro 156<br>86 a\u00f1os&#8212; jubilado Servicio Penitenciario&#8212;-nacido en Bs As<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">VENANCIO DOMINGUEZ <\/h2>\n\n\n\n<p>Falleci\u00f3 el dia 17 de marzo de 2026 Sus hijos Venancio y Blanca Dominguez, su hija pol\u00edtica Mariana Pascuale, sus nietos Jeremias, Florencia, Diego, Marcelo, Evangelina y Cristian, sus bisnietos, sus nietos pol\u00edticos, sus hermanos, sus hermanos pol\u00edticos, sus sobrinos y dem\u00e1s deudos participan su fallecimiento y que sus restos ser\u00e1n cremados en el Crematorio Cementerio Parque de Mercedes el martes 17 de marzo de 2026 a las 11 horas previo responso oficiado en la Iglesia San Luis. <br>Punto de encuentro Iglesia San Luis 11.30 hs<br>Casa de duelo 104 nro 229<br>91 a\u00f1os&#8212; jubilado&#8212;-nacido en Espa\u00f1a<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">JUAN ALBERTO NAVARRETE <\/h2>\n\n\n\n<p>Falleci\u00f3 el 15 de marzo de 2026. Su esposa: Elsa Mabel Apa; sus hijos: Alberto y Fabian; sus hijas pol\u00edticas: Luciana y Paola; sus nietos: Candela,   Julieta, Nicol\u00e1s, Nazarena e Isabella; sus hermanos y dem\u00e1s familiares participan a sus relaciones su fallecimiento y que sus restos ser\u00e1n trasladados al Crematorio del Cementerio Parque previo responso que se oficiar\u00e1 a la 12,00 hs en la Iglesia San Jos\u00e9. Casa Velatoria: 19 y 20 (lunes 16\/03 a partir). Casa de Duelo: 17 N\u00b0 15. 76 a\u00f1os \u2013 Jubilado. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">MIGUEL ANGEL CAPUTO (Papo)<\/h2>\n\n\n\n<p>Falleci\u00f3 el dia 14 de marzo de 2026 Su hija Silvia Caputo, su hijo pol\u00edtico Marcos Cosmelli, sus nietos Valentina y Mateo, su hermano Jorge Caputo, sus hermanos pol\u00edticos, sus sobrinos y dem\u00e1s deudos participan su fallecimiento y que sus restos ser\u00e1n cremados en el Crematorio Cementerio Parque de Mercedes el s\u00e1bado 14 de marzo de 2026  a las 16 horas. Punto de encuentro Crematorio Cementerio Parque. Casa de duelo 26 bis 103 y 105 Nro 3138. 80 a\u00f1os&#8212; jubilado&#8212;-nacido en Bs As.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">HECTOR ALBERTO ROMERO<\/h2>\n\n\n\n<p> Falleci\u00f3 el 13 de marzo de 2026. Su esposa: Patricia Edith Real; sus hijos: Octavio y Gabriel Romero, Gonzalo Lopez; su padre: Alejandro Hector Romero y dem\u00e1s familiares participan a sus relaciones su fallecimiento y que sus restos ser\u00e1n trasladados al crematorio del Cementerio Parque previo responso que se oficiar\u00e1 a la 12,00 hs en la Iglesia San Jos\u00e9. Punto de encuentro: Iglesia San Jos\u00e9. Casa de Duelo: 41 N\u00b0 3074. 63 a\u00f1os <\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">ROBERTO NICOLAS DE CHICO <\/h2>\n\n\n\n<p>Falleci\u00f3 el dia 13 de marzo de 2026. Su esposa Evangelina Russi, sus hijos Tiara y Jerem\u00edas De Chico, su hija pol\u00edtica Irupe Chaves, su madre Rosa Benitez, sus padres pol\u00edticos Antonio Russi y Rosa Ben\u00edtez, su nieta Gaia, sus hermanos Walter, Marcelo, Oscar y Andrea De Chico, sus hermanos politicos, sus sobrinos Sus primos y dem\u00e1s deudos participan su fallecimiento y que sus restos seran inhumados en el Cementerio de Mercedes el s\u00e1bado 14 de marzo de 2026  a las 10 horas previo responso oficiado en la Iglesia San Luis  Casa velatoria 37 nro 320 (a partir 20 hs) Casa de duelo 57 y 18. 48 a\u00f1os&#8212; Empleado Municipal&#8212;-nacido en Bs As.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">BEATRIZ GLADYS   POLLERO vda de GARRO<\/h2>\n\n\n\n<p>Falleci\u00f3 el 13 de marzo de 2026. Su hija: Yamila   Alvarez;   Su   Hijo   Pol\u00edtico:   Oscar   Horacio   Ferrer;   Sus Hermanas:   Amanda,   Hilda   y   Mirta;   Sus   Sobrinos,   Primos   y dem\u00e1s familiares participan a sus relaciones su fallecimiento y que sus restos ser\u00e1n inhumados en el Cementerio Parque a las 17,30 Hs.Casa Velatoria: 19 y 20 (A partir de 13,00 Hs)Casa de Duelo: 112 bis N\u00b0 669. 87 a\u00f1os \u2013 Jubilada<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">SARA ISABEL REPETTO vda de PELLI  <\/h2>\n\n\n\n<p>Falleci\u00f3 el 10 de marzo de 2026. Sus hijos: Leonardo, Sergio y Leticia Pelli, sus hijos pol\u00edticos, sus nietas: In\u00e9s y Ana Paula, sus sobrinos y dem\u00e1s deudos participan su fallecimiento  e invitan al sepelio de sus restos que ser\u00e1n  inhumados en el Cementerio Municipal el mi\u00e9rcoles 11 a las 10 hs partiendo del cortejo f\u00fanebre desde  Avenida 29 Nro 330. Casa de duelo: 30 Nro 898. 89 a\u00f1os, jubilada, nacida en San Andr\u00e9s de Giles.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">JORGE EZEQUIEL SALVO <\/h2>\n\n\n\n<p>Falleci\u00f3 el 8 de marzo de 2026 Su esposa: Maricel Pagano, sus hijos Santiago y Lautaro Salvo, su madre: Eva Elvira Perez vda de Salvo, sus padres pol\u00edticos: Jorge Pagano y Silvia Mart\u00ednez, sus hermanas: Gisela y Loana Salvo, sus hermanos pol\u00edticos, sus sobrinos, sus t\u00edos, sus primos y dem\u00e1s deudos participan su fallecimiento e invitan al sepelio de sus restos que ser\u00e1n inhumados en el Cementerio Municipal el lunes 9 previo que se oficiar\u00e1 oficiad en Iglesia San Jos\u00e9 a las 17.15 hs.<br>Casa velatoria: 19 y 20<br>Casa de duelo: 17 Nro 397<br>43 a\u00f1os, comerciante<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">RUBEN JOSE CRETELLA<\/h2>\n\n\n\n<p>Falleci\u00f3 el 9 de marzo de 2026. Sus hermanos: Hilda Maria, Niria Raquel, Juan Carlos, Mart\u00edn Orlando y Nelida Esther Cretella, sus hermanas y hermanos pol\u00edticos, sus sobrinos y dem\u00e1s familiares participan a sus relaciones su fallecimiento y que sus restos ser\u00e1n inhumados en el Cementerio Municipal previo responso que se oficiar\u00e1 a las 15 hs en la Iglesia San Jos\u00e9. Casa Velatoria: 22, 35 y 37. Casa de Duelo: 27 N\u00b0 1126. 89 a\u00f1os \u2013 Jubilado.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">MARCELO RAUL FLORES<\/h2>\n\n\n\n<p>Falleci\u00f3 el 8 de marzo de 2026. Sus hermanos: Fernando y Sergio Flores; su hermana pol\u00edtica: Sonia, sus sobrinos: Candela, Lucas y Soledad y dem\u00e1s familiares participan a sus relaciones su fallecimiento y que sus restos ser\u00e1n trasladados al Crematorio del Cementerio Parque previo responso que se oficiara el lunes 9 de marzo a las 10,00 hs en la Iglesia San Luis. Punto de Encuentro: 10,00 hs Iglesia San Luis. Casa de Duelo: 43 N\u00b0 782. 63 a\u00f1os \u2013 Jubilado.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">EDGAR MANUEL ASENZO<\/h2>\n\n\n\n<p>Falleci\u00f3 el 28 de febrero de 2026 Su esposa: Mar\u00eda Elena Macedo, sus hijos: Claudia, Guillermo, Nicol\u00e1s y Matilde (+), sus hijos pol\u00edticos: Daniel V\u00e1zquez, Silvia Angulo y Romina Tomassone, sus nietos: Agustina, Manuel, Clara, Camila, Mar\u00eda Emilia, Olivia y Charo, sus hermanos: Jorge y Mar\u00eda del Carmen, dem\u00e1s familiares y amigos participan su fallecimiento y que sus restos fueron Cremados en el Crematorio del Cementerio Parque el domingo 1 previo responso oficiado en Iglesia San Luis a las 10 hs. Casa de duelo: 22 Nro 488 5to D. 92 a\u00f1os, jubilado.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">SILVIA DORLISA ESQUIVEL DE PEREZ  <\/h2>\n\n\n\n<p>Falleci\u00f3 el 3 de marzo de 2026 Su esposo: Armando H\u00e9ctor Perez, sus hijos: Adriana, Jorge y Pablo Mart\u00ednez, sus hijas pol\u00edticas: Daniela Hurtado y Claudia Lindavist, sus nietos: Florencia, Manuel, Mart\u00edn, Facundo, Camila, Lautaro, Emiliano y Agostina, sus bisnietos: Augusto, Gianlucca, Sasha y Bruna, su hermano: H\u00e9ctor y dem\u00e1s deudos participan su fallecimiento  y que sus restos ser\u00e1n trasladados al   Crematorio del Cementerio Parque el mi\u00e9rcoles 04 previo responso que se oficiar\u00e1  en Iglesia San Jos\u00e9 a las 11.00 hs. Casa de duelo: 37 Nro 726. 89 a\u00f1os, jubilado. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">OFELIA MAGDALENA NEGRO <\/h2>\n\n\n\n<p>Falleci\u00f3 el 2 de marzo de 2026. Sus esposo: Juan Daniel Pescio, su hijo: Juan Gabriel Pescio Negro y dem\u00e1s familiares participan a sus relaciones su fallecimiento y que sus restos fueron inhumados en el Cementerio Municipal martes 03\/03 a las 9,00 hs. Casa de Duelo: 106 N\u00b0 277. 75 a\u00f1os \u2013 Jubilada.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">RAMON ANTONIO PATERNESI <\/h2>\n\n\n\n<p>Falleci\u00f3 el 2 de marzo de 2026. Sus Hijos: Felix Dario, Roberto Antonio, Ana Alejandra, Victor Hugo y Maria Evangelina Paternesi, sus nietos y dem\u00e1s familiares participan a sus relaciones su fallecimiento  y que sus restos ser\u00e1n inhumados en el Cementerio Municipal previo responso que se oficiar\u00e1 el martes 3 de marzo a las 11,30 hs en la Iglesia Cristo Rey. Casa Velatoria: calle 22 entre 35 y 37 (02\/03 a partir de 18,00 hs) Casa de Duelo: 8 N\u00b0 1240. 84 a\u00f1os \u2013 Jubilado<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">HNA CARMEN ROSA RAVASIO <\/h2>\n\n\n\n<p>Falleci\u00f3 el 2 de marzo de 2026. La comunidad   religiosa Hermanas de la Divina Providencia  participa a sus relaciones su fallecimiento y que sus   restos ser\u00e1n inhumados en el Cementerio Municipal previa Misa de cuerpo presente que se oficiar\u00e1 a las 17,00 hs. Casa de Duelo: 32 N\u00b0 562. 98 a\u00f1os \u2013 Religiosa Jubilada. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">DOMINGO ALFREDO COSEGLIA <\/h2>\n\n\n\n<p>Falleci\u00f3 el dia 2 de marzo de 2026 Su esposa Maria Cristina Ferraro, su hermana politica Elena Monica Ferraro, su sobrina Luciana Ferraro, su amigo Pablo Flores, y dem\u00e1s deudos participan su fallecimiento y que sus restos ser\u00e1n inhumados en el Cementerio de Mercedes el lunes 2 de marzo de 2026 a las 11 horas previo responso oficiado en la Iglesia San Patricio .<br>Punto de encuentro Iglesia San Patricio 11 hs<br>casa de duelo 23 nro 828<br>77 a\u00f1os&#8212; jubilado&#8212;-nacido en Italia<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">RA\u00daL N\u00c9STOR PISANI<\/h2>\n\n\n\n<p>Falleci\u00f3 el d\u00eda 1 de marzo de 2026. Su esposa: Ana Mar\u00eda Denezio, sus hijos: Mariana y Pablo, su hija pol\u00edtica: Romina, sus nietos: Agust\u00edn y Gino, su hermana: Alicia, sobrinos, sobrinos pol\u00edticos, primos y dem\u00e1s deudas participan su fallecimiento.<br>Sus restos fueron velados en 25 de Mayo N\u00b0 224, Chivilcoy, de 10 a 12.<br>Casa de duelo: Lavalle 1376, Chivilcoy<br>79 a\u00f1os<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">RAUL GUSTAVO SA\u00d1ON <\/h2>\n\n\n\n<p>Falleci\u00f3 el dia 28 de febrero de 2026 Su esposa Mar\u00eda Emilia Sanabria, sus hijos Franco y Facundo, sus hijas politicas M\u00eda y Florencia, su madre politica Emilia Lagorio, sus nietos Constanza y Uma, sus hermanos Esteban, Guillerma, Rene y Marta, sus hermanos pol\u00edticos, su t\u00eda Hermelinda, sus sobrinos, sus primnos y dem\u00e1s deudos participan su fallecimiento y que sus restos ser\u00e1n inhumados en el Cementerio de Mercedes el domingo 1\u00b0 de Marzo de 2026 a las 12.30 horas previo responso oficiado en la Iglesia San Luis .<br>casa velatoria 19 y 20<br>casa de duelo 507 e 504 y 502 Gowland<br>53 a\u00f1os&#8212; Empleado&#8212;-nacido en Chaco<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">DANIEL ANGEL POLLERO <\/h2>\n\n\n\n<p>Falleci\u00f3 el dia 27 de febrero de 2026 Su esposa Mary Maidana, sus hijos Martin, Daniela y Claudio Pollero, sus hijos politicos Santiago y Roberta, su madre Martha Jurado, sus nietos Benjamin y Amelie, su hermana Graciela Pollero, sus hermanos politicos, sus sobrinos Roberta, Ezequiel, Chingu y Joaquin, y dem\u00e1s deudos participan su fallecimiento y que sus restos seran cremados en el Crematorio Cementerio Parque de Mercedes el viernes 27 de febrero de 2026 a las 17.30 horas previo responso oficiado en la Iglesia San Luis .<br>casa velatoria 19 y 20 a partir 11 hs<br>casa de duelo 10 nro 201<br>71 a\u00f1os&#8212; jubilado&#8212;-nacido en Bs As<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">FLORENTINA RUIZ DIAZ vda de LUQUE<\/h2>\n\n\n\n<p>Falleci\u00f3 el 26 de febrero de 2026. Sus hijos Olga, Susana, Jorge, Jose, Juana y Francisco, sus hijos pol\u00edticos, sus nietos, sus bisnietos, sus nietos pol\u00edticos, sus hermanos, sus hermanos pol\u00edticos, sus sobrinos y dem\u00e1s deudos participan su fallecimiento y que sus restos seran inhumados en el Cementerio de Mercedes el jueves 26 de febrero de 2026 a las 17.30 horas .-<br>casa velatoria 19 20 a partir 13 hs<br>casa de duelo 19 y 132<br>83 a\u00f1os&#8212; jubilada&#8212;-nacida en Corrientes<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">ROBERTO LUIS BALBI <\/h2>\n\n\n\n<p>Falleci\u00f3 el 24 de febrero de 2026 Su esposa Teresita Wyse, sus hijos Lorena y Sebastian Balbi, su hija pol\u00edtica Vanesa Regalado, su madre politica Ita Massa, sus nietos Malena, Jano, Federica y Amancay, su nieto pol\u00edtico Braian, su hermana pol\u00edtica Mar\u00eda Ester Wyse, sus sobrinos y dem\u00e1s deudos participan su fallecimiento y que sus restos ser\u00e1n cremados en el Crematorio Cementerio Parque de Mercedes el mi\u00e9rcoles 25 de febrero de 2026 a las 15.30 horas previo responso oficiado en la Iglesia Cristo Rey .-<br>casa velatoria 20 y 19 a partir 13.30 hs<br>casa de duelo 7 nro 768<br>76 a\u00f1os&#8212; Retirado Policia Federal&#8212;-nacido en Bs As.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">BEATRIZ CRISTINA GALINDRE vda de DIAZ<\/h2>\n\n\n\n<p>Falleci\u00f3 el 24 de febrero de 2026. Su hija Marcela Beatriz D\u00edaz, su hijo politico Carlos Alberto Mosso, sus nietos Gast\u00f3n, Carolina, Luciana y Aylen Mosso, sus bisnietas Isabela y Lucia, sus nietos pol\u00edticos Manuel Badano, Francisco Denis y Yanina Mart\u00ednez Gauna, sus hermanos Norma, Emilia y Luis Galindre, sus hermanos pol\u00edticos, sus sobrinos y dem\u00e1s deudos participan su fallecimiento y que sus restos seran Cremados en el Crematorio Cementerio Parque de Mercedes el martes 24 de febrero de 2026 a las 18.30 horas .-<br>casa velatoria 20 y 19<br>casa de duelo 35 nro 1093<br>79 a\u00f1os&#8212; jubilado&#8212;-nacida en Bs As.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">ARMANDO FRANCISCO MONTOVIO <\/h2>\n\n\n\n<p>Falleci\u00f3 el 24 de febrero de 2026. Su esposa Carla Landaeta Becerra, sus hijos Camila, Manuel y Esteban Montovio, sus padres pol\u00edticos Carlos Landaeta Becerra y Rosa Lossino, sus nietos Segundo, Constantino y Guadalupe, sus hermanos pol\u00edticos, sus sobrinos y dem\u00e1s deudos participan su fallecimiento y que sus restos ser\u00e1n inhumados en el Cementerio de Mercedes el dia martes 24 de febrero de 2026 a las 11 horas previo responso oficiado en la Iglesia San Luis .-<br>Casa velatoria 19 y 20 a partir 9 hs<br>Casa de duelo 5 nro 211<br>68 a\u00f1os&#8212; Docente&#8212;-nacido en Bs As<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">BRAIAN OSCOIDE<\/h2>\n\n\n\n<p>Falleci\u00f3 el d\u00eda 22 de febrero de 2026. Sus padres Jorgelina Lucero y Gustavo Oscoide; su hijo Eithan Gael Oscoide; sus hermanos Maximiliano Furriol; Santino Lucero; Stefan\u00eda, Alan, Jonatan, Stephanie y Valentina Oscoide, t\u00edas, primos y dem\u00e1s deudos participan de su fallecimiento. <br>Sepelio: 24 de febrero a las 11 horas en el Cementerio local, previo Responso en Casa Velatoria Municipal<br>Casa velatoria: 10 entre 55 y 57, de 8 a 10.45<br>Casa de duelo: calle 53 entre 26 y 28<br>23 a\u00f1os, empleado<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">CLORINDA ENRIQUETA BUSCA vda de CAPOFERRI<\/h2>\n\n\n\n<p>Falleci\u00f3 el 23 de febrero de 2026 Sus hijos: Jorge y Silvia Capoferri, su hijo pol\u00edtico: Marcelo Garc\u00eda, su nieta: Francesca, sus fieles colaboradoras: Silvia, Silvia, Elba, Teresa, Marta e Hilda y dem\u00e1s deudos participan su fallecimiento e invitan a acompa\u00f1ar sus restos hasta el Crematorio del Cementerio Parque el lunes 23<br>previo responso que se oficiar\u00e1 en Iglesia San Luis ( punto de encuentro ) a las 11 hs. Casa de duelo: 43 Nro 344<br>97 a\u00f1os, jubilada<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">MARCELINO ALBERTO GOMEZ <\/h2>\n\n\n\n<p>Falleci\u00f3 el 21 de febrero de 2026 Sus hijos: Marcelo Fabi\u00e1n y Gabriela Cecilia G\u00f3mez, su hija pol\u00edtica: Nancy Noem\u00ed Segura, sus nietos: Agustina, Guadalupe, Candelaria, Paula, Francisco, Joaqu\u00edn, Lucio y Sim\u00f3n, sus bisnietos: Emilia, Faustina, Isabel y Lorenzo y dem\u00e1s deudos participan su fallecimiento y que ser\u00e1n trasladados al Crematorio del Cementerio Parque el s\u00e1bado 21 previo responso que se oficiar\u00e1 en la Iglesia San Vicente de Paul a las 17.30 hs<br>Casa velatoria: 19 y 20<br>Casa de duelo: 101 Nro 516<br>86 a\u00f1os, jubilado<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">NOEMI MU\u00d1OZ vda. de GONZ\u00c1LEZ <\/h2>\n\n\n\n<p>Falleci\u00f3 el 21 de febrero de 2026 Sus hijos: Daniel y Mercedes Gonz\u00e1lez, sus hijos pol\u00edticos: Daniel Panessi y Margarita Bertana, sus nietos: Noelia, Mariana y Florencia Panessi, Andrea, Sergio, Fernando y Mar\u00eda Gonz\u00e1lez, sus bisnietos: Roc\u00edo, Sof\u00eda, Rom\u00e1n, Santiago, Camila, Brisa y Emilia, sus nietos pol\u00edticos, su hermana: Argentina Mu\u00f1oz, y dem\u00e1s deudos participan su fallecimiento y que sus restos ser\u00e1n traslados al Crematorio del Cementerio Parque el s\u00e1bado 21 previo responso que se oficiar\u00e1 en Iglesia San Jos\u00e9 a las 16 hs<br>Casa velatoria: 20 y 19<br>Casa de duelo: Cuartel 121 Altamira<br>93 a\u00f1os, jubilada<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">CLAUDIA RENEE GODOY vda de GUANZINI <\/h2>\n\n\n\n<p>Falleci\u00f3 el 19 de febrero de 2026 Su hijo: Franco Nicol\u00e1s Guanzini Godoy, su madre: Mar\u00eda Juana Francisca Reinoso, y dem\u00e1s deudos participan su fallecimiento e invitan al sepelio de sus restos que ser\u00e1n inhumados en el Cementerio Municipal el jueves 19 previo responso que se oficiar\u00e1 en Iglesia San Jos\u00e9 a las 11.30 hs<br>Casa velatoria: 20 y 19<br>Casa de duelo: Republica de Chile Nro 23<br>62 a\u00f1os, jubilada<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">ANDREA BEATRIZ GALEOTA <\/h2>\n\n\n\n<p>Falleci\u00f3 el 18 de febrero de 2026 Su compa\u00f1ero: Luis Alberto Laurino, su hijo: Augusto Laurino Galeota, su madre del coraz\u00f3n: Miriam Gabriela Tealdi, sus hermanas: Paula, Camila y Constanza, sus sobrinos y adem\u00e1s deudos participan su fallecimiento e invitan al sepelio de sus restos que ser\u00e1n inhumados en el Cementerio Municipal el jueves 19 previo responso que se oficiar\u00e1 en la parroquia Cristo Rey a las 17 hs<br>Casa velatoria:19 y 20 (desde 19\/2 a las 13 hs)<br>Casa de duelo: 511 entre 502 y 504<br>46 a\u00f1os, empleada<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">ALICIA ESTER VERNA vda de AMUTIO <\/h2>\n\n\n\n<p>Falleci\u00f3 el 15 de febrero de 2026. Sus hijos: Gabriela y Virginia; sus hijos pol\u00edticos: Leandro y Fernando; sus nietos: Carmela, Milagros, Joaquin y Mora y dem\u00e1s familiares participan a sus relaciones su fallecimiento y que sus restos ser\u00e1n trasladados al Crematorio del Cementerio Parque el lunes 16 de febrero a las 10,00 hs. Punto de Encuentro: Cementerio Parque. Casa de Duelo: 28 N\u00b0 616. 83 a\u00f1os \u2013 Jubilada.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">MARGOT JOSEFINA LOISA vda de MENDEZ <\/h2>\n\n\n\n<p>Falleci\u00f3 el 10 de febrero de 2026. Sus hijos: Hernan Javier, Alicia Beatriz y Eduardo Esteban Felix Mendez; sus hijos politicos: Gabriela Martino, Rodolfo Alvarez y Agustina Ceresoli; sus nietos: Lautaro, Juan Mart\u00edn, Ivo, Santiago, Gonzalo, Ignacio, Estanislao y Felicitas; su hija del coraz\u00f3n: Zulma Ortiz, sus sobrinos y dem\u00e1s familiares participan a sus relaciones su fallecimiento y que sus restos ser\u00e1n trasladados al Crematorio del Cementerio Parque previo responso que se oficiar\u00e1 el mi\u00e9rcoles 11\/02 a las 10,00 hs en la Iglesia San Luis.<br>Casa de Duelo: 23 N\u00b0 928<br>86 a\u00f1os \u2013 Jubilada Docente.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">JULIO ALFREDO VILLALBA<\/h2>\n\n\n\n<p>Falleci\u00f3 el 9 de febrero de 2026. Su esposa: Elsa Antonia Borni, sus hijos: Leandro, Amorina, David y Natalia Villalba; sus hijos pol\u00edticos: Claudina, Mariano, Mar\u00eda y Mauricio; sus nietos: El\u00edas, Juan Pablo, Mateo, Francisco, Valentin y Jeremias y dem\u00e1s familiares participan a sus relaciones su fallecimiento y que sus restos seran trasladados al Cementerio Municipal previo responso que se oficiara a las 11,30 hs en la Iglesia Universal.<br>Casa Velatoria: 20 y 19 (10\/02 a partir de 08,00 hs)<br>Casa de Duelo: 8 N\u00b0 1529.<br>83 a\u00f1os \u2013 Jubilado.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">NORMA INES DAMONTE de MAURI <\/h2>\n\n\n\n<p>Falleci\u00f3 el 9 de febrero de 2026. Su esposo: Mario Hector Mauri, sus hijos: Hern\u00e1n, Daniela y Mane; sus nietos: Juli y Juani y dem\u00e1s familiares participan a sus relaciones su fallecimiento y que sus restos ser\u00e1n trasladados al Crematorio del Cementerio Parque previo responso que se oficiar\u00e1 a las 17,00 hs en la Iglesia San Luis. Casa Velatoria: 19 y 20 (10\/02 a partir de 10,00 hs.) Casa de Duelo: 24 N\u00b0 218. 80 a\u00f1os \u2013 Jubilada.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">ERNESTO ALFREDO MINON <\/h2>\n\n\n\n<p>Falleci\u00f3 el dia 7 de febrero de 2026 Su esposa Maria Beatriz Basualdo, sus hijos Karina, Jos\u00e9 y Agustin Minon, sus hijas pol\u00edticas Lucia y Soledad, sus nietos Yaro, Carmela y Pilar y demas deudos participan su fallecimiento y que sus restos seran Cremados en el Crematorio Cementerio Parque de Mercedes el dia s\u00e1bado 7 de febrero de 2026  a las 16 horas . Punto de encuentro Cementerio Parque de Mercedes 16 hs. Casa de duelo 9 nro 538. 81 a\u00f1os&#8212; jubilado&#8212;-nacido en Bs As.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">RENALDO OMAR FURRIOL<\/h2>\n\n\n\n<p>Fallecio el s\u00e1bado 7 de Febrero 2026A los 75 a\u00f1osNacido en MercedesJubilado MunicipalVelatorio de  14 a 16,30 en Casa Velatoria Municipal calle 10 \u2013 55 y 57Sus restos ser\u00e1n inhumados en el Cementerio Local el dia 7 a las 16,30 htsCasa de duelo calle 42 e\/ 17 y 19<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">MARIA DE LAS MERCEDES MANSILLA <\/h2>\n\n\n\n<p>Frayalleci\u00f3 el 6 de febrero de 2026 Su compa\u00f1ero de vida: Jorge Wetzel, sus hijos en el afecto: Jacqueline y Cristian, su madre: Othelma (Pichona) Vianello, sus hermanos: Carolina y Juan Mart\u00edn Mansilla, sus hermanos pol\u00edticos: Juan Pablo Rosales y Paola Bonici, sus sobrinos: Josefina, F\u00e1tima y Juan Segundo Rosales, y dem\u00e1s deudos participan su fallecimiento e invitan a acompa\u00f1ar sus restos hasta el Crematorio del Cementerio Parque el s\u00e1bado 7 previo responso que se oficiar\u00e1 en la Parroquia Cristo Rey a las 12.00 hs Casa velatoria: 22 Nro 891 (desde 07 \/02 a las 8 hs) Casa de duelo: 38 nro 755. 58 a\u00f1os, empleada.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">ALBERTO RIVERO <\/h2>\n\n\n\n<p>Falleci\u00f3 el d5 de febrero de 2026 Sus hijos Fernando, Jose, Daniela, Sergio y Santiago Rivero, sus hijos pol\u00edticos, sus nietos y dem\u00e1s deudos participan su fallecimiento y que sus restos seran inhumados en el Cementerio de Mercedes el jueves 5 de febrero de 2026  a las 17.30 horas previo responso oficiado en la Iglesia San Luis. Casa velatoria 20 y 19 a partir 15 hs. Casa de duelo 659 y 620. 69 a\u00f1os&#8212; jubilado &#8211; nacido en Salta. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">JORGE OMAR FARIAS <\/h2>\n\n\n\n<p>Falleci\u00f3 el 4 de febrero de 2026 Sus hijos Sebasti\u00e1n y Rodrigo Farias, su hija pol\u00edtica Natalia Su\u00e1rez, su nieto Benjam\u00edn, sus hermanos, sus hermanos pol\u00edticos, sus sobrinos y dem\u00e1s deudos participan su fallecimiento y que sus restos ser\u00e1n inhumados en el Cementerio de Mercedes el jueves 5 de febrero de 2026  a las 11.30 horas previo responso oficiado en la Iglesia San Luis. Casa velatoria 19 y 20 a partir 07 hs. Casa de duelo 59 nro 239. 72 a\u00f1os&#8212; jubilado &#8211; nacido en Bs As. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">MARIA ELVIRA BRIGIDA ROSLI vda de BIANCHI<\/h2>\n\n\n\n<p>Falleci\u00f3 el dia 2 de febrero de 2026 Su hijo Jorge Bianchi Rosli, su hija pol\u00edtica Natalia Ressia, sus hermanas Estela y Nelly, sus hermanos pol\u00edticos, sus sobrinos y dem\u00e1s deudos participan su fallecimiento y que sus restos ser\u00e1n inhumados en el Cementerio de Mercedes el martes 3 de febrero de 2026  a las 11.30 horas previo responso oficiado en la Iglesia San Patricio. Casa velatoria 19 y 20 (a partir 18 hs). Casa de duelo 15 nro 3087. 89 a\u00f1os&#8212; jubilada&#8212;-nacida en Bs As.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">DIEGO HERNAN RODAS <\/h2>\n\n\n\n<p>Falleci\u00f3 el 2 de febrero de 2026. Su esposa: Mail\u00e9n C\u00f3rdoba, sus hijos: Ian y Milo, sus padres: Fortunato Rodas y Maria Elena Oschenlaeger, sus padres pol\u00edticos: Natalia Passadore y Carlos C\u00f3rdoba, sus hermanas: Mariana y Laura, sus hermanos pol\u00edticos, y dem\u00e1s deudos participan su fallecimiento y que sus restos ser\u00e1n trasladados el lunes 2 al Crematorio del Cementerio Parque a las 17,30 hs<br>Casa de duelo: 59 Nro 156<br>36 a\u00f1os, metal\u00fargico<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">JORGELINA VERONICA SALCE <\/h2>\n\n\n\n<p>Falleci\u00f3 el 2 de febrero de 2026 Sus padres: Jorge Salce y Mar\u00eda Cristina Zacagnino, sus hermanas: Elisabet y Silvana Salce, sus hermanos pol\u00edticos: H\u00e9ctor Volpe y Claudio Juarez, sus sobrinos: Mar\u00eda Milagros, Trinidad, Angeles, Lourdes, Dar\u00edo y M\u00eda, y dem\u00e1s deudos participan su fallecimiento e invitan al sepelio de sus restos que ser\u00e1n inhumados en el Cementerio Municipal el lunes 02 previo responso que se oficiar\u00e1 en Iglesia San Luis a las 16 hs<br>Casa velatoria: 22 nro 891<br>Casa de duelo: 47 Nro 784<br>46 a\u00f1os, pensionada<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">SANTOS ALBERTO DUARTE <\/h2>\n\n\n\n<p>Falleci\u00f3 el 01 de febrero de 2026 Su pareja Vanesa Gonz\u00e1lez, sus hijos: Viviana, Javier, Gast\u00f3n, David, Soledad, Karina, Gabriel, Sof\u00eda y Mauricio, sus hijos pol\u00edticos, sus nietos y dem\u00e1s deudos participan su fallecimiento e invitan al sepelio de sus restos que ser\u00e1n inhumados en el Cementerio Municipal el lunes 02 previo responso que se oficiar\u00e1 en Iglesia San Luis a las 11.30 hs. Casa velatoria: 37 Nro 320 ( desde 02\/2 a las 07 hs ). Casa de duelo: 32 Nro 190.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">GRACIELA MABEL MARTINEZ vda de ECHAZU LEZICA <\/h2>\n\n\n\n<p>Falleci\u00f3 el 30 de enero de 2026. Sus hijos: In\u00e9s, Mercedes, Lucila, Felipe, Tom\u00e1s y Catalina; sus hijos Pol\u00edticos, sus nietos; su hermana: Estela Martinez vda de Gallo; su hermana pol\u00edtica: Lilian Romano vda de Mart\u00ednez, sus sobrinos y dem\u00e1s familiares participan a sus relaciones su fallecimiento y que sus restos ser\u00e1n trasladados al Cementerio Parque el s\u00e1bado 31 de enero a las 11,30 hs. Casa Mortuoria: 48 N\u00b0 772. 79 a\u00f1os <\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">MARIA ESTER GOMEZ DE AGUIRRE <\/h2>\n\n\n\n<p>Falleci\u00f3 el 27 de enero de 2029 Su esposo Omar Aguirre, sus hijos Oscar y Omar, sus hijas pol\u00edticas, sus nietos, sus bisnietos, sus hermanos, sus hermanos pol\u00edticos, sus sobrinos y dem\u00e1s deudos participan su fallecimiento e invitan a acompa\u00f1ar sus restos hasta el Crematorio del Cementerio Parque el mi\u00e9rcoles 28 previo responso que se oficiar\u00e1 en Iglesia San Luis a las 11 hs. Casa velatoria : 20 y 19 (desde 28\/1 a las 08 hs)<br>Casa de duelo: 26 bis Nro 3225<br>77 a\u00f1os, jubilada. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">LILA CADENA ALVAREZ y CAMILO JOEL CADENA<\/h2>\n\n\n\n<p>Fallecieron el 26 de enero de 2026. Sus familiares, amigos y dem\u00e1s allegados participan su fallecimiento e invitan al sepelio de sus restos que ser\u00e1n inhumados en el Cementerio Municipal el mi\u00e9rcoles 28 a las 17 hs. Casa velatoria: 22 Nro 891 ( apertura 28\/1 a las 07 hs). Casa de duelo: 16 Nro 113. 61 y 22 a\u00f1os de edad. Comerciantes. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">PEDRO VICENTE  LESCANO <\/h2>\n\n\n\n<p>Falleci\u00f3 el 27 de enero de 2026 Su esposa: Emilia Benedicta Altuna, sus hijos: Fabi\u00e1n, Claudio , N\u00e9stor, Alejandra y Vanesa, sus hijos pol\u00edticos, sus nietos, sus bisnietos, sus hermanos, sus hermanos pol\u00edticos, sus sobrinos y dem\u00e1s deudos participan su fallecimiento e invitan al sepelio de sus sus restosque ser\u00e1n inhumados en el Cementerio Municipal el martes 27 previo responso que se oficiar\u00e1 en Iglesia San Luis a las 11.30 hs<br>Casa velatoria: 19 y 20<br>Casa de duelo: 29 bis 1636<br>78 a\u00f1os, jubilado<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">SILVIO RODOLFO PARDO (El Sapo)<\/h2>\n\n\n\n<p>Falleci\u00f3 el d\u00eda 26 de enero de 2026. Su esposa: Ver\u00f3nica Vargas, hijos: Lautaro, F\u00e1tima, Ezequiel, Nazareno y Lionel, madre pol\u00edtica: Mar\u00eda Eva Villagra, hermanos, hermanos pol\u00edticos, sobrinos, primos y dem\u00e1s deudos participan su fallecimiento.Sepelio: sus restos ser\u00e1n inhumados en el Cementerio Municipal el martes 27, previo responso que se oficiar\u00e1 en Iglesia San Luis a las 10. Casa velatoria: 20 y 19. Casa de duelo: 131 y 58. 53 a\u00f1os, jornalero.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">JUAN DOMINGO BERARDO<\/h2>\n\n\n\n<p>Falleci\u00f3 el 26  de enero de 2026 Su esposa: Carmen Catalina Zerr, su hijo: Dar\u00edo Walter Germ\u00e1n Berardo, su hija pol\u00edtica: Mirta Baz\u00e1n, sus nietos: Agustina y Carlitos, su hermana: Beatr\u00edz Barzola, sus hermanos pol\u00edticos, sus sobrinos y dem\u00e1s deudos participan su fallecimiento ser\u00e1n trasladados al Crematorio del Cementerio Parque el lunes 26 previo responso que se oficiar\u00e1 en Iglesia San Jos\u00e9 a las 17 hs. <br>Casa velatoria: 20 y 19<br>Casa de duelo: 50 Nro 606<br>79 a\u00f1os, jubilado<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">MARIA ESTHER CARBALLO vda. de MINETTI <\/h2>\n\n\n\n<p>Falleci\u00f3 el 26 de enero de 2026 Sus hijos: Liliana Esther, Juan Carlos y Nestor Fabi\u00e1n Minetti, sus hijos pol\u00edtico: Victor Omar D\u00b4Angelo y Viviana In\u00e9s Cagnone, sus nietos: Gast\u00f3n, Nicol\u00e1s, Jonathan y Emanuel, sus bisnietos: Lorenzo y Salvador, sus nietas pol\u00edticas: Agustina, Ana Clara, Romina y Constanza, su hija del coraz\u00f3n : Beatr\u00edz Bernal, sus nieto del coraz\u00f3n: Miguel sus sobrinos y dem\u00e1s deudos participan su fallecimiento e invitan al sepelio de sus restos que ser\u00e1n inhumados en el Cementerio Parque el lunes 26 previo responso que se oficiar\u00e1 en la parroquia Cristo Rey a las 15.30 hs<br>Casa velatoria: 20 y 19<br>Casa de duelo: 5 Nro 3156<br>82 a\u00f1os, jubilada<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">HECTOR PEDRO DAGNINO <\/h2>\n\n\n\n<p>Falleci\u00f3 el 23 de enero de 2026. Su esposa: Maria Rosa Rudino; sus hijas: Yanina y Melisa Dagnino; sus hijos pol\u00edticos: Cristian y Javier; sus nietos: Bianca, Joaqu\u00edn y Franco, su hermano: Osvaldo; su hermana pol\u00edtica: Nora y dem\u00e1s familiares participan a sus relaciones su fallecimiento y que sus restos ser\u00e1n inhumados en el Cementerio Municipal previo responso que se oficiara el s\u00e1bado 24\/01 a las 10,00 hs en la Iglesia San Luis.<br>Casa Velatoria: 19 y 20 (23\/01 a partir de 18,00 hs)<br>Casa de Duelo: 29 N\u00b0 70.<br>76 a\u00f1os \u2013 Jubilado.<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">SANTIAGO METRO  <\/h2>\n\n\n\n<p>Falleci\u00f3 el 21 de enero de 2026. Sus padres, sus hermanos, su mujer, sus sobrinos y dem\u00e1s familiares participan su fallecimiento e invitan al sepelio de  sus restos que ser\u00e1n  inhumados en el Cementerio Municipal el jueves 22 previo responso  que se oficiar\u00e1 en Iglesia San Luis  (punto de encuentro) a las 17 hs. 65 a\u00f1os, jubilado.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">JULIETA ROXANA RUIZ DIAZ <\/h2>\n\n\n\n<p>Falleci\u00f3 el 19 de enero de 2026. Su pareja: Miguel \u00c1ngel Ram\u00edrez; su hija: Juanita Oliver; sus padres: Cristina Samudio y Mario Ruiz Diaz; sus hermanos: Jesica, Mario, Lautaro, Vanesa, Sofia y Cristian; sus sobrinos: Dilan, Lazaro, Sebastian, Dulce, Pilar, Mateo, Santiago, Abril, Marcos y Bastian y dem\u00e1s familiares participan a sus relaciones su fallecimiento y que sus restos seran inhumados el mi\u00e9rcoles 21 de enero en el Cementerio Parque a las 10,00 hs.<br>Casa Velatoria: 22, 35 y 37 (20\/01 a partir de 20,30 hs).<br>Casa de Duelo: 12 N\u00b0 3010.<br>34 a\u00f1os \u2013 Empleada.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">MIRTA NORMA MARQUEZ  vda de FERRARO <\/h2>\n\n\n\n<p>Falleci\u00f3 el 19 de Enero de 2026. Sus hijos: Miguel, Julio, Luis, Jorge, Rolando, Claudio, Rafael y Carlos; sus hijas pol\u00edticas: Rosa D\u00edaz, Gabriela Avila, M\u00f3nica Mart\u00edn, Anal\u00eda Montoya   y Claudia Casavalle; sus nietos, bisnietos, sus hermanos, sobrinos, primos y dem\u00e1s familiares participan a sus   relaciones su fallecimiento y que sus restos ser\u00e1n inhumados en el Cementerio Municipal previo responso que se oficio a las 10,00 hs en la Iglesia San Luis. Casa Velatoria: 19 y 20 (20\/01 a partir de 08,00 hs) Casa de Duelo: 61 e\/16 y 18. 80 a\u00f1os \u2013 Jubilada.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">AZUCENA ETHEL PERIA vda de ETCHEGONCELHAY<\/h2>\n\n\n\n<p>Falleci\u00f3 el 15 de enero de 2026 Sus hijas: Euge y Tere, su yerno: Marito, sus nietos: Coti, Delfi, Achu, Nacho, Mati y Rolo, su bisnieta: Kata y dem\u00e1s familiares y amigos participan su fallecimiento al sepelio de sus restos   que ser\u00e1n inhumados en el Cementerio Parque el viernes 16 previo responso que se oficiar\u00e1  en Bas\u00edlica Catedral (punto de encuentro) a las 16 hs. Casa de duelo: Fray Justo Santa Mar\u00eda de Oro 2904 4 A CABA. 89 a\u00f1os, jubilada docente.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">ROBERTO ALCIDES TASSARA <\/h2>\n\n\n\n<p>Falleci\u00f3 el 12 de enero de 2026. Su esposa: Iris Lady Abinal, sus hijos: Roberto, Viviana y Marcelo; Sus Hijos Pol\u00edticos: Teresa, Eduardo y Patricio; Sus Nietos: Federico, Camila, Guido, Lucas, Micaela y Renzo; Su Hermana: Matilde, Sus Sobrinos y dem\u00e1s familiares participan a sus relaciones su fallecimiento y que sus restos seran trasladados al Cementerio Parque previo responso que se oficiara a las 17,30 hs. en la Iglesia San Patricio.Casa Velatoria: 19 y 20. Casa de Duelo: 37 N\u00b0 248. 92 a\u00f1os \u2013 Jubilado. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">GABRIELA JUANA MARCHESINI vda de CUSA (Titi)<\/h2>\n\n\n\n<p>Falleci\u00f3 el 13 de enero de 2026. Sus hijos: Gabriela, Mariana y Juan Pablo; sus hijos pol\u00edticos: Jorge Luis, Rolli y Silvia; sus nietos: Facundo, Belen, Ana, Lucio y Clara, sus sobrinos, primos  y dem\u00e1s familiares participan a sus   relaciones   su   fallecimiento   y   que   sus   restos   ser\u00e1n trasladados   al   Crematorio   del   Cementerio   Parque   previo responso   que   se   oficiara  a   las   16,30   hs   en   la   Iglesia   San Patricio. Casa de Duelo: 30 N\u00b0 1043. 89 a\u00f1os \u2013 Jubilada. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">CLAUDIA SANDRA ALTUNA vda de PONCE  <\/h2>\n\n\n\n<p>Falleci\u00f3 el 10 de enero de 2026 Su compa\u00f1ero de vida : Rodolfo Testi, su hija: Roc\u00edo Bel\u00e9n Ponce, su hijo pol\u00edtico: Nicolas Uribarri, su nieto: Antonio, sus hermanos, sus hermanos pol\u00edticos, sus sobrinos y dem\u00e1s deudos participan su fallecimiento y que sus restos ser\u00e1n  trasladados al Crematorio del Cementerio Parque el domingo 11 previo responso que se oficiar\u00e1 en Iglesia San Luis a las 11,45 hs Casa velatoria: 19 y 20 (desde 11\/1 a las 07.30 hs) Casa de duelo: 31 Nro 1320. 57 a\u00f1os, pensionada.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">ANA ROSA ROMANO vda de MONACO  <\/h2>\n\n\n\n<p>Falleci\u00f3 el 7 de enero de 2026 Sus hijos Mariana, Mar\u00eda de los \u00c1ngeles y Jorge, sus nietos; Mateo, Candela, Tom\u00e1s, Nicol\u00e1s y Josefina, sus hijos pol\u00edticos: Nadia, Walter y Pablo, sus hermanos: Carlos, Mar\u00eda del Carmen e In\u00e9s, su hija del coraz\u00f3n Denise, sus sobrinos y dem\u00e1s deudos participan su fallecimiento  y que sus restos ser\u00e1n inhumados en el Cementerio Municipal el domingo 11 a las 10 hs. Casa velatoria: 20 y 19 (desde 11\/1 a las 8 hs) Casa de duelo: 9 Nro 645. 76 a\u00f1os, jubilada.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">GLADYS BEATRIZ PERTOSSI vda de GARRIDO <\/h2>\n\n\n\n<p>Falleci\u00f3 el 8 de enero de 2026 Sus hijas Marcela y Patricia, sus hijos pol\u00edticos: Horacio y Oscar, su hija del coraz\u00f3n: Ver\u00f3nica, sus nietos: Esteban, Ignacio, Diana, C\u00e9sar, Andr\u00e9s y Javier, sus bisnietos: Pilar, Mauro y Juan F\u00e9lix, y dem\u00e1s deudos participan su fallecimiento e invitan al  sepelio de sus restos que ser\u00e1n inhumados en el Cementerio Municipal el viernes 9 previo responso ques e oficiar\u00e1 en Iglesia San Luis a las 11 hs. Casa velatoria: 20 y 19 (desde 09\/01 a las 07 hs) Casa de duelo: 32 Nro 921. 89 a\u00f1os, jubilada. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">JUAN CARLOS GUTIERREZ <\/h2>\n\n\n\n<p>Falleci\u00f3 el 7 de enero de 2026 Su esposa: Ver\u00f3nica Patricia Iraola, sus hijos: Mar\u00eda, Elisabeth, Melisa, Florencia, Sof\u00eda, Lucas y Olivia, sus hijos pol\u00edticos, sus nietos, sus padres pol\u00edticos: Eduardo Iraola y Mar\u00eda del Carmen Garc\u00eda, sus hermanos: Estela, Julio y Alfredo, sus hermanos pol\u00edticos, sus sobrinos, sus primos y dem\u00e1s deudos participan su fallecimiento e invitan al sepelio de sus restos que ser\u00e1n inhumados en el Cementerio Municipal el jueves 08 previo responso que se oficiar\u00e1 en Iglesia San Luis a las 11 hs. Casa velatoria: 22 Nro 891 Casa de duelo: 4 Nro 1544. 65 a\u00f1os, jubilado.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">SARA BEATRIZ CIRILLO<\/h2>\n\n\n\n<p>Falleci\u00f3 el 6 de enero de 2026 Sus familiares y amigos participan su fallecimiento e invitan al sepelio de sus restos que ser\u00e1n inhumados en el Cementerio Municipal el martes 6 previo responso que se oficiar\u00e1 en Iglesia San Luis a las 17 hs<br>Casa velatoria: 22 Nro 891<br>Casa de duelo: 10 Nro 1230<br>78 a\u00f1os, jubilada<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">ALBERTO ANIBAL GEARTY <\/h2>\n\n\n\n<p>Falleci\u00f3 el 6 de enero de 2026 Su esposa: Mirta Beatr\u00edz Carretero, sus hijos: Mat\u00edas y Vanesa Gearty, sus hijos del coraz\u00f3n: Ignacio Ezequiel y Lucas Ivaldi, sus hijos pol\u00edticas: Gabriela Garc\u00eda Rey y Y\u00e9sica Fajardo, sus nietos, y dem\u00e1s deudos participan su fallecimiento e invitan al sepelio de sus restos que ser\u00e1n inhumados en el Cementerio Municipal el martes 6 previo responso oficiado en Iglesia San Luis ( punto de encuentro ) a las 11.00 hs<br>Casa de duelo: 24 entre 29 y 31<br>78 a\u00f1os, jubilado Banco Provincia<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">TOMAS MENDEZ <\/h2>\n\n\n\n<p>Falleci\u00f3 el 5 de enero de 2026. Su compa\u00f1era de vida: Dora Acosta, sus hijos: M\u00f3nica, C\u00e9sar, Jes\u00fas y Juan Acosta, sus hijos pol\u00edticos: Ra\u00fal Mart\u00ednez, Cristina Rey Grange, Mariela Cloke y Celeste Olgu\u00edn, sus nietos, sus bisnietos, sus tataranietos sus sobrinos y dem\u00e1s deudos participan su fallecimiento e invitan al sepelio de sus restos que ser\u00e1n inhumados en el Cementerio Municipal el lunes 05 previo responso que se oficiar\u00e1 en Iglesia San Jos\u00e9 ( punto de encuentro ) a las 16 hs<br>Casa de duelo: 58 entre 19 y 21<br>94 a\u00f1os, jubilado Policia Pcia<br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">HECTOR OSCAR POGGIO<\/h2>\n\n\n\n<p>Falleci\u00f3 el 2 de enero de 2026. Sus hijos: Walter Javier y Sergio Damian Poggio; su hija pol\u00edtica: Carolina Bisioli; sus nietos: Agustina Soler Poggio, Sofia, Lucio y Julieta Poggio y dem\u00e1s familiares participan a sus relaciones su fallecimiento y que sus restos ser\u00e1n trasladados al Crematorio del Cementerio Parque previo responso que se oficiar\u00e1 a las 16,00 hs en la Iglesia San Luis. Casa Velatoria: 20 y 19. Casa de Duelo: 312 N\u00b0 3295. 81 a\u00f1os \u2013 Jubilado.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">SANTOS SOLIVELLA<\/h2>\n\n\n\n<p>Falleci\u00f3 el 1 de enero de 2026. Su esposa: Nelva Leonor Oliva; sus hijos: Angel Marcelo y Zulma Liliana Solivella; sus nietos: Silvina, Mar\u00eda Luj\u00e1n y Diego Ramon Pascuale, Sixto y Mateo Solivella y dem\u00e1s familiares participan a sus relaciones su fallecimiento y que sus restos ser\u00e1n trasladados al Cementerio Municipal a las 11:30 hs. Casa de Duelo: 13 y 20 N\u00b0 445. 90 a\u00f1os \u2013 Jubilado.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.hoymercedes.com.ar\/principal\/funebres-2025\/#gsc.tab=0\">Avisos F\u00fanebres 2025<\/a> <\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>MONICA EDITH CAMUSONI DE TESSORE Falleci\u00f3 el 12 de mayo de 2026 Su esposo Oscar Alberto Tessore, sus hijos: Gisella, &#8230; <a title=\"F\u00fanebres 2026\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/funebres-2026\/\" aria-label=\"Leer m\u00e1s sobre F\u00fanebres 2026\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":195674,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-190574","page","type-page","status-publish","has-post-thumbnail"],"wps_subtitle":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/pages\/190574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=190574"}],"version-history":[{"count":154,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/pages\/190574\/revisions"}],"predecessor-version":[{"id":196008,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/pages\/190574\/revisions\/196008"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/195674"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=190574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}