{"id":100481,"date":"2019-09-26T20:39:26","date_gmt":"2019-09-26T23:39:26","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=100481"},"modified":"2019-09-27T23:19:49","modified_gmt":"2019-09-28T02:19:49","slug":"exitoso-torneo-de-tenis-en-la-categoria-d","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2019\/09\/26\/exitoso-torneo-de-tenis-en-la-categoria-d\/","title":{"rendered":"Exitoso torneo de tenis en la Categor\u00eda D"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Se realiz\u00f3 en la ma\u00f1ana del pasado s\u00e1bado 21 el 4to torneo interno del Calendario Anual de las Escuelas del Club Mercedes y de la Liga de Padres para la categor\u00eda \u00abD\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En las canchas de la Liga con la presencia de 34 jugadores se pudieron disputar los partidos de las zonas (donde clasificaron los 2 mejores de cada una) y los cuartos de final quedando para el pr\u00f3ximo domingo 29 las semifinales y final.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se alumnos fueron divididos en dos grupos por nivel y el rendimiento demostrado por los ni\u00f1os fue excelente, c\u00f3mo as\u00ed tambi\u00e9n el comportamiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Organizado por los directores de las escuelas los profesores Mauricio Pisoni y Hern\u00e1n Ricaldoni llevado adelante por los colaboradores Juan Manuel Regueiro y Emiliano Marcelo los ni\u00f1os pudieron disfrutar de jugar \u00e9ste hermoso deporte haciendo sus primeras experiencias en la competencia,\u00a0 adem\u00e1s de conocer y hacer amigos de otros participantes. Muy contentos todos los integrantes del equipo de profes por el nivel de los chicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\n\nLos resultados fueron los siguientes:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Categor\u00eda D-1&nbsp;<br>Zona 1<br>1- Pedro Murrie<br>2- Benicio Fusco<br>3- Bautista Ricaldoni<br>4- Lucas G\u00f3mez<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zona II<br>1- Aar\u00f3n Cazenave<br>2- Joaqu\u00edn Trevis\u00e1n<br>3- Benito Torrontegui<br>4- Justo de Marco<br>5- Bautista Alfons\u00edn<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zona III<br>1- Juan Deprati<br>2- Tiziano Meccia<br>3- Benjam\u00edn Gollo<br>4- Santino Boffi<br>5- Santiago Nincov&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zona IV<br>1- Matias R\u00e9<br>2- Luca del Giudice<br>3- Faustino Villalba<br>4- Felipe Rivero<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuartos<br>Juan Deprati a Joaqu\u00edn Trevis\u00e1n 11-8<br>Benicio Fusco a Matias R\u00e9 11-10<br>Aar\u00f3n Cazenave a Tiziano Meccia 11-9<br>Pedro Murrie a Luca del Giudice 11-5<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Categoria D-2 con 16 jugadores&nbsp;<br>Zona I<br>1- Bruno Mart\u00ednez<br>2- Juan Fernandez<br>3- Juli\u00e1n Guerrero<br>4- Gregorio Neyra<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zona II<br>1- Pedro Tipito<br>2- Manuel Cinto<br>3- Vito Maschio<br>4- Fran Ruiz<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zona III<br>1- Valentina Pucci<br>2- Joaqu\u00edn Vulponi<br>3- Fran Petiti<br>4- Matilda S\u00e1nchez<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zona IV<br>1- Bautista Portesi<br>2- Donato Cavallero<br>3- Tomas Moya<br>4- Bernardo Walsh<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuartos<br>Valentina Pucci a Manuel Cinto 11-5<br>Donato Cavallero a Bruno Martinez 11-10<br>Bautista Portesi a Juan Fern\u00e1ndez 11-7<br>Pedro Tipito a Joaqu\u00edn Vulponi 11-9<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se realiz\u00f3 en la ma\u00f1ana del pasado s\u00e1bado 21 el 4to torneo interno del Calendario Anual de las Escuelas del &#8230; <a title=\"Exitoso torneo de tenis en la Categor\u00eda D\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2019\/09\/26\/exitoso-torneo-de-tenis-en-la-categoria-d\/\" aria-label=\"Leer m\u00e1s sobre Exitoso torneo de tenis en la Categor\u00eda D\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[21],"tags":[204,6924],"class_list":["post-100481","post","type-post","status-publish","format-standard","hentry","category-deportes","tag-deportes-2","tag-tenis","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","wps_subtitle":"Tenis","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/100481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=100481"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/100481\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=100481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=100481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=100481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}