{"id":103836,"date":"2019-12-10T23:31:58","date_gmt":"2019-12-11T02:31:58","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=103836"},"modified":"2019-12-11T12:07:51","modified_gmt":"2019-12-11T15:07:51","slug":"en-la-manana-del-miercoles-juran-los-consejeros-escolares","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2019\/12\/10\/en-la-manana-del-miercoles-juran-los-consejeros-escolares\/","title":{"rendered":"En la ma\u00f1ana del mi\u00e9rcoles juran los Consejeros Escolares"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En la sesi\u00f3n preparatoria del lunes, Jos\u00e9 Luis Pisano qued\u00f3 como presidente del cuerpo, Daniel Ivaldis como Vice, Soledad Alfredo como Secretaria y Florencia Comalini a cargo de la tesorer\u00eda. En el recinto del HCD, prestar\u00e1n juramento los tres nuevos integrantes. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-attachment-id=\"103838\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2019\/12\/10\/en-la-manana-del-miercoles-juran-los-consejeros-escolares\/fb_img_15760311849121104-01-800x600\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/12\/FB_IMG_15760311849121104-01-800x600.jpeg\" data-orig-size=\"800,600\" data-comments-opened=\"0\" data-image-title=\"FB_IMG_15760311849121104-01-800&amp;#215;600\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/12\/FB_IMG_15760311849121104-01-800x600.jpeg\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/12\/FB_IMG_15760311849121104-01-800x600.jpeg\" alt=\"\" class=\"wp-image-103838\"\/><figcaption>Consejeros entrantes y salientes junto a los que siguen dos a\u00f1os m\u00e1s<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Hasta el recinto del Concejo Deliberante, se trasladar\u00e1 el cuerpo de Consejeros Escolares para tomar juramento a los tres nuevos integrantes. Jos\u00e9 Luis Pisano que renueva su cargo por cuatro a\u00f1os m\u00e1s, Florencia Comalini que integr\u00f3 la lista del Frente de Todos en segundo lugar, y Daniel Ivaldis que encabez\u00f3 la lista de Juntospor el Cambio para Consejo Escolar. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A partir de la hora 10 ser\u00e1 el acto protocolar de jura y la conformaci\u00f3n de las autoridades del cuerpo que est\u00e1 a cargo de la representaci\u00f3n local de la Direcci\u00f3n General de Cultura y Educaci\u00f3n de la provincia de Buenos Aires que desde hoy estar\u00e1 a cargo de Agustina Vila.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dif\u00edcil fue la sesi\u00f3n preparatoria del cuerpo de Consejeros Escolares. En el mismo momento que suced\u00eda la del departamento deliberativo, los detalles se conocieron despu\u00e9s narrada por sus integrantes.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-attachment-id=\"103837\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2019\/12\/10\/en-la-manana-del-miercoles-juran-los-consejeros-escolares\/fb_img_15760311922160667-01-800x600\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/12\/FB_IMG_15760311922160667-01-800x600.jpeg\" data-orig-size=\"800,600\" data-comments-opened=\"0\" data-image-title=\"FB_IMG_15760311922160667-01-800&amp;#215;600\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/12\/FB_IMG_15760311922160667-01-800x600.jpeg\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/12\/FB_IMG_15760311922160667-01-800x600.jpeg\" alt=\"\" class=\"wp-image-103837\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"> La intenci\u00f3n original era acordar todo un\u00e1nimemente para que Jos\u00e9 Luis Pisano fuese el titular del cuerpo. Pero el consejero Gustavo Freites present\u00f3 la moci\u00f3n para que sea Ivaldis, el presidente. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No obstante, tal como lo establece la ley de educaci\u00f3n, la definici\u00f3nla dio la cantidad de votos obtenido en las elecciones que para ambos fueron las de octubre pasado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> Es as\u00ed que Pisano qued\u00f3 como Presidente, Ivaldis como Vicepresidente y luego propusieron y aprobaron a Soledad Alfredo como Secretaria, cargo que viene desarrollando desde hace dos a\u00f1os, y a Florencia Comalini en la Tesorer\u00eda del cuerpo. En tanto,Freites y Agust\u00edn Bavastro ser\u00e1n vocales en el cuerpo de Consejeros Escolares. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la sesi\u00f3n preparatoria del lunes, Jos\u00e9 Luis Pisano qued\u00f3 como presidente del cuerpo, Daniel Ivaldis como Vice, Soledad Alfredo &#8230; <a title=\"En la ma\u00f1ana del mi\u00e9rcoles juran los Consejeros Escolares\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2019\/12\/10\/en-la-manana-del-miercoles-juran-los-consejeros-escolares\/\" aria-label=\"Leer m\u00e1s sobre En la ma\u00f1ana del mi\u00e9rcoles juran los Consejeros Escolares\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":103837,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[23],"tags":[1714,1317,12783],"class_list":["post-103836","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion","tag-consejeros-escolares","tag-consejo-escolar","tag-jura","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"wps_subtitle":"A partir de la hora 10","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/12\/FB_IMG_15760311922160667-01-800x600.jpeg","_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/103836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=103836"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/103836\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/103837"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=103836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=103836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=103836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}