{"id":107656,"date":"2020-03-14T23:00:39","date_gmt":"2020-03-15T02:00:39","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=107656"},"modified":"2020-03-16T19:41:41","modified_gmt":"2020-03-16T22:41:41","slug":"confirman-casos-de-coronavirus-en-lujan-y-en-chivilcoy","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2020\/03\/14\/confirman-casos-de-coronavirus-en-lujan-y-en-chivilcoy\/","title":{"rendered":"Coronavirus: Confirman casos en Luj\u00e1n y en Chivilcoy"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Durante la jornada del s\u00e1bado, los municipios de Luj\u00e1n y Chivilcoy confirmaron que los casos que sospechosos es cada una de las localidades, dieron positivo al COVID-19 (Coronavirus).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0Desde el gobierno del Municipio de Lujan informaron que se trata de un vecino de 45 a\u00f1os que hab\u00eda viajado a Estados Unidos. El mi\u00e9rcoles fue aislado en el Hospital Municipal y el jueves hab\u00eda sido trasladado a un sanatorio de Capital Federal, donde \u00abevoluciona de manera favorable\u00bb. Aseguran que por el momento no hay otros casos sospechosos en Luj\u00e1n. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tanto, en Chivilcoy, la Directora de la Regi\u00f3n Sanitaria X, Lic Carolina Di N\u00e1poli,  confirm\u00f3 y explic\u00f3 que se recibi\u00f3 el resultado del laboratorio del paciente que estuvo internado en un centro de Salud privado de dicha ciudad y fuera derivado a su lugar de residencia en Capital Federal para su tratamiento y seguimiento. En cuanto a las personas que estuvieron en contacto con el paciente, la funcionaria dijo que estar\u00e1n en \u201caislamiento total y control m\u00e9dico de evoluci\u00f3n, a cargo de los profesionales del Hospital\u201d. Adem\u00e1s, cont\u00f3 que el joven est\u00e1 con buena evoluci\u00f3n en su departamento de Capital Federal. Es el \u00fanico caso confirmado de Chivilcoy.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante la jornada del s\u00e1bado, los municipios de Luj\u00e1n y Chivilcoy confirmaron que los casos que sospechosos es cada una &#8230; <a title=\"Coronavirus: Confirman casos en Luj\u00e1n y en Chivilcoy\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2020\/03\/14\/confirman-casos-de-coronavirus-en-lujan-y-en-chivilcoy\/\" aria-label=\"Leer m\u00e1s sobre Coronavirus: Confirman casos en Luj\u00e1n y en Chivilcoy\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":107434,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[9791],"tags":[16175,9322,8703,134],"class_list":["post-107656","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud","tag-coronavirus","tag-region","tag-region-sanitaria-x","tag-salud","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2020\/03\/IMG_20200312_134134.jpg","wps_subtitle":"Informaci\u00f3n regional","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/107656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=107656"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/107656\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/107434"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=107656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=107656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=107656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}