{"id":107744,"date":"2020-03-16T14:50:34","date_gmt":"2020-03-16T17:50:34","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=107744"},"modified":"2020-03-16T19:38:41","modified_gmt":"2020-03-16T22:38:41","slug":"san-a-de-giles-confirman-caso-sospechoso-de-covid-19","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2020\/03\/16\/san-a-de-giles-confirman-caso-sospechoso-de-covid-19\/","title":{"rendered":"Coronavirus: Confirman caso sospechoso en San Andr\u00e9s de Giles"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"> En una conferencia de prensa desarrollada este mediod\u00eda, el intendente municipal confirm\u00f3 un nuevo caso sospechoso de contagio de COVID-19.  Se trata del esposo de la mujer internada el viernes con s\u00edntomas de la enfermedad. y el secretario de salud Diego Schiaffino confirm\u00f3 que no tuvieron ninguna contacto con otras personas. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"346\" data-attachment-id=\"107745\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2020\/03\/16\/san-a-de-giles-confirman-caso-sospechoso-de-covid-19\/16-giles-coronavirus\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2020\/03\/16-giles-coronavirus.jpeg\" data-orig-size=\"750,346\" data-comments-opened=\"0\" data-image-title=\"16 giles coronavirus\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2020\/03\/16-giles-coronavirus.jpeg\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2020\/03\/16-giles-coronavirus.jpeg\" alt=\"\" class=\"wp-image-107745\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abLlegaron a Ezeiza y los fueron a buscar en dos veh\u00edculos, todos ellos volvieron en uno y las personas que los fueron a buscar en el otro\u00bb. El intendente municipal tambi\u00e9n inform\u00f3 que la direcci\u00f3n de migraciones estar\u00eda por enviar informaci\u00f3n sobre vecinos que viajaron o est\u00e1n en el exterior. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El intendente informo que la atenci\u00f3n a los posibles casos de contagio, sera focalizada en un sector especial del hospital, separado de la guardia para preservar a los pacientes que se atienden en la misma. Todas las actividades municipales, talleres la pileta municipal y todos los dem\u00e1s estamentos municipales han cancelado sus actividades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El intendente tambi\u00e9n informo la puesta en funcionamiento de la linea 107 para denuncias de vecinos que no cumplan la cuarentena,\u00a0\u00abEstamos monitoreando algunos casos, recibimos algunas denuncias pero ninguna fue comprobada\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre la situaci\u00f3n del comercio. Puglielli confirmo que se ha discriminado ( de acuerdo al decreto provincial) en permitir la apertura de lugares de gastronom\u00eda pero con su capacidad reducida al cincuenta por ciento. Sobre la licencia de los empleados municipales Puglielli dijo que se est\u00e1n estudiando para empleados de mas de sesenta a\u00f1os<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: Noticias Gilenses<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En una conferencia de prensa desarrollada este mediod\u00eda, el intendente municipal confirm\u00f3 un nuevo caso sospechoso de contagio de COVID-19. &#8230; <a title=\"Coronavirus: Confirman caso sospechoso en San Andr\u00e9s de Giles\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2020\/03\/16\/san-a-de-giles-confirman-caso-sospechoso-de-covid-19\/\" aria-label=\"Leer m\u00e1s sobre Coronavirus: Confirman caso sospechoso en San Andr\u00e9s de Giles\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":107745,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[5501],"tags":[16175,16313,9322,134,2123],"class_list":["post-107744","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-region","tag-coronavirus","tag-covid-19","tag-region","tag-salud","tag-san-andres-de-giles","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2020\/03\/16-giles-coronavirus.jpeg","wps_subtitle":"Coronavirus en la regi\u00f3n","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/107744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=107744"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/107744\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/107745"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=107744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=107744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=107744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}