{"id":109205,"date":"2020-04-09T17:52:45","date_gmt":"2020-04-09T20:52:45","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=109205"},"modified":"2020-04-09T18:08:01","modified_gmt":"2020-04-09T21:08:01","slug":"coronovirus-lujan-fue-declarada-como-zona-de-circulacion-comunitaria-del-virus","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2020\/04\/09\/coronovirus-lujan-fue-declarada-como-zona-de-circulacion-comunitaria-del-virus\/","title":{"rendered":"Coronovirus: Luj\u00e1n fue declarada como zona de circulaci\u00f3n comunitaria del virus"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>En un mensaje a la comunidad, el Intendente de la Municipalidad de Luj\u00e1n, Leonardo Boto, le habl\u00f3 a la comunidad y anunci\u00f3 que profundizar\u00e1n los controles y el aislamiento social. <\/em><\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/k_3pRuhPi1s?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=es-ES&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El Intendente Municipal, Leonardo Boto, se dirigi\u00f3 una vez m\u00e1s a los lujanenses a trav\u00e9s de un video difundido en medios de comunicaci\u00f3n y redes sociales, para informar sobre las \u00faltimas novedades en relaci\u00f3n a la evoluci\u00f3n de la pandemia de Coronavirus en el distrito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Acompa\u00f1ado por la Secretaria de Salud, Mariana Gir\u00f3n, y el Director Asociado del Hospital, Diego Pagliaro, el Jefe Comunal comenz\u00f3 haciendo referencia al fallecimiento del primer lujanense v\u00edctima de Coronavirus, ocurrido este mi\u00e9rcoles en la Cl\u00ednica San Jos\u00e9, y afirm\u00f3 que \u201cse est\u00e1n llevando adelante todos los estudios epidemiol\u00f3gicos para determinar la fuente de contagio\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este sentido, comunic\u00f3 el cambio de categor\u00eda que el Ministerio de Salud de la provincia de Buenos Aires dispuso desde este jueves para todos los partidos incluidos en la Regi\u00f3n Sanitaria S\u00e9ptima. \u201cLa regi\u00f3n fue declarada zona de circulaci\u00f3n comunitaria del virus, y esto conlleva una serie de cambios en el tratamiento de esta situaci\u00f3n\u201d, se\u00f1al\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, la Secretaria de Salud explic\u00f3 que la modificaci\u00f3n de categor\u00eda \u201cnos obliga a entrar en una nueva fase en el tratamiento de esta contingencia y ajustar el protocolo de actuaci\u00f3n por el cual todos los pacientes con sintomatolog\u00eda respiratoria y fiebre van a ser abordados como sospechosos de COVID-19 hasta que<br>se descarte por laboratorio esa patolog\u00eda\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tanto, el Director del Hospital indic\u00f3 que en el centro sanitario \u201cel protocolo est\u00e1 en funcionamiento desde hace varios d\u00edas, pero vamos a reforzar el triage de entrada. Todo paciente febril va a ser derivado al sector para atenci\u00f3n de paciente febriles\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, el Intendente asegur\u00f3 que, \u201cante esta nueva situaci\u00f3n, vamos a insistir mucho con el aislamiento social, por lo menos hasta la fecha que determin\u00f3 el presidente; es la \u00fanica forma de combatir esta pandemia\u201d, en tanto adelant\u00f3 que \u201che dado instrucciones a Defensa Civil y a los cuerpos de Inspectores para que sean absolutamente severos en el cumplimiento de la cuarentena y el aislamiento social\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, recomend\u00f3 a la poblaci\u00f3n \u201cel uso de cualquier tipo de tapabocas o barbijos en ambientes p\u00fablicos o ambientes donde hay determinados grados de aglomeraci\u00f3n, como bancos y supermercados\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por \u00faltimo, agradeci\u00f3 a los lujanenses \u201cpor el esfuerzo hecho hasta ahora\u201d y pidi\u00f3 que \u201ccontinuemos de la misma manera para proteger la salud de nuestros vecinos y vecinas, y proteger la vida de todos los lujanenses\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> De acuerdo al \u00faltimo protocolo enviado por la provincia de Buenos Aires, las zonas de transmisi\u00f3n local en Argentina son: <br>Ciudad Aut\u00f3noma de Buenos Aires <br>En Buenos Aires: en los siguientes municipios correspondientes al \u00c1rea Metropolitana: <br>\u25cf Regi\u00f3n Sanitaria V (completa): General San Mart\u00edn, Jos\u00e9 C. Paz, Malvinas Argentinas, San Fernando, San Isidro, San Miguel, Tigre, Vicente L\u00f3pez, Campana, Escobar, Exaltaci\u00f3n de la Cruz, Pilar, Z\u00e1rate <br>\u25cf Regi\u00f3n Sanitaria VI (completa): Almirante Brown, Avellaneda, Berazategui, Esteban Echeverr\u00eda, Ezeiza, Florencio Varela, Lan\u00fas, Lomas de Zamora, Quilmes <br>\u25cf Regi\u00f3n Sanitaria VII (completa): Hurlingham, Ituzaing\u00f3, Merlo, Moreno, Mor\u00f3n, Tres de Febrero, General Las Heras, General Rodr\u00edguez, Luj\u00e1n, Marcos Paz. <br>\u25cf Regi\u00f3n Sanitaria XI en los siguientes municipios: Berisso, Brandsen, Ca\u00f1uelas, Ensenada, La Plata, Presidente Per\u00f3n, San Vicente <br>\u25cf Regi\u00f3n Sanitaria XII: La Matanza <br>Provincia del Chaco <br>En Santa Fe: Ciudad de Santa Fe &#8211; Rosario &#8211; Rafaela <br>En C\u00f3rdoba: Ciudad de C\u00f3rdoba \u2013 Alta Gracia \u2013 Rio Cuarto <br>En Tierra del Fuego: Ushuaia <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: Luj\u00e1n en L\u00ednea<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En un mensaje a la comunidad, el Intendente de la Municipalidad de Luj\u00e1n, Leonardo Boto, le habl\u00f3 a la comunidad &#8230; <a title=\"Coronovirus: Luj\u00e1n fue declarada como zona de circulaci\u00f3n comunitaria del virus\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2020\/04\/09\/coronovirus-lujan-fue-declarada-como-zona-de-circulacion-comunitaria-del-virus\/\" aria-label=\"Leer m\u00e1s sobre Coronovirus: Luj\u00e1n fue declarada como zona de circulaci\u00f3n comunitaria del virus\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":109206,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[5501],"tags":[16467,16175,16313,86,9322,134],"class_list":["post-109205","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-region","tag-circulacion-comunitaria","tag-coronavirus","tag-covid-19","tag-lujan","tag-region","tag-salud","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2020\/04\/09-lujan-coronavirus.png","wps_subtitle":"Informaci\u00f3n regional","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/109205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=109205"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/109205\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/109206"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=109205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=109205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=109205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}