{"id":1150,"date":"2010-12-20T03:40:55","date_gmt":"2010-12-20T03:40:55","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=1150"},"modified":"2010-12-20T04:28:24","modified_gmt":"2010-12-20T04:28:24","slug":"la-artista-local-fernanda-ottolini-despidio-el-ano-en-confiteria-el-club","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2010\/12\/20\/la-artista-local-fernanda-ottolini-despidio-el-ano-en-confiteria-el-club\/","title":{"rendered":"La artista local Fernanda Ottolini despidi\u00f3 el a\u00f1o en confiter\u00eda el Club (Video)"},"content":{"rendered":"<figure id=\"attachment_1152\" aria-describedby=\"caption-attachment-1152\" style=\"width: 290px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2010\/12\/DSC01029.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"1152\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2010\/12\/20\/la-artista-local-fernanda-ottolini-despidio-el-ano-en-confiteria-el-club\/dsc01029\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2010\/12\/DSC01029.jpg\" data-orig-size=\"400,267\" data-comments-opened=\"1\" data-image-title=\"Fernanda Ottolini II\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2010\/12\/DSC01029.jpg\" class=\"size-medium wp-image-1152\" title=\"Fernanda Ottolini II\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2010\/12\/DSC01029-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2010\/12\/DSC01029-300x200.jpg 300w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2010\/12\/DSC01029.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-1152\" class=\"wp-caption-text\">Fernanda Ottolini en El Club<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">La artista local Fernanda Ottolini cerr\u00f3 su a\u00f1o de presentaciones en nuestra ciudad en un show extenso y movido en la Confiter\u00eda El Club.<\/p>\n<p style=\"text-align: justify;\">En un a\u00f1o que le permiti\u00f3 nuevamente recorrer diversas ciudades de la zona y presentarse tanto en \u00e1mbitos p\u00fablicos como privados, en actos solidarios y escenarios compartidos, la artista se present\u00f3 con un importante marco de p\u00fablico en El Club donde adem\u00e1s de los habituales clientes del lugar que disfrutaron el espect\u00e1culo estaban presentes despidiendo el a\u00f1o diversas instituciones, como personal del Centro de Educaci\u00f3n Complementaria, miembros de la Coalici\u00f3n C\u00edvica Ari, Personal de la ESB N\u00ba \u00a07, las chicas de Mercedes F\u00fatbol Club, estudiantes de la UNLu y amigos\u00a0 y familiares.<\/p>\n<p style=\"text-align: justify;\">El repertorio incluy\u00f3 temas para todos los gustos as\u00ed como una interacci\u00f3n fluida y amena con el p\u00fablico que se permiti\u00f3 bromear, cantar y solicitar canciones.<\/p>\n<p style=\"text-align: justify;\">Tangos como \u201cEl bazar de los juguetes\u201d o\u00a0 \u201cY te parece todav\u00eda\u201d, latinos como \u201cQu\u00e9 ser\u00e1 de ti\u201d, \u201cMientes\u201d, \u201cLa fuerza del enga\u00f1o\u201d, Rock al estilo Clapton en \u201cMaravillosa esta noche\u201d o a nivel nacional con \u201cMi enfermedad\u201d as\u00ed como una segunda parte bien movida donde muy pocos quedaron en sus asientos acompa\u00f1ando con palmas a los que bailaban temas como: \u201cLlora me llama\u201d, \u201cCoraz\u00f3n valiente\u201d, \u201cQui\u00e9reme\u201d, \u201cCoraz\u00f3n mentiroso\u201d; \u201cQui\u00e9n eres t\u00fa\u201d y muchos m\u00e1s.<\/p>\n<p style=\"text-align: justify;\">Como nota de color fue la invitaci\u00f3n que le hizo al concejal Jos\u00e9 Cestari para que mostrara sus cualidades a la hora del baile generando una virtual y humor\u00edstica batalla de baile con el intendente Selva dado que \u00e9ste lo hab\u00eda echo la semana anterior con \u00a0la actriz y humorista Gladys Florimonte. Cestari no s\u00f3lo tom\u00f3 el asunto con humor sino que, junto a sus amistades bail\u00f3 al ritmo de la m\u00fasica tropical qued\u00e1ndose hasta el final de la velada.<\/p>\n<p style=\"text-align: justify;\">Fernanda, por lo pronto, que adem\u00e1s estuvo en Suipacha durante el mismo fin de semana, tiene previsto regresar a las tablas locales luego de la temporada de verano 2011.<\/p>\n<p style=\"text-align: justify;\">Fragmento Video del tema \u00abllegaremos a tiempo\u00bb con el cual cerr\u00f3 la presentaci\u00f3n:<\/p>\n<p style=\"text-align: justify;\">[media id=8 width=500 height=440]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La artista local Fernanda Ottolini cerr\u00f3 su a\u00f1o de presentaciones en nuestra ciudad en un show extenso y movido en &#8230; <a title=\"La artista local Fernanda Ottolini despidi\u00f3 el a\u00f1o en confiter\u00eda el Club (Video)\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2010\/12\/20\/la-artista-local-fernanda-ottolini-despidio-el-ano-en-confiteria-el-club\/\" aria-label=\"Leer m\u00e1s sobre La artista local Fernanda Ottolini despidi\u00f3 el a\u00f1o en confiter\u00eda el Club (Video)\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[1],"tags":[272],"class_list":["post-1150","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-fernanda-ottolini","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","wps_subtitle":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/1150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=1150"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/1150\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=1150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=1150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=1150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}