{"id":116444,"date":"2020-09-11T11:47:19","date_gmt":"2020-09-11T14:47:19","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=116444"},"modified":"2020-09-12T10:09:12","modified_gmt":"2020-09-12T13:09:12","slug":"proyecto-hcd-piden-justicia-y-esclarecimiento-por-la-muerte-de-astudillo-castro","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2020\/09\/11\/proyecto-hcd-piden-justicia-y-esclarecimiento-por-la-muerte-de-astudillo-castro\/","title":{"rendered":"Proyecto HCD: piden justicia y esclarecimiento por la muerte de Astudillo Castro"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A trav\u00e9s de un proyecto de Resoluci\u00f3n, el bloque de Juntos por el Cambio de Mercedes \u00abmanifiesta el m\u00e1s en\u00e9rgico pedido de justicia y esclarecimiento de la desaparici\u00f3n y muerte dudosa de Facundo Astudillo Castro\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para tratar en la pr\u00f3xima sesi\u00f3n del Concejo Deliberante, el proyecto expresa la \u00abm\u00e1s profunda preocupaci\u00f3n sobre el accionar de la Polic\u00eda Bonaerense y pedir al Ministro de Seguridad de la Provincia de Buenos Aires Sergio Berni que tenga a bien de informar a este Honorable Concejo Deliberante sobre la actuaci\u00f3n de las fuerzas de seguridad a su cargo y la necesidad de que las mismas se manejen en el cumplimiento de todos y cada uno de los tratados internacionales de los que el Estado Argentino es parte, que velan por la protecci\u00f3n y los Derechos Humanos de las personas\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A trav\u00e9s de un proyecto de Resoluci\u00f3n, el bloque de Juntos por el Cambio de Mercedes \u00abmanifiesta el m\u00e1s en\u00e9rgico &#8230; <a title=\"Proyecto HCD: piden justicia y esclarecimiento por la muerte de Astudillo Castro\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2020\/09\/11\/proyecto-hcd-piden-justicia-y-esclarecimiento-por-la-muerte-de-astudillo-castro\/\" aria-label=\"Leer m\u00e1s sobre Proyecto HCD: piden justicia y esclarecimiento por la muerte de Astudillo Castro\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":116210,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[5],"tags":[15365,804,9405],"class_list":["post-116444","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-juntos-por-el-cambio","tag-policia-bonaerense","tag-proyecto-hcd","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2020\/09\/05-juntos-x-cambio.jpg","wps_subtitle":"Para tratar en la sesi\u00f3n pr\u00f3xima","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/116444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=116444"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/116444\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/116210"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=116444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=116444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=116444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}