{"id":119001,"date":"2020-10-25T16:39:26","date_gmt":"2020-10-25T19:39:26","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=119001"},"modified":"2020-10-27T09:08:55","modified_gmt":"2020-10-27T12:08:55","slug":"cuento-del-tio-intento-de-estafa-a-vecinos","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2020\/10\/25\/cuento-del-tio-intento-de-estafa-a-vecinos\/","title":{"rendered":"Cuento del t\u00edo: intento de estafa a vecinos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En horas de la ma\u00f1ana del viernes, dos familias de la ciudad recibieron, pr\u00e1cticamente a la misma hora, llamadas telef\u00f3nicas a sus tel\u00e9fonos fijos con el fin de estafar a los adultos mayores. Una mujer alegando que era una de las hijas y un hombre diciendo que era uno de los nietos, les pidieron d\u00f3lares \u201cpara ser cambiados porque dejaban de estar en circulaci\u00f3n\u201d. Los intentos de cuento del t\u00edo est\u00e1n siendo investigados por la fiscal\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lleg\u00f3 a la redacci\u00f3n de Hoy Mercedes las historias de dos familias mercedinas que el viernes pasado, a pocos minutos de diferencia y a pocas cuadras de distancia, recibieron llamadas a sus tel\u00e9fonos fijos con una historia similar. Por un lado, una de las familias recibi\u00f3 el llamado de \u201cuna hija\u201d que le ped\u00eda los d\u00f3lares a sus padres para ser cambiados en el banco, y por el otro lado, una voz de var\u00f3n joven, diciendo que era \u201cel nieto\u201d de quien hablaba con una historia similar e insistiendo en una segunda llamada para hablar con otras de las personas de la casa que en el primer llamado no estaba disponible.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo a lo narrado por una de las familias, la voz del otro lado del tel\u00e9fono explicaba que un contador hab\u00eda dicho que ciertos billetes dejar\u00edan de circular y por eso hab\u00eda que completar una planilla con los n\u00fameros de los billetes y llevar eso con los mismos billetes al banco, que no llegaron a identificar a qu\u00e9 sucursal bancaria. La situaci\u00f3n no lleg\u00f3 a mayores porque la familia advirti\u00f3 la potencial estafa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego se supo que a pocas cuadras, otra familia hab\u00eda recibido una llamada similar con una historia parecida. Por eso se teme que hubiese en la zona una persona atenta a tomar d\u00f3lares de las personas que atend\u00edan el tel\u00e9fono.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ese mismo viernes, una de las familias se comunic\u00f3 con la Fiscal\u00eda de Mercedes para advertir y denunciar el intento de delito catalogado como \u00abphishing\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde la Fiscal\u00eda solicitaron a la comunidad que tomen los recaudos para evitar la concreci\u00f3n del famoso cuento del t\u00edo, asimismo recordaron los consejos publicados por el Ministerio P\u00fablico Fiscal de la provincia de Buenos Aires. (<a href=\"https:\/\/www.mpba.gov.ar\/phishing\" target=\"_blank\" rel=\"noopener\">VER AQUI<\/a>)<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">\u00bfQu\u00e9 es el Phishing?<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">El objetivo del \u00abphishing\u00bb y el cuento del t\u00edo con componentes digitales, es conseguir los datos personales de un usuario o persona. Sean estas claves de acceso y contrase\u00f1as, n\u00fameros de cuentas bancarias, n\u00fameros de tarjeta de cr\u00e9dito, identidades, etc.; el atacante busca alcanzar \u00abtodos los datos posibles\u00bb de su v\u00edctima para luego usarlos de manera fraudulenta.<br>Los delincuentes montan una p\u00e1gina web similar a la de una organizaci\u00f3n conocida y env\u00edan de forma masiva correos electr\u00f3nicos requiriendo ACTUALIZACI\u00d3N DE DATOS. En el mencionado correo informan que se registraron aparentes operaciones en la cuenta de la v\u00edctima, o que la cuenta del usuario fue bloqueada, entre otras afirmaciones. El mensaje contiene un enlace a la p\u00e1gina web falsa.<br><strong>El objetivo:<\/strong>\u00a0causar en la v\u00edctima la impresi\u00f3n de que tiene que actuar inmediatamente para impedir el aparente problema.<br>Otro instrumento por la cual los delincuentes act\u00faan es el tel\u00e9fono; se valen de la informaci\u00f3n conseguida, p\u00fablica o robada, para evaluar a sus v\u00edctimas. Por ejemplo, env\u00edan un mensaje a tu celular indicando que ganaste un aparente premio y qu\u00e9 debes llamar al n\u00famero se\u00f1alado en el mensaje, o bien, una llamada para pedirte la supuesta validaci\u00f3n de datos. Con ardides tales ganan tu confianza, y una vez conquistada la misma, les facilitas datos sensibles como el PIN o la clave de acceso a tu cuenta o, inclusive, de manera concreta te solicitan que te dirijas al cajero autom\u00e1tico.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">\u00bfCu\u00e1les son algunas las excusas que utilizan al momento de contactarte?<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Cobrar la IFE, u otra asignaci\u00f3n social, acreditaci\u00f3n de un premio, nuevos beneficios, etc. Cualquier excusa capaz de captar tu atenci\u00f3n.<br>Tambi\u00e9n se han detectado mensajes de trav\u00e9s de servicios como WhatsApp y Redes Sociales, as\u00ed como tambi\u00e9n por Sms -Smishing- los que te ofrecen cupones descuento, encuestas o premios por rellenar una encuesta con tus datos personales. De la misma manera, la web a la que te remiten es falsa.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Consejos para evitar ser v\u00edctima del Phishing<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Nunca facilites informaci\u00f3n confidencial ni por mail, ni por tel\u00e9fono. El tipo de informaci\u00f3n a la que hacemos referencia son: n\u00fameros de cuenta, clave de la tarjeta de cr\u00e9dito o contrase\u00f1as de acceso a redes sociales o cuentas de correo.<br>Ten\u00e9 en cuenta que los delincuentes se hacen pasar por una empresa o servicio conocido y los enlaces presentes en los correos electr\u00f3nicos te redirigen a p\u00e1ginas fraudulentas que simulan ser las oficiales.<br>Por lo antes dicho, si deseas actualizar tus datos en el sitio web oficial de la organizaci\u00f3n, escribe t\u00fa mismo la direcci\u00f3n web de la organizaci\u00f3n en el navegador. Nunca entres a los links o archivos adjuntos al mensaje.<br>Por otro lado, evitando descargar archivos no te expones a que se instale en tu computadora un malware, o programa malicioso, y robe tu informaci\u00f3n personal.<br><br><strong>Si te llaman por tel\u00e9fono:<\/strong><br>Marca vos mismo el n\u00famero telef\u00f3nico oficial de la organizaci\u00f3n con la que te quer\u00e9s comunicar. Nunca los brindes datos personales cuando te llaman sin que vos hayas solicitado el contacto.<br><br><strong>C\u00f3mo lidiar con un correo de phishing y correos de spam o una llamada telef\u00f3nica<\/strong><br>&#8211; Eliminar el correo, hacer caso omiso y denunciar.<br>&#8211; No respondas o cort\u00e1 inmediatamente.<br><br><strong>Para mantenerte seguro:<\/strong><br>&#8211; Cambia las contrase\u00f1as de forma inmediata.<br>&#8211; Evitar difundir tu informaci\u00f3n personal a trav\u00e9s de redes sociales, mant\u00e9n tus redes sociales con la configuraci\u00f3n de seguridad adecuada, evita tener tu red social p\u00fablica.<br>&#8211; Evita dejar tus datos en p\u00e1ginas web de dudosa procedencia o p\u00e1ginas de pagos sin el certificado de seguridad.<br>&#8211; Utiliza contrase\u00f1as \u00fanicas para cada servicio, con al menos 8 caracteres diferentes que incluyan may\u00fasculas, min\u00fasculas, n\u00fameros y caracteres especiales.<br>&#8211; Si quieres realizar cualquier tipo de operaci\u00f3n bancaria o comercial, trata de no hacerlo desde computadoras p\u00fablicas o desde una red WIFI abierta, ya que es m\u00e1s f\u00e1cil captar este tipo de datos.<br>&#8211; Disp\u00f3n de un filtro antispam o herramientas que bloquean el correo considerado como \u201cno deseado\u201d. Mant\u00e9n al d\u00eda las actualizaciones de tu antivirus y antispam.<br>&#8211; Cataloga como spam los correos sospechosos, con t\u00edtulos extra\u00f1os y provenientes de direcciones desconocidas.<br>&#8211; Siempre corrobor\u00e1 la direcci\u00f3n URL de la p\u00e1gina web a la que accedas, no debe tener alteraciones tales como: faltas de ortograf\u00eda, reemplazo de letras por n\u00fameros, min\u00fasculas por may\u00fasculas o a la inversa.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Si has sido v\u00edctima de un fraude de phishing y has dado tus datos personales, debes seguir estos consejos:<\/h5>\n\n\n\n<ul class=\"wp-block-list\"><li>Denunciar ante la fiscal\u00eda de turno de tu departamento judicial, aportando todas las pruebas de cargo que tengas, tales como capturas de pantalla, los mails fraudulentos, certificados bancarios que demuestren los cargos ilegales que hayas sufrido en tus cuentas, etc.<\/li><li>Se debe informar a la entidad bancaria de este hecho para que establezca unos mecanismos de seguridad que eviten posibles cargos fraudulentos.<\/li><li>Cambia tu contrase\u00f1a de inmediato.<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>En horas de la ma\u00f1ana del viernes, dos familias de la ciudad recibieron, pr\u00e1cticamente a la misma hora, llamadas telef\u00f3nicas &#8230; <a title=\"Cuento del t\u00edo: intento de estafa a vecinos\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2020\/10\/25\/cuento-del-tio-intento-de-estafa-a-vecinos\/\" aria-label=\"Leer m\u00e1s sobre Cuento del t\u00edo: intento de estafa a vecinos\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":54332,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[85],"tags":[3761,17219,96],"class_list":["post-119001","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial","tag-cuento-del-tio","tag-intento-de-estafa","tag-policial-2","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/09\/Estafas-telefonicas.jpg","wps_subtitle":"Prevenci\u00f3n","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/119001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=119001"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/119001\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/54332"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=119001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=119001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=119001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}