{"id":125233,"date":"2021-02-23T06:53:00","date_gmt":"2021-02-23T09:53:00","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=125233"},"modified":"2021-02-22T22:59:52","modified_gmt":"2021-02-23T01:59:52","slug":"selva-destaca-compromiso-del-gobierno-con-la-clase-trabajadora","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2021\/02\/23\/selva-destaca-compromiso-del-gobierno-con-la-clase-trabajadora\/","title":{"rendered":"Selva destaca \u201ccompromiso\u201d del gobierno con la clase trabajadora"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u201cNuestro Presidente Alberto Fern\u00e1ndez incluy\u00f3 por decreto en el temario de sesiones extraordinarias, el proyecto de ley de Sergio Massa que busca cambiar el piso para el impuesto a las ganancias\u201d, destac\u00f3 el diputado nacional Carlos Selva, del Frente de Todos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEste alivio fiscal marca el fuerte compromiso del Gobierno con la clase media trabajadora, jubilados y jubiladas\u201d, dio en referencia a la firma por parte del presidente de la Naci\u00f3n, Alberto Fern\u00e1ndez, de un decreto para tratar Ganancias en Extraordinarias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De esta manera se espera que el proyecto sea aprobado ya en el mes de marzo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El decreto fue publicado en el Bolet\u00edn Oficial para que se debata en comisi\u00f3n en febrero, y se cree que el Presidente har\u00e1 un anuncio formal en la Asamblea Legislativa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cNuestro Presidente Alberto Fern\u00e1ndez incluy\u00f3 por decreto en el temario de sesiones extraordinarias, el proyecto de ley de Sergio Massa &#8230; <a title=\"Selva destaca \u201ccompromiso\u201d del gobierno con la clase trabajadora\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2021\/02\/23\/selva-destaca-compromiso-del-gobierno-con-la-clase-trabajadora\/\" aria-label=\"Leer m\u00e1s sobre Selva destaca \u201ccompromiso\u201d del gobierno con la clase trabajadora\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":120361,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[5210],"tags":[39,161,10113],"class_list":["post-125233","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica-nacional","tag-carlos-selva","tag-diputados","tag-politica-nacional","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2020\/11\/18-selva-sesion-1.jpg","wps_subtitle":"Pol\u00edtica legislativa","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/125233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=125233"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/125233\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/120361"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=125233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=125233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=125233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}