{"id":128270,"date":"2021-04-16T07:20:00","date_gmt":"2021-04-16T10:20:00","guid":{"rendered":"https:\/\/www.hoymercedes.com.ar\/principal\/?p=128270"},"modified":"2021-04-15T22:44:10","modified_gmt":"2021-04-16T01:44:10","slug":"jano-behro-gano-en-una-fecha-de-tenis-en-las-canchas-municipales","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2021\/04\/16\/jano-behro-gano-en-una-fecha-de-tenis-en-las-canchas-municipales\/","title":{"rendered":"Jano Behro gan\u00f3 en una fecha de tenis en las canchas municipales"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En las canchas profesionales municipales de tenis \u201cMary Ter\u00e1n de Weiss\u201d, se pudo llevar adelante una nueva participaci\u00f3n protocolizada correspondiente al \u201cMes de la Inauguraci\u00f3n\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dicha propuesta cuenta con un campeonato por fin de semana para que distintos actores de la ciudad puedan disfrutar del nuevo espacio y, en este caso, la tercera fecha fue la oportunidad para los menores.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Siendo para uso libre y gratuito, de caracter\u00edsticas \u00fanicas en la regi\u00f3n, se disput\u00f3 en la modalidad de Singles y tuvo la participaci\u00f3n de 12 j\u00f3venes tenistas locales, bajo la organizaci\u00f3n del Profesor Ariel Vivas.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los resultados de la jornada del jueves 1 de abril:\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Octavos de Final:\u00a0<br>Cagnone a Lafarga 4\/0 W.O.\u00a0<br>Mustoni a Ricciardulli 4\/0 W.O.\u00a0<br>Collazzo a L\u00f3pez 4\/2.\u00a0<br>Toscano a Fink 4\/1.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuartos de Final:\u00a0<br>Mustoni a Cagnone 4\/1.\u00a0<br>Behro a Tosco 4\/2.\u00a0<br>Pareja a Valle 4\/0 W.O.\u00a0<br>Collazzo a Toscano 4\/1.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Semifinales:\u00a0<br>Jano Behro a Benjam\u00edn Mustoni 6\/2.\u00a0<br>Juan Cruz Pareja a Alejo Collazzo 7\/5.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Final:\u00a0\u00a0<br>Jano Behro a Juan Cruz Pareja 6\/1.<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En las canchas profesionales municipales de tenis \u201cMary Ter\u00e1n de Weiss\u201d, se pudo llevar adelante una nueva participaci\u00f3n protocolizada correspondiente &#8230; <a title=\"Jano Behro gan\u00f3 en una fecha de tenis en las canchas municipales\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2021\/04\/16\/jano-behro-gano-en-una-fecha-de-tenis-en-las-canchas-municipales\/\" aria-label=\"Leer m\u00e1s sobre Jano Behro gan\u00f3 en una fecha de tenis en las canchas municipales\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":128272,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[21],"tags":[17702,204,13568,6924],"class_list":["post-128270","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","tag-cancha-municipal","tag-deportes-2","tag-menores","tag-tenis","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2021\/04\/15-cancha-de-tenis.jpg","wps_subtitle":"Menores","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/128270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=128270"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/128270\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/128272"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=128270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=128270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=128270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}