{"id":129131,"date":"2021-04-28T11:26:12","date_gmt":"2021-04-28T14:26:12","guid":{"rendered":"https:\/\/www.hoymercedes.com.ar\/principal\/?p=129131"},"modified":"2021-04-28T20:44:02","modified_gmt":"2021-04-28T23:44:02","slug":"segunda-ola-carlos-selva-pide-medidas-mas-extremas","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2021\/04\/28\/segunda-ola-carlos-selva-pide-medidas-mas-extremas\/","title":{"rendered":"Segunda ola: Carlos Selva pide medidas \u00abm\u00e1s extremas\u00bb"},"content":{"rendered":"\n<p>El diputado nacional\u00a0<strong>Carlos Selva<\/strong>\u00a0pidi\u00f3 medidas m\u00e1s extremas para controlar la segunda ola del coronavirus. El legislador nacional del Frente de Todos fue vacunado el pasado viernes junto a su esposa Cristina Arias y por esta horas manifest\u00f3 la necesidad de extremar cuidados en Buenos Aires y apunt\u00f3 contra la \u201coposici\u00f3n irresponsable\u201d.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"425\" data-attachment-id=\"129132\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2021\/04\/28\/segunda-ola-carlos-selva-pide-medidas-mas-extremas\/28-vacunado-selva\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2021\/04\/28-vacunado-selva.jpg\" data-orig-size=\"640,425\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"28 vacunado selva\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2021\/04\/28-vacunado-selva.jpg\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2021\/04\/28-vacunado-selva.jpg\" alt=\"\" class=\"wp-image-129132\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2021\/04\/28-vacunado-selva.jpg 640w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2021\/04\/28-vacunado-selva-630x418.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2021\/04\/28-vacunado-selva-150x100.jpg 150w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure><\/div>\n\n\n\n<p>El diputado nacional del Frente de Todos y ex intendente de Mercedes&nbsp;<a href=\"https:\/\/www.politicargentina.com\/notas\/202104\/36752-el-massismo-pidio-medidas-mas-extremas-alerto-sobre-la-situacion-en-buenos-aires-y-apunto-contra-la-oposicion-irresponsable.html\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>en di\u00e1logo con \u00abPol\u00edtica Argentina\u00bb<\/strong><\/a>&nbsp;se refiri\u00f3 al estado de situaci\u00f3n de la pandemia de coronavirus al remarcar la necesidad de profundizar las medidas gubernamentales a los efectos de que se siga propagando la problem\u00e1tica. \u201cSi seguimos as\u00ed en tres d\u00edas nos quedamos sin camas\u201d, sostuvo sobre Mercedes.<\/p>\n\n\n\n<p>\u00abTenemos que tomar m\u00e1s restricciones\u00bb, dijo y consider\u00f3 que la problem\u00e1tica este a\u00f1o es m\u00e1s compleja porque \u201cse est\u00e1 demostrando que los casos tienen m\u00e1s durabilidad en t\u00e9rminos de internaci\u00f3n con lo que marcar\u00e1 claramente una saturaci\u00f3n del sistema sanitario\u201d.<\/p>\n\n\n\n<p>\u201cPor lo tanto, las restricciones tienen que ser mayores y con m\u00e1s demora en el tiempo, cuesti\u00f3n que podamos recuperar la normalidad lo antes posible\u201d, a\u00f1adi\u00f3 en declaraciones a&nbsp;<em>Pol\u00edtica Argentina.<\/em><\/p>\n\n\n\n<p>Seg\u00fan el diputado, \u201chay que darle tiempo al sistema de salud para que se ordene nuevamente. En distritos como Luj\u00e1n, est\u00e1 totalmente desbordado. Mercedes tiene un poco de margen pero sigue en el orden de los 30 y 50 contagios en promedio\u201d. \u201cSi esto sigue as\u00ed, en tres d\u00edas nos quedamos sin camas\u201d, advirti\u00f3.<\/p>\n\n\n\n<p>Selva remarc\u00f3 que se debe \u201cser solidario con el personal m\u00e9dico porque ya no dan m\u00e1s\u201d. \u201cNo hay forma de que podamos garantizar salud si no tenemos medidas m\u00e1s extremas\u201d, insisti\u00f3.<\/p>\n\n\n\n<p>Consultado sobre el rol de la oposici\u00f3n y la dirigencia porte\u00f1a del PRO, consider\u00f3 que \u201cno se puede calificar a la oposici\u00f3n de otra forma que no sea irresponsable\u201d. \u201cHan tenido una actitud totalmente irresponsable, especularon con lo que no hab\u00eda que especular que es la salud de los argentinos, especularon con su electorado pero es momento de ser solidario\u201d, recalc\u00f3.<\/p>\n\n\n\n<p>Y repudi\u00f3 tambi\u00e9n a los medios hegem\u00f3nicos por \u201cc\u00f3mo enfocaron estos temas en el marco de la crisis en la que estamos\u201d.<\/p>\n\n\n\n<p>Fuente: Prensa Carlos Selva<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El diputado nacional\u00a0Carlos Selva\u00a0pidi\u00f3 medidas m\u00e1s extremas para controlar la segunda ola del coronavirus. El legislador nacional del Frente de &#8230; <a title=\"Segunda ola: Carlos Selva pide medidas \u00abm\u00e1s extremas\u00bb\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2021\/04\/28\/segunda-ola-carlos-selva-pide-medidas-mas-extremas\/\" aria-label=\"Leer m\u00e1s sobre Segunda ola: Carlos Selva pide medidas \u00abm\u00e1s extremas\u00bb\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":129132,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[5210],"tags":[39,16175,10113,765],"class_list":["post-129131","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica-nacional","tag-carlos-selva","tag-coronavirus","tag-politica-nacional","tag-vacunacion","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2021\/04\/28-vacunado-selva.jpg","wps_subtitle":"Vacunado junto a su esposa","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/129131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=129131"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/129131\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/129132"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=129131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=129131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=129131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}