{"id":13067,"date":"2012-05-24T03:54:57","date_gmt":"2012-05-24T03:54:57","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=13067"},"modified":"2012-05-24T03:54:57","modified_gmt":"2012-05-24T03:54:57","slug":"repavimentacion-por-deficiencias-en-construccion","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2012\/05\/24\/repavimentacion-por-deficiencias-en-construccion\/","title":{"rendered":"Repavimentaci\u00f3n por deficiencias en construcci\u00f3n"},"content":{"rendered":"<p><a href=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2012\/05\/Arreglos-Av29.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"13069\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2012\/05\/24\/repavimentacion-por-deficiencias-en-construccion\/arreglos-av29\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2012\/05\/Arreglos-Av29.jpg\" data-orig-size=\"612,459\" data-comments-opened=\"1\" data-image-title=\"Arreglos-Av29\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2012\/05\/Arreglos-Av29.jpg\" class=\"aligncenter size-full wp-image-13069\" title=\"Arreglos-Av29\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2012\/05\/Arreglos-Av29.jpg\" alt=\"\" width=\"612\" height=\"459\" \/><\/a><\/p>\n<p>Se trata del sector donde ese encuentra el cantero que divide las manos de la avenida 29 ya que en ambos laterales el pavimento \u00a0hab\u00eda comenzado a agrietarse de manera peligrosa<\/p>\n<p>Una vez m\u00e1s ayer a la ma\u00f1ana personal municipal debi\u00f3 concurrir a la Avenida 29 entre v\u00eda del Belgrano y calles 42 para reparar una rotura que se hab\u00eda generado en torno al trabajo efectuado no hace tanto tiempo cuando recordar\u00e1n al romperse el ca\u00f1o cloacal se hundi\u00f3 casi la totalidad del cantero existente que adem\u00e1s de decoraci\u00f3n sirve para separar las manos de circulaci\u00f3n vehicular.<\/p>\n<p>Los trabajos que se debieron realizar obligaron al personal municipal a cortar la circulaci\u00f3n de la mano que desde el Parque va a al centro.<\/p>\n<p>Consultados cual era el inconveniente el personal que se encontraba trabajando sostuvo \u201cpor alg\u00fan motivo la parte de pavimento nuevo que se construy\u00f3 al reparar la ultima vez los canteros comenzaron a agrietarse y exist\u00eda un peligro cierto de producirse un nuevo problema m\u00e1s o menos similar al ya ocurrido, por tal motivo se decidi\u00f3 en prime lugar levantar ese pavimento agrietado, consolidar mucho mejor la parte de la base de tierra y luego si volver a construir la carpeta asf\u00e1ltica calculando que con suerte durante la jornada del mi\u00e9rcoles iban a concluir con la totalidad de la tareas.<\/p>\n<p><a href=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2012\/05\/Arreglos-Av29-II.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"13070\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2012\/05\/24\/repavimentacion-por-deficiencias-en-construccion\/arreglos-av29-ii\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2012\/05\/Arreglos-Av29-II.jpg\" data-orig-size=\"612,459\" data-comments-opened=\"1\" data-image-title=\"Arreglos-Av29-II\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2012\/05\/Arreglos-Av29-II.jpg\" class=\"aligncenter size-full wp-image-13070\" title=\"Arreglos-Av29-II\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2012\/05\/Arreglos-Av29-II.jpg\" alt=\"\" width=\"612\" height=\"459\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2012\/05\/Arreglos-Av29-II.jpg 612w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2012\/05\/Arreglos-Av29-II-300x225.jpg 300w\" sizes=\"auto, (max-width: 612px) 100vw, 612px\" \/><\/a><\/p>\n<p>Posteriormente al ser consultado acerca si sobre la otra mano deb\u00edan realizar el mismo trabajo respondieron \u201ca\u00fan no sabemos concretamente, pero entendemos que si porque tambi\u00e9n se ha comenzado a agrietar la \u00faltima parte del pavimento construido aunque si \u201custedes recorren todo el sector y miran con detenimiento podr\u00e1n comprobar que el pavimento se encuentra agrietado en varios sectores seguramente producto del movimiento que se genera a lo largo de todo el d\u00eda con la cantidad de tr\u00e1nsito que circula por este lugar recordando que debajo de la pate donde est\u00e1 el cantero se encuentra el ca\u00f1o maestro de obras sanitarias que termina llegando a la Planta Depuradora de Residuos cloacales por lo cual si bien cuenta con una muy buena bases muchas veces va cediendo sin que nos demos cuenta y por eso se generan la grietas y finalmente las roturas\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se trata del sector donde ese encuentra el cantero que divide las manos de la avenida 29 ya que en &#8230; <a title=\"Repavimentaci\u00f3n por deficiencias en construcci\u00f3n\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2012\/05\/24\/repavimentacion-por-deficiencias-en-construccion\/\" aria-label=\"Leer m\u00e1s sobre Repavimentaci\u00f3n por deficiencias en construcci\u00f3n\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[1],"tags":[2227,1951,2228,2226,1173,18],"class_list":["post-13067","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-29-y-40-pavimento-roto","tag-avenida-29","tag-obras-en-mercedes","tag-obras-publicas-mercedes","tag-salomone","tag-selva","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","wps_subtitle":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/13067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=13067"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/13067\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=13067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=13067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=13067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}