{"id":131961,"date":"2021-06-17T10:20:00","date_gmt":"2021-06-17T13:20:00","guid":{"rendered":"https:\/\/www.hoymercedes.com.ar\/principal\/?p=131961"},"modified":"2021-06-17T09:50:11","modified_gmt":"2021-06-17T12:50:11","slug":"el-diputado-selva-participo-de-reunion-con-el-titular-de-trenes-argentinos-y-ustarroz","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2021\/06\/17\/el-diputado-selva-participo-de-reunion-con-el-titular-de-trenes-argentinos-y-ustarroz\/","title":{"rendered":"El diputado Selva particip\u00f3 de reuni\u00f3n con el titular de Trenes Argentinos y Ustarroz"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El titular de Trenes Argentinos,\u00a0<strong>Mart\u00edn Marinucci<\/strong>, visit\u00f3 la ciudad de Mercedes en la previa al inicio de las obras de renovaci\u00f3n de v\u00edas. Junto al intendente\u00a0<strong>Juan Ustarroz<\/strong>\u00a0y el diputado nacional\u00a0<strong>Carlos Selva<\/strong>\u00a0dialogaron sobre el inicio de los trabajos de renovaci\u00f3n de v\u00edas entre Luj\u00e1n y Mercedes de la l\u00ednea Sarmiento.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"350\" data-attachment-id=\"131962\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2021\/06\/17\/el-diputado-selva-participo-de-reunion-con-el-titular-de-trenes-argentinos-y-ustarroz\/17-selva-marinucci\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2021\/06\/17-selva-marinucci.jpg\" data-orig-size=\"640,350\" data-comments-opened=\"0\" data-image-title=\"17 selva marinucci\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2021\/06\/17-selva-marinucci.jpg\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2021\/06\/17-selva-marinucci.jpg\" alt=\"\" class=\"wp-image-131962\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2021\/06\/17-selva-marinucci.jpg 640w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2021\/06\/17-selva-marinucci-630x345.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2021\/06\/17-selva-marinucci-150x82.jpg 150w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n abordaron el trabajo conjunto realizado a partir de la instalaci\u00f3n del coche de la Unidad de G\u00e9nero y la Unidad de Discapacidad de Trenes Argentinos que fue emplazado en la estaci\u00f3n local, donde se realizaron capacitaciones en esa tem\u00e1tica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Marinucci se refiri\u00f3 a la obra que iniciar\u00e1 en las pr\u00f3ximas semanas y que implicar\u00e1 la renovaci\u00f3n total de las v\u00edas entre Luj\u00e1n y Mercedes: \u201cNuestra prioridad es brindar m\u00e1s servicios con la mayor seguridad posible, la renovaci\u00f3n de las v\u00edas, la puesta en condiciones de las estaciones, la posibilidad de articular con los municipios en los cuadros de estaci\u00f3n para que puedan realizar intervenciones y que los predios linderos sean utilizados para beneficiar a los vecinos y vecinas\u201d, remarc\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego de la reuni\u00f3n, las autoridades recorrieron un predio lindero a la c\u00e1rcel local donde se&nbsp;instalar\u00e1 el llamado \u201cVag\u00f3n de Jesus\u201d. Se trata de un coche que fue donado por ADIF al Obispado local y ser\u00e1 destinado a atender a personas en situaci\u00f3n de vulnerabilidad, las que recibir\u00e1n contenci\u00f3n por parte de la Parroquia San Jos\u00e9 y el P\u00e1rroco Hern\u00e1n Arturo L\u00f3pez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La obra de renovaci\u00f3n de v\u00edas<br><\/strong>Seg\u00fan se inform\u00f3 se renovar\u00e1n 35 kil\u00f3metros de v\u00edas: cambio de durmientes por estructuras de hormig\u00f3n, renovaci\u00f3n integral de rieles y fijaciones de v\u00eda, colocaci\u00f3n de piedra balasto y recuperaci\u00f3n de los cruces a nivel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El objetivo de las intervenciones es \u201cincrementar la velocidad de circulaci\u00f3n, disminuir los tiempos de viaje y beneficiar a los pasajeros y pasajeras brind\u00e1ndole mejor confort en el viaje y seguridad operativa\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n se efect\u00faan mejoras edilicias en los apeaderos La Reja, Francisco \u00c1lvarez, P. P. Mar\u00edn, J\u00e1uregui, Olivera y Gowland; la instalaci\u00f3n de iluminaci\u00f3n LED en varias de estas paradas y sus entornos y la reparaci\u00f3n integral de dos puentes (ubicados sobre los arroyos Pereyra y Cha\u00f1a).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: Prensa Carlos Selva<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El titular de Trenes Argentinos,\u00a0Mart\u00edn Marinucci, visit\u00f3 la ciudad de Mercedes en la previa al inicio de las obras de &#8230; <a title=\"El diputado Selva particip\u00f3 de reuni\u00f3n con el titular de Trenes Argentinos y Ustarroz\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2021\/06\/17\/el-diputado-selva-participo-de-reunion-con-el-titular-de-trenes-argentinos-y-ustarroz\/\" aria-label=\"Leer m\u00e1s sobre El diputado Selva particip\u00f3 de reuni\u00f3n con el titular de Trenes Argentinos y Ustarroz\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":131962,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[5210],"tags":[],"class_list":["post-131961","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica-nacional","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2021\/06\/17-selva-marinucci.jpg","wps_subtitle":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/131961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=131961"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/131961\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/131962"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=131961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=131961"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=131961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}