{"id":135027,"date":"2021-08-10T12:18:34","date_gmt":"2021-08-10T15:18:34","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=135027"},"modified":"2021-08-10T12:54:41","modified_gmt":"2021-08-10T15:54:41","slug":"dos-detenidos-por-abuso-sexual-de-menor","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2021\/08\/10\/dos-detenidos-por-abuso-sexual-de-menor\/","title":{"rendered":"Dos detenidos por abuso sexual de menor"},"content":{"rendered":"\n<p>En las jornadas del martes 3 y el jueves 5 del corriente se llevaron a cabo las detenciones de dos sujetos de 39 y 26 a\u00f1os, sindicados como autores de abuso sexual de una menor de 12 a\u00f1os, ocurrido en la localidad de Pla, partido de Alberti.<\/p>\n\n\n\n<p>A ra\u00edz de la denuncia efectuada a principios del mes de abril por la familia de la menor se dio inicio a las actuaciones en la Unidad Funcional de Instrucci\u00f3n y Juicio N.\u00ba 6 del Departamento Judicial Mercedes \u2013 a cargo del dr. Luis Carcagno.<\/p>\n\n\n\n<p>Se impartieron las directivas correspondientes y se solicit\u00f3 por ante el Juzgado de Garant\u00edas N\u00b0 3, una orden de detenci\u00f3n para con tres sujetos imputados por hechos ocurridos en diferentes jornadas del presente a\u00f1o en perjuicio de la menor de edad. <\/p>\n\n\n\n<p>La medida fue concedida, se procedi\u00f3 a su ejecuci\u00f3n y dos de los sujetos fueron detenidos y conducidos ante los estrados de la nombrada Dependencia Fiscal. El tercer imputado se encuentra con pedido de captura activa. <\/p>\n\n\n\n<p>Se les recibi\u00f3 declaraci\u00f3n en los t\u00e9rminos del art. 308 del C\u00f3digo Procesal Penal en orden al delito de \u201cAbuso sexual con acceso carnal\u201d en la jornada del 5 de agosto \u00faltimo y se dispuso su alojamiento en la sede de la DDI Mercedes, a disposici\u00f3n del Juzgado de Garant\u00edas interviniente. <\/p>\n\n\n\n<p>Fuente: Ministerio P\u00fablico Fiscal  &#8211; Depto Judicial Mercedes<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En las jornadas del martes 3 y el jueves 5 del corriente se llevaron a cabo las detenciones de dos &#8230; <a title=\"Dos detenidos por abuso sexual de menor\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2021\/08\/10\/dos-detenidos-por-abuso-sexual-de-menor\/\" aria-label=\"Leer m\u00e1s sobre Dos detenidos por abuso sexual de menor\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":127982,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[85],"tags":[17966,215,96,1057],"class_list":["post-135027","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial","tag-abuso-a-menos","tag-detenciones","tag-policial-2","tag-regional","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2021\/04\/PoliciaComual.jpg","wps_subtitle":"Regional","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/135027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=135027"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/135027\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/127982"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=135027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=135027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=135027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}