{"id":138107,"date":"2021-09-30T15:38:00","date_gmt":"2021-09-30T18:38:00","guid":{"rendered":"https:\/\/www.hoymercedes.com.ar\/principal\/?p=138107"},"modified":"2021-09-30T16:53:11","modified_gmt":"2021-09-30T19:53:11","slug":"dos-detenidos-y-secuestro-de-mercaderia-y-vehiculos-robados","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2021\/09\/30\/dos-detenidos-y-secuestro-de-mercaderia-y-vehiculos-robados\/","title":{"rendered":"Dos detenidos y secuestro de mercader\u00eda y veh\u00edculos robados"},"content":{"rendered":"\n<p><em>El procedimiento se llev\u00f3 a cabo el jueves con personal de las Sub DDI y DDI Luj\u00e1n. Los aprehendidos tienen 33 y 38 a\u00f1os oriundos de la Localidad de Moreno y San Martin, mientras que otros sujetos se fugaron del lugar en una camioneta no identificada. Secuestraron veh\u00edculos y mercader\u00eda robada.<\/em><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"557\" data-attachment-id=\"138108\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2021\/09\/30\/dos-detenidos-y-secuestro-de-mercaderia-y-vehiculos-robados\/secuestro-vehiculos-robados-696x557\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2021\/09\/Secuestro-Vehiculos-Robados-696x557-1.jpg\" data-orig-size=\"696,557\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Secuestro-Veh\u00edculos-Robados-696&amp;#215;557\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2021\/09\/Secuestro-Vehiculos-Robados-696x557-1.jpg\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2021\/09\/Secuestro-Vehiculos-Robados-696x557-1.jpg\" alt=\"\" class=\"wp-image-138108\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2021\/09\/Secuestro-Vehiculos-Robados-696x557-1.jpg 696w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2021\/09\/Secuestro-Vehiculos-Robados-696x557-1-630x504.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2021\/09\/Secuestro-Vehiculos-Robados-696x557-1-150x120.jpg 150w\" sizes=\"auto, (max-width: 696px) 100vw, 696px\" \/><\/figure><\/div>\n\n\n\n<p>Todo comenz\u00f3 el martes por la tarde, cuando distintas unidades investigativas de la DDI y SUBDDI Luj\u00e1n, a cargo del comisario inspector Luis R\u00edos del Puerto y el comisario inspector Marcos Granili, respectivamente, mientras se encontraban desarrollando labores de investigaci\u00f3n en la jurisdicci\u00f3n lograron establecer que habr\u00eda varios rodados con sujetos ocultos en una zona descampada.<\/p>\n\n\n\n<p>Ocurri\u00f3, concretamente, \u201csobre la calle Fray de Torres y un camino rural, as\u00ed como tambi\u00e9n sobre la vera del r\u00edo Lujan, evidenciando un transbordo de mercader\u00eda de posible procedencia il\u00edcita\u201d, se\u00f1alaron desde la Sub Delegaci\u00f3n Departamental de Investigaciones de Luj\u00e1n.<\/p>\n\n\n\n<p>Y agregaron que \u201cposteriormente, con el actuar del personal designado y tomando todas las medidas de seguridad debido al lugar, se logr\u00f3 en el lugar la aprehensi\u00f3n de dos sujetos masculinos mayores de edad: uno de 33 a\u00f1os y otro de 38, oriundos de la localidad de Moreno y San Mart\u00edn. Mientras que se dieron a la fuga otros sujetos en una camioneta no identificada y de la cual se trata de establecer m\u00e1s circunstancias\u201d.<\/p>\n\n\n\n<p>Por su parte, el personal policial secuestr\u00f3 varios veh\u00edculos, entre los que mencionaron \u201cun cami\u00f3n marca Ford Cargo de color blanco, una Ford F100 de color gris, una camioneta Chevrolet S10 doble cabina de color gris y una Volkswagen Gol Country sedan de color azul. Asimismo, oculta a pocos metros tambi\u00e9n se secuestr\u00f3 una pluma de color azul, que se utiliza sobre la plancha del cami\u00f3n para la descarga de mercader\u00eda, con gran cantidad de ladrillos huecos, pack de pa\u00f1ales marca Huggies, pack de yerba mate, como as\u00ed elementos para la investigaci\u00f3n tel\u00e9fono celulares y anotaciones\u201d, detallaron.<\/p>\n\n\n\n<p>En el marco de la investigaci\u00f3n tambi\u00e9n se logr\u00f3 determinar que el cami\u00f3n secuestrado habr\u00eda sido robado en la localidad de Mor\u00f3n en la modalidad de \u201cpirater\u00eda del asfalto\u201d. Este hecho se caratul\u00f3 como \u201crobo calificado de mercader\u00eda en transito y privaci\u00f3n ilegal de la libertad\u201d y ocurri\u00f3 en julio.<\/p>\n\n\n\n<p>En tanto, indicaron que \u201ccon correr de la investigaci\u00f3n se logr\u00f3 establecer que los otros rodados secuestrados pose\u00edan pedido de secuestro activo de distintos hechos delictuales en las localidades de Mor\u00f3n y Merlo\u201d.<\/p>\n\n\n\n<p>Finalmente, los aprehendidos quedaron a disposici\u00f3n de la Fiscal\u00eda N\u00b0 10 a cargo de la Dra. Mariana Su\u00e1rez, respondiendo al Ministerio P\u00fablico Fiscal del Departamento Judicial Mercedes, quien resolver\u00e1 sobre la situaci\u00f3n procesal.<\/p>\n\n\n\n<p>Fuente: Luj\u00e1n Hoy<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El procedimiento se llev\u00f3 a cabo el jueves con personal de las Sub DDI y DDI Luj\u00e1n. Los aprehendidos tienen &#8230; <a title=\"Dos detenidos y secuestro de mercader\u00eda y veh\u00edculos robados\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2021\/09\/30\/dos-detenidos-y-secuestro-de-mercaderia-y-vehiculos-robados\/\" aria-label=\"Leer m\u00e1s sobre Dos detenidos y secuestro de mercader\u00eda y veh\u00edculos robados\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":138108,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[201,85],"tags":[96,1057],"class_list":["post-138107","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lujan-2","category-policial","tag-policial-2","tag-regional","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2021\/09\/Secuestro-Vehiculos-Robados-696x557-1.jpg","wps_subtitle":"Policial regional","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/138107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=138107"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/138107\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/138108"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=138107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=138107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=138107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}