{"id":152572,"date":"2022-09-02T12:32:00","date_gmt":"2022-09-02T15:32:00","guid":{"rendered":"https:\/\/www.hoymercedes.com.ar\/principal\/?p=152572"},"modified":"2022-09-02T12:08:57","modified_gmt":"2022-09-02T15:08:57","slug":"sos-habitat-invita-a-manifestarse-por-la-ley-de-humedales","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2022\/09\/02\/sos-habitat-invita-a-manifestarse-por-la-ley-de-humedales\/","title":{"rendered":"SOS H\u00e1bitat invita a manifestarse por la ley de humedales"},"content":{"rendered":"\n<p>Este s\u00e1bado 3 de agosto, a partir de la hora 15, la asociaci\u00f3n civil S.O.S. H\u00e1bitat estar\u00e1 llevando adelante su acci\u00f3n local en el marco de las actividades plurinacional por los humedales. En el sector nuevo del Parque Municipal, donde est\u00e1 rinc\u00f3n de nativas, realizar\u00e1n carteles para colocar en diferentes puntos de la ciudad. <\/p>\n\n\n\n<p>\u00abMovilizaci\u00f3n por Ley de Humedales\u00bb, expresa la invitaci\u00f3n de la agrupaci\u00f3n ambientalista. \u00abEl s\u00e1bado te esperamos para pintar carteles para pedir por la ley de humedales YA! Venite con lo que tengas para pintar y el equipo de mate. La idea es visibilizar este tema tan importante a lo largo del partido. Si no pod\u00e9s unirte en el rinc\u00f3n de nativas, armate un cartel y colocalo en la puerta de tu casa. Mandanos la foto as\u00ed lo difundimos en las redes y medios de comunicaci\u00f3n!\u00bb, agregan. <\/p>\n\n\n\n<p>\u00abNuestros humedales se encuentran en estado de emergencia. Nos movilizamos a lo largo de todo el pa\u00eds con acciones locales coordinadas, en defensa de los humedales y reclamando una ley nacional que los proteja. Pero no queremos cualquier ley, apoyamos el texto consensuado de manera abierta y participativa en Diputados (Expte. 0075-D-2022). Hoy, m\u00e1s que nunca, es fundamental hacer escuchar la voz de los territorios\u00bb, destacan. <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" data-attachment-id=\"152573\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2022\/09\/02\/sos-habitat-invita-a-manifestarse-por-la-ley-de-humedales\/sos-ha-hume\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2022\/09\/sos-ha-hume.png\" data-orig-size=\"640,640\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"sos ha hume\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2022\/09\/sos-ha-hume.png\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2022\/09\/sos-ha-hume.png\" alt=\"\" class=\"wp-image-152573\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2022\/09\/sos-ha-hume.png 640w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2022\/09\/sos-ha-hume-620x620.png 620w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2022\/09\/sos-ha-hume-150x150.png 150w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Este s\u00e1bado 3 de agosto, a partir de la hora 15, la asociaci\u00f3n civil S.O.S. H\u00e1bitat estar\u00e1 llevando adelante su acci\u00f3n local en el marco de las actividades plurinacional por los humedales<\/p>\n","protected":false},"author":1,"featured_media":152573,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[8],"tags":[2311,43,100,887],"class_list":["post-152572","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociedad","tag-humedales","tag-medio-ambiente","tag-reclamo","tag-sos-habitat","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2022\/09\/sos-ha-hume.png","wps_subtitle":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/152572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=152572"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/152572\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/152573"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=152572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=152572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=152572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}