{"id":153989,"date":"2022-10-12T07:02:00","date_gmt":"2022-10-12T10:02:00","guid":{"rendered":"https:\/\/www.hoymercedes.com.ar\/principal\/?p=153989"},"modified":"2022-10-11T23:08:49","modified_gmt":"2022-10-12T02:08:49","slug":"la-extraccion-de-litio","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2022\/10\/12\/la-extraccion-de-litio\/","title":{"rendered":"La extracci\u00f3n de Litio\u00a0"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Por Cristi\u00e1n Frers* &#8211; En la Argentina, el litio se extrae a trav\u00e9s de la evaporaci\u00f3n de la salmuera presente en los salares. Se trata de una t\u00e9cnica m\u00e1s econ\u00f3mica que la extracci\u00f3n del mineral de roca, que por otro lado goza de ventajas medioambientales, y del que nuestro pa\u00eds puede sacar provecho debido a la presencia de salares en la Puna de Jujuy, Salta y Catamarca.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde fines del 2015 Sales de Jujuy, la empresa formada por tres socios estrat\u00e9gicos: Orocobre, la reconocida extractora australiana de litio; la automotriz japonesa Toyota; y Jemse (Jujuy Energ\u00eda y Miner\u00eda Sociedad del Estado), la estatal juje\u00f1a.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta uni\u00f3n de empresas busca maximizar las posibilidades econ\u00f3micas del emprendimiento proyectado para los pr\u00f3ximos 40 a\u00f1os: la primera aporta el know how para extraer el litio en los salares juje\u00f1os; la segunda, advirtiendo del potencial uso del mineral en la industria automotriz -y gran conocedora de la demanda de Asia, donde se fabrican el grueso de los celulares y las tabletas-, se orienta a la colocaci\u00f3n de la materia prima en el mercado; y, la tercera busca ser parte de un negocio relativamente nuevo y estrat\u00e9gico de la provincia, con amplio potencial de crecimiento, a la vez que intenta garantizarse la oferta necesaria para cuando, en un futuro, se completen los proyectos en danza de producci\u00f3n de bater\u00edas en Jujuy.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hay otros dos en funcionamiento: uno m\u00e1s antiguo en el Salar del Hombre Muerto (Catamarca), y otro a peque\u00f1a escala a\u00fan, en el Salar del Rinc\u00f3n de Salta, que en conjunto brindan toda la producci\u00f3n de la materia prima (alrededor de 40.000 toneladas) que es exportada en un 100% y\u2026 Con suerte tambi\u00e9n se podr\u00eda agregar la de Salinas de Gualicho, en Rio Negro.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El proceso de fabricaci\u00f3n de litio comienza en uno de los 17 pozos estrat\u00e9gicamente ubicados en el salar, que tienen una profundidad de hasta 200 metros.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bombas especiales extraen la salmuera, que luego es transportada a trav\u00e9s de ca\u00f1os de 16 pulgadas (salmueroductos), cuya extensi\u00f3n m\u00e1s larga es de 16 kil\u00f3metros. Al cabo del recorrido, la salmuera es colocada en grandes piletones.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A partir de all\u00ed, durante alrededor de un a\u00f1o, el proceso va desde la extracci\u00f3n del mineral de la salmuera hasta que se convierte en producto terminado, bajo la forma s\u00f3lida de sales<strong>.<\/strong> Entonces se apila en bolsas para ser despachado para la exportaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La salmuera va pasando por 17 piletas, en la medida que aumenta la concentraci\u00f3n de litio y el agua se va evaporando, a cielo abierto, bajo las condiciones medioambientales \u00fanicas que ofrece la puna juje\u00f1a -clima des\u00e9rtico de mucho sol y viento en el d\u00eda, y poqu\u00edsimas lluvias- que favorecen la evaporaci\u00f3n del agua, y por lo tanto permiten extraer el mineral a costos competitivos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hay gente que sostiene que la explotaci\u00f3n del litio requiere de perforaciones de agua\u202fque luego, se coloca en piletones hasta dejarla evaporar para luego extraer el litio. Para sacar litio hay que hacer perforaciones. Y en la tierra se superponen napas de aguas saladas y de aguas dulces. El litio se extrae perforando, pero al hacerlo se mezclan el agua dulce y la salada y ah\u00ed se contamina el agua porque ya no se puede usar ni para consumo humano ni para riego. El agua que sacan la llevan a unos piletones y ah\u00ed la dejan secar, evaporar para as\u00ed extraer el litio.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uno de los argumentos que se sostienen desde los gobiernos provinciales para intentar avanzar con la explotaci\u00f3n del litio, es que no se utilizan grandes cantidades de agua. Pero\u202fdesde las comunidades abor\u00edgenes aseguran que la del litio \u00abes una miner\u00eda de agua\u00bb y que \u201cno tiene un impacto ambiental diferente a la miner\u00eda del oro\u201d. \u00abCuando se perfora no queda m\u00e1s laguna porque la secan. Es una miner\u00eda de agua. Es verdad que no se usan explosivos, pero si se produce un da\u00f1o ambiental grande porque se utiliza much\u00edsima cantidad de agua. Adem\u00e1s, el mismo litio cuando se mueve es contaminante.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No voy a negar que conozco Salinas Grandes en Jujuy y en Salinas de Gualicho en Rio Negro, los dos salares m\u00e1s grandes de Argentina y el agua en estos lugares es realmente es escasa ya que se necesitan dos millones de litros de agua para producir una tonelada de litio. La obtenci\u00f3n de recursos minerales que se extraen por disoluci\u00f3n y concentraci\u00f3n tienen la desventaja del uso intensivo del agua, que suele ser de procedencias alejadas y potable de consumo humano se confrontan con los costos-beneficios y suelen encontrar hueco legales que perjudican a los pobladores por lo que es necesario legislar al respecto priorizando la salud y bienestar futuro exigiendo a las empresas la implementaci\u00f3n de t\u00e9cnicas innovadoras de aprovechamiento eficientes y dejando de lado lo eficaz y econ\u00f3mico con que se depredan los recursos escasos que perjudican la econom\u00eda en el corto y mediano plazo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hay que entender que en la zona hay cuencas que son cerradas que se nutren de la lluvia. Se crean naturalmente peque\u00f1os dep\u00f3sitos acu\u00edferos en donde se almacena el agua dulce. Al realizarse una perforaci\u00f3n en los salares y extraer esa agua salina no apta para el consumo, se produce un desplazamiento del agua dulce que est\u00e1 en la cuenca hacia el salar. En consecuencia<strong>,\u202f<\/strong>el agua que las comunidades usan para riego y consumo humano se saliniza y altera el balance hidrogeol\u00f3gico<strong>. <\/strong>Para un territorio en donde\u202fel d\u00e9ficit h\u00eddrico es extremo, esta gesti\u00f3n del agua significa un desequilibrio para el ecosistema, para las comunidades y para la biodiversidad&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otro lado, convengamos que entre ambas posiciones existen Estudios de Impacto Ambiental que deber\u00eda producirse en forma estatal y privada, antes que los emprendimientos mineros comiencen con la extracci\u00f3n del mineral y sobre todas las cosas que sea Vox Populi para que la gente lo entienda y se quede tranquila que no se ver\u00e1 afectada la producci\u00f3n ganadera ni la producci\u00f3n agr\u00edcola especialmente de las comunidades abor\u00edgenes.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al consultarle al\u202fMinistro de Ambiente y Desarrollo Sostenible, Juan Cabandi\u00e9,\u202fsobre c\u00f3mo est\u00e1n siendo gestionados estos recursos estrat\u00e9gicos, \u00e9l sostuvo que<strong>\u202f<\/strong>\u201ca la ley de miner\u00eda habr\u00eda que mejorarla\u201d<strong>\u202f<\/strong>y \u201cHay que mirar aquellas normativas que nos ponen en menores condiciones para el desarrollo argentino\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Muchas veces se contempla lo ambiental como anti productivista. Sin embargo<strong>,\u202f<\/strong>toda actividad es productivista siempre y cuando no se degrade lo ambiental<strong>\u202f<\/strong>en pos de utilidades y ganancias.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">*Cristi\u00e1n Frers \u2013 T\u00e9cnico Superior en Gesti\u00f3n Ambiental y T\u00e9cnico Superior en Comunicaci\u00f3n Social (Periodista).&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Cristi\u00e1n Frers* &#8211; En la Argentina, el litio se extrae a trav\u00e9s de la evaporaci\u00f3n de la salmuera presente en los salares. <\/p>\n","protected":false},"author":1,"featured_media":154018,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-153989","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opinion","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2022\/10\/Litio-trabajador-1.jpg","wps_subtitle":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/153989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=153989"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/153989\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/154018"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=153989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=153989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=153989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}