{"id":174808,"date":"2024-04-13T15:05:56","date_gmt":"2024-04-13T18:05:56","guid":{"rendered":"https:\/\/www.hoymercedes.com.ar\/principal\/?p=174808"},"modified":"2024-04-13T15:05:58","modified_gmt":"2024-04-13T18:05:58","slug":"inauguran-totem-en-homenaje-al-centro-de-veteranos-de-guerra-de-malvinas","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2024\/04\/13\/inauguran-totem-en-homenaje-al-centro-de-veteranos-de-guerra-de-malvinas\/","title":{"rendered":"Inauguran t\u00f3tem en homenaje al Centro de Veteranos de Guerra de Malvinas"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-attachment-id=\"174809\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2024\/04\/13\/inauguran-totem-en-homenaje-al-centro-de-veteranos-de-guerra-de-malvinas\/totemveteranos-1\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/04\/TotemVeteranos-1-scaled.jpeg\" data-orig-size=\"2560,1707\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Inauguran t\u00f3tem en homenaje al Centro de Veteranos de Guerra de Malvinas\" data-image-description=\"&lt;p&gt;Inauguran t\u00f3tem en homenaje al Centro de Veteranos de Guerra de Malvinas&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Inauguran t\u00f3tem en homenaje al Centro de Veteranos de Guerra de Malvinas&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/04\/TotemVeteranos-1-1024x683.jpeg\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/04\/TotemVeteranos-1-1024x683.jpeg\" alt=\"\" class=\"wp-image-174809\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/04\/TotemVeteranos-1-1024x683.jpeg 1024w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/04\/TotemVeteranos-1-630x420.jpeg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/04\/TotemVeteranos-1-150x100.jpeg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/04\/TotemVeteranos-1-1536x1024.jpeg 1536w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/04\/TotemVeteranos-1-2048x1366.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Con una amplia participaci\u00f3n de la ciudadan\u00eda se inaugur\u00f3 el t\u00f3tem en homenaje a nuestros veteranos y ca\u00eddos en Malvinas. Participaron nuestros h\u00e9roes locales, el intendente Ustarroz, trabajadores municipales que efectuaron la obra, vecinos y vecinos que acompa\u00f1an la causa Malvinas y la ratificaci\u00f3n de la soberan\u00eda nacional sobre el territorio actualmente usurpado por Inglaterra.&nbsp; La obra fue votada por unanimidad en el Concejo Deliberante. Se encuentra en la rotonda de Avenida 2 y Avenida de los Inmigrantes.<\/p>\n\n\n\n<p><strong>Veteranos<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-attachment-id=\"174811\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2024\/04\/13\/inauguran-totem-en-homenaje-al-centro-de-veteranos-de-guerra-de-malvinas\/totemveteranos-15\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/04\/TotemVeteranos-15.jpg\" data-orig-size=\"2048,1365\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;SEBASTIANAMBROSSIO&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;SebastianAmbrossio&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Inauguran t\u00f3tem en homenaje al Centro de Veteranos de Guerra de Malvinas\" data-image-description=\"&lt;p&gt;Inauguran t\u00f3tem en homenaje al Centro de Veteranos de Guerra de Malvinas&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Inauguran t\u00f3tem en homenaje al Centro de Veteranos de Guerra de Malvinas&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/04\/TotemVeteranos-15-1024x683.jpg\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/04\/TotemVeteranos-15-1024x683.jpg\" alt=\"\" class=\"wp-image-174811\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/04\/TotemVeteranos-15-1024x683.jpg 1024w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/04\/TotemVeteranos-15-630x420.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/04\/TotemVeteranos-15-150x100.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/04\/TotemVeteranos-15-1536x1024.jpg 1536w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/04\/TotemVeteranos-15.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Walter Castro, integrante del Centro de Veteranos de guerra de Malvinas, cont\u00f3 sobre el t\u00f3tem que \u201cen este caso, la petici\u00f3n particular surgi\u00f3 con ayuda, l\u00f3gicamente, de la Municipalidad, de Luis (Ponce), sobre todo, que fue quien nos impuls\u00f3 a este proyecto. Y el acompa\u00f1amiento de todos los bloques, los concejales, realmente, estuvimos el d\u00eda que aprobaron y nos llen\u00f3 de emoci\u00f3n. As\u00ed que a todos agradecidos, a los trabajadores municipales que siempre se portan diez puntos con nosotros, la verdad que es un plantel que tienen impresionante\u201d sostuvo<\/p>\n\n\n\n<p>M\u00e1s adelante tambi\u00e9n agradeci\u00f3 a las y los presentes \u201cque nos acompa\u00f1an a todos lados, con la locura nuestra y con las cosas que se nos ocurren\u201d.<\/p>\n\n\n\n<p>Mario Luna, hermano del Soldado Luna, ca\u00eddo en Malvinas, agradeci\u00f3 a los veteranos, a la comunidad, los trabajadores por el recuerdo y homenaje.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Sentimientos<\/strong><\/p>\n\n\n\n<p>El intendente Ustarroz manifest\u00f3 que le generaba\u201csentimientos muy lindos, &nbsp;el orgullo de contribuir a realizar una acci\u00f3n m\u00e1s en la ciudad que tienda a recordar nuestras Malvinas, a nuestros ca\u00eddos, a quienes fueron a combatir y mantener viva la llama del reclamo justo sobre nuestras islas, sobre nuestra soberan\u00eda, creo que eso es muy valioso, fundamentalmente para las nuevas generaciones y como dec\u00edamos en el \u00faltimo acto, que las nuevas generaciones nos interpelen y que tambi\u00e9n sigan haciendo acciones en pos de mantener viva esta llama tan importante, que como dec\u00eda Mariana, nos une, yo quiero tambi\u00e9n felicitar y celebrar, mejor dicho, la decisi\u00f3n del Honorable Consejo Deliberante que demostr\u00f3 que hay causas que nos unen y que es muy importante, lo dijo Walter, lo que sintieron cuando vieron que todos los representantes de nuestro pueblo apoyaron este monumento, este nuevo espacio en la ciudad de Mercedes\u201d<\/p>\n\n\n\n<p>Tambi\u00e9n quiso \u201cexpresar el orgullo por los trabajadores de la municipalidad, porque adem\u00e1s de haber hecho esto, en tiempo r\u00e9cord arreglaron y acondicionaron todo el espacio y lo hicieron como cada cosa que hacen, con mucho amor, con mucho compromiso\u201d<\/p>\n\n\n\n<p>Antes de finalizar y destacar el valioso aporte que veteranos hacen a nuestra comunidad reafirm\u00f3 que \u201cesto es de todo el pueblo de Mercedes para ustedes, para nuestros queridos veteranos y para sus familiares, much\u00edsimas gracias\u201d<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-attachment-id=\"174810\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2024\/04\/13\/inauguran-totem-en-homenaje-al-centro-de-veteranos-de-guerra-de-malvinas\/totemveteranos-13\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/04\/TotemVeteranos-13.jpg\" data-orig-size=\"2048,1365\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;SEBASTIANAMBROSSIO&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;SebastianAmbrossio&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Inauguran t\u00f3tem en homenaje al Centro de Veteranos de Guerra de Malvinas\" data-image-description=\"&lt;p&gt;Inauguran t\u00f3tem en homenaje al Centro de Veteranos de Guerra de Malvinas&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Inauguran t\u00f3tem en homenaje al Centro de Veteranos de Guerra de Malvinas&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/04\/TotemVeteranos-13-1024x683.jpg\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/04\/TotemVeteranos-13-1024x683.jpg\" alt=\"\" class=\"wp-image-174810\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/04\/TotemVeteranos-13-1024x683.jpg 1024w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/04\/TotemVeteranos-13-630x420.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/04\/TotemVeteranos-13-150x100.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/04\/TotemVeteranos-13-1536x1024.jpg 1536w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/04\/TotemVeteranos-13.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><strong>Merecido<\/strong><\/p>\n\n\n\n<p>La presidenta del Concejo Deliberante, Mariana San Mart\u00edn remarc\u00f3 que \u201ces un homenaje m\u00e1s que merecido, como cada uno de los que se decide hacer a nuestros veteranos, a nuestros ex combatientes. Y en lo particular, en este caso, que fue una petici\u00f3n particular que pas\u00f3 por el Honorable Consejo Deliberante, donde tuvimos la grandeza, el entendimiento, la uni\u00f3n, esa uni\u00f3n que los veteranos nos ense\u00f1aron a tener\u201d manifest\u00f3 y destac\u00f3 que \u201clas Malvinas nos unen, no es un eslogan, es un hecho, tiene que seguir siendo un hecho\u201d<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-attachment-id=\"174812\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2024\/04\/13\/inauguran-totem-en-homenaje-al-centro-de-veteranos-de-guerra-de-malvinas\/totemveteranos-14\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/04\/TotemVeteranos-14.jpg\" data-orig-size=\"2048,1365\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;SEBASTIANAMBROSSIO&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;SebastianAmbrossio&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Inauguran t\u00f3tem en homenaje al Centro de Veteranos de Guerra de Malvinas\" data-image-description=\"&lt;p&gt;Inauguran t\u00f3tem en homenaje al Centro de Veteranos de Guerra de Malvinas&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Inauguran t\u00f3tem en homenaje al Centro de Veteranos de Guerra de Malvinas&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/04\/TotemVeteranos-14-1024x683.jpg\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/04\/TotemVeteranos-14-1024x683.jpg\" alt=\"\" class=\"wp-image-174812\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/04\/TotemVeteranos-14-1024x683.jpg 1024w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/04\/TotemVeteranos-14-630x420.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/04\/TotemVeteranos-14-150x100.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/04\/TotemVeteranos-14-1536x1024.jpg 1536w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/04\/TotemVeteranos-14.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Con una amplia participaci\u00f3n de la ciudadan\u00eda se inaugur\u00f3 el t\u00f3tem en homenaje a nuestros veteranos y ca\u00eddos en Malvinas. &#8230; <a title=\"Inauguran t\u00f3tem en homenaje al Centro de Veteranos de Guerra de Malvinas\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2024\/04\/13\/inauguran-totem-en-homenaje-al-centro-de-veteranos-de-guerra-de-malvinas\/\" aria-label=\"Leer m\u00e1s sobre Inauguran t\u00f3tem en homenaje al Centro de Veteranos de Guerra de Malvinas\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":174809,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[8],"tags":[14753,756],"class_list":["post-174808","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociedad","tag-centro-de-veteranos-de-malvinas","tag-veteranos-de-malvinas","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/04\/TotemVeteranos-1-scaled.jpeg","wps_subtitle":"Acompa\u00f1amiento social","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/174808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=174808"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/174808\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/174809"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=174808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=174808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=174808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}