{"id":175620,"date":"2024-05-13T21:41:59","date_gmt":"2024-05-14T00:41:59","guid":{"rendered":"https:\/\/www.hoymercedes.com.ar\/principal\/?p=175620"},"modified":"2024-05-13T21:42:00","modified_gmt":"2024-05-14T00:42:00","slug":"kicillof-formalizo-mas-apoyo-a-todas-ciudades-de-la-provincia","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2024\/05\/13\/kicillof-formalizo-mas-apoyo-a-todas-ciudades-de-la-provincia\/","title":{"rendered":"Kicillof formaliz\u00f3 m\u00e1s apoyo a todas ciudades de la Provincia"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-attachment-id=\"175621\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2024\/05\/13\/kicillof-formalizo-mas-apoyo-a-todas-ciudades-de-la-provincia\/ustarroz-kicillof\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/05\/Ustarroz-Kicillof.jpg\" data-orig-size=\"1600,1066\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Ustarroz-Kicillof\" data-image-description=\"&lt;p&gt;Kicillof formaliz\u00f3 m\u00e1s apoyo a las ciudades de la Provincia&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Kicillof formaliz\u00f3 m\u00e1s apoyo a las ciudades de la Provincia&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/05\/Ustarroz-Kicillof-1024x682.jpg\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/05\/Ustarroz-Kicillof-1024x682.jpg\" alt=\"Kicillof formaliz\u00f3 m\u00e1s apoyo a las ciudades de la Provincia\" class=\"wp-image-175621\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/05\/Ustarroz-Kicillof-1024x682.jpg 1024w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/05\/Ustarroz-Kicillof-630x420.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/05\/Ustarroz-Kicillof-150x100.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/05\/Ustarroz-Kicillof-1536x1023.jpg 1536w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/05\/Ustarroz-Kicillof-700x465.jpg 700w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/05\/Ustarroz-Kicillof.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Mercedes recibe apoyo de la Provincia de Buenos Aires. El intendente Ustarroz particip\u00f3 de la firma de convenio para recibir fondos del gobierno provincial en momentos en que el gobierno nacional cort\u00f3 todo el apoyoa los municipios del pa\u00eds.En esta ocasi\u00f3n Axel Kicillof, encabez\u00f3 este lunes el acto en el que se firm\u00f3 el segundo desembolso del Fondo de Fortalecimiento Fiscal Municipal, que asciende a $37.549 millones para los 135 distritos. Fue en el Teatro Argentino de La Plata, junto a la vicegobernadora Ver\u00f3nica Magario; los ministros de Econom\u00eda, Pablo L\u00f3pez, y de Gobierno, Carlos Bianco; la jefa de Asesores, Cristina \u00c1lvarez Rodr\u00edguez; intendentas e intendentes bonaerenses.<\/p>\n\n\n\n<p>Kicillof destac\u00f3 que \u201cestamos atravesando una situaci\u00f3n in\u00e9dita en la Argentina, producto de un Gobierno nacional que se ha desentendido de los problemas cotidianos de los argentinos y las argentinas\u201d. \u201cEl federalismo y las atribuciones de la Naci\u00f3n no son optativas: aunque su marco ideol\u00f3gico les diga que todo lo va a resolver el mercado, juraron sobre una Constituci\u00f3n Nacional que les otorga responsabilidades y los hace garantes de determinados derechos\u201d, agreg\u00f3.<\/p>\n\n\n\n<p>\u201cNosotros no pensamos tomar ese ejemplo: en este momento en el que nuestro pueblo est\u00e1 experimentando una angustia muy grande, no le podemos responder con crueldad y ego\u00edsmo, sino con m\u00e1s presencia del Estado y solidaridad entre la Provincia y los municipios para dar respuesta\u201d, expres\u00f3 el Gobernador y a\u00f1adi\u00f3: \u201cLa recesi\u00f3n, la ca\u00edda de la recaudaci\u00f3n y la quita ilegal de fondos por parte del Gobierno nacional impacta sobre la provincia y los distritos: hoy estamos demostrando que el Gobierno provincial no deserta, respeta el federalismo y reconoce la importancia de las y los intendentes\u201d.<\/p>\n\n\n\n<p>La segunda cuota del FFFM representa m\u00e1s del 30% de los $116.000 millones que los distritos recibir\u00e1n este a\u00f1o. Se trata de un instrumento creado en diciembre de 2023 a partir de la Ley N\u00ba15.480, que establece la transferencia de fondos no reintegrables y de libre disponibilidad a partir del Coeficiente \u00danico de Distribuci\u00f3n (CUD).<\/p>\n\n\n\n<p>\u201cFrente a un Gobierno nacional que decidi\u00f3 interrumpir las transferencias de recursos a las provincias, nosotros cumplimos con la Ley y les damos apoyo a los municipios en este contexto tan dif\u00edcil\u201d, sostuvo L\u00f3pez y agreg\u00f3: \u201cCon esta segunda cuota del FFFM, ya distribuimos este a\u00f1o cerca de $50 mil millones entre todos los distritos bonaerenses\u201d.<\/p>\n\n\n\n<p>Este desembolso se da en el marco de un in\u00e9dito ajuste del Gobierno nacional que est\u00e1 afectando la recaudaci\u00f3n de la provincia y los municipios. La provincia de Buenos Aires fue la m\u00e1s afectada por el recorte de transferencias no autom\u00e1ticas de la Naci\u00f3n: a abril de este a\u00f1o, implic\u00f3 un recorte de un bill\u00f3n de pesos, monto que alcanzar\u00eda para financiar m\u00e1s de un a\u00f1o del Servicio Alimentario Escolar. Asimismo, los municipios han sufrido una p\u00e9rdida de coparticipaci\u00f3n de $88.000 que equivale a casi la mitad de su masa salarial neta.<\/p>\n\n\n\n<p>\u201cNuestro compromiso es trabajar codo a codo con las y los intendentes para amortiguar los efectos de las pol\u00edticas econ\u00f3micas y la deserci\u00f3n del Gobierno nacional\u201d, resalt\u00f3 Kicillof y concluy\u00f3: \u201cInvito a todos y todas las intendentes a que sean parte de los reclamos que impulsamos para defender a la provincia de Buenos Aires\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mercedes recibe apoyo de la Provincia de Buenos Aires. El intendente Ustarroz particip\u00f3 de la firma de convenio para recibir &#8230; <a title=\"Kicillof formaliz\u00f3 m\u00e1s apoyo a todas ciudades de la Provincia\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2024\/05\/13\/kicillof-formalizo-mas-apoyo-a-todas-ciudades-de-la-provincia\/\" aria-label=\"Leer m\u00e1s sobre Kicillof formaliz\u00f3 m\u00e1s apoyo a todas ciudades de la Provincia\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":175621,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[8881],"tags":[17619,19476,424],"class_list":["post-175620","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-axel-kicillof","tag-fondos-de-la-provincia","tag-ustarroz","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/05\/Ustarroz-Kicillof.jpg","wps_subtitle":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/175620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=175620"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/175620\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/175621"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=175620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=175620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=175620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}