{"id":177694,"date":"2024-08-05T07:16:00","date_gmt":"2024-08-05T10:16:00","guid":{"rendered":"https:\/\/www.hoymercedes.com.ar\/principal\/?p=177694"},"modified":"2024-08-05T00:22:01","modified_gmt":"2024-08-05T03:22:01","slug":"la-fiesta-de-la-galleta-con-masiva-asistencia-en-tomas-jofre","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2024\/08\/05\/la-fiesta-de-la-galleta-con-masiva-asistencia-en-tomas-jofre\/","title":{"rendered":"La Fiesta de la Galleta con masiva asistencia en Tom\u00e1s Jofr\u00e9"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-attachment-id=\"177695\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2024\/08\/05\/la-fiesta-de-la-galleta-con-masiva-asistencia-en-tomas-jofre\/sja_9048\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/SJA_9048.jpg\" data-orig-size=\"1319,879\" data-comments-opened=\"0\" data-image-title=\"La Fiesta de la Galleta con masiva asistencia en Tom\u00e1s Jofr\u00e9\" data-image-description=\"&lt;p&gt;La Fiesta de la Galleta con masiva asistencia en Tom\u00e1s Jofr\u00e9&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;La Fiesta de la Galleta con masiva asistencia en Tom\u00e1s Jofr\u00e9&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/SJA_9048-1024x682.jpg\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/SJA_9048-1024x682.jpg\" alt=\"La Fiesta de la Galleta con masiva asistencia en Tom\u00e1s Jofr\u00e9\" class=\"wp-image-177695\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/SJA_9048-1024x682.jpg 1024w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/SJA_9048-630x420.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/SJA_9048-150x100.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/SJA_9048-700x465.jpg 700w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/SJA_9048.jpg 1319w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La <strong>Fiesta de la galleta de Campo<\/strong> convoc\u00f3 a miles de turistas. Fue en la <strong>plaza Domingo Silvano<\/strong>, en <strong>Tom\u00e1s Jofr\u00e9<\/strong>, conmemorando el d\u00eda del panadero. Shows en vivo, gastronom\u00eda, restaurantes repletos, artesanos, feria y la mejor galleta de la regi\u00f3n. Con apoyo de la <strong>Provincia<\/strong> se concret\u00f3 la <strong>7\u00b0 edici\u00f3n<\/strong>. El <strong>intendente Ustarroz<\/strong> agradeci\u00f3 \u201ca quienes hicieron posible esta hermosa fiesta y a cada visitante, impulsando el trabajo, la cultura, el turismo y en encuentro en nuestro pueblo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Celebraci\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El intendente <strong>Juan Ustarroz<\/strong> remarc\u00f3 lo lindo de estar \u201ccelebrando el D\u00eda del Panadero en esta fiesta y este marco\u201d y \u201cfelicitamos a todas y todos por el enorme trabajo\u201d destacando que \u201cson oficios realmente muy importantes\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEstamos muy contentos de esta fiesta. Quiero tambi\u00e9n agradecer a todas y todos los que lo hacen posible, a las y los trabajadores y trabajadoras municipales. A los artesanos, restaurantes, puesteros, a cada turista\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Remarc\u00f3 que \u201cen estos tiempos dif\u00edciles, ver tanta gente, con un estado que acompa\u00f1a, que promueve, es muy importante, por eso muchas gracias por venir y visitar nuestras fiestas, nuestros pueblos, apoyando la cultura, el trabajo y el encuentro\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" data-attachment-id=\"177696\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2024\/08\/05\/la-fiesta-de-la-galleta-con-masiva-asistencia-en-tomas-jofre\/mhm_4228\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/MHM_4228.jpg\" data-orig-size=\"1316,879\" data-comments-opened=\"0\" data-image-title=\"La Fiesta de la Galleta con masiva asistencia en Tom\u00e1s Jofr\u00e9\" data-image-description=\"&lt;p&gt;La Fiesta de la Galleta con masiva asistencia en Tom\u00e1s Jofr\u00e9&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;La Fiesta de la Galleta con masiva asistencia en Tom\u00e1s Jofr\u00e9&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/MHM_4228-1024x684.jpg\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/MHM_4228-1024x684.jpg\" alt=\"La Fiesta de la Galleta con masiva asistencia en Tom\u00e1s Jofr\u00e9\" class=\"wp-image-177696\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/MHM_4228-1024x684.jpg 1024w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/MHM_4228-630x421.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/MHM_4228-150x100.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/MHM_4228.jpg 1316w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fiesta<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Francisco Dinova<\/strong>, director de turismo, expreso que \u201ces una alegr\u00eda ver esta plaza colmada\u201d pidiendo un fuerte aplauso para las y los panaderos \u201cno solo los que nos acompa\u00f1an hoy, a todos, porque hoy es su d\u00eda. Esta fiesta nace en homenaje a esas panader\u00edas que todav\u00eda sostienen esos viejos hornos a le\u00f1a, la tradici\u00f3n y cultura del interior a la hora de elaborar el producto que tanto nos gusta\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aprovech\u00f3 para \u201cagradecerle a las y los trabajadores municipales, a las cooperativas, a todos los productores y por sobre todo a los feriantes de esta plaza, que todos los fines de semana atienden a los visitantes, con fr\u00edo, con calor, llueva, ellos siempre est\u00e1n\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Provincia de Buenos Aires acompa\u00f1\u00f3 la fiesta no s\u00f3lo en su infraestructura, sino tambi\u00e9n con espacio de juego del programa \u201cRecreo\u201d y banco provincia con un stand propio.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-attachment-id=\"177697\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2024\/08\/05\/la-fiesta-de-la-galleta-con-masiva-asistencia-en-tomas-jofre\/dsc00654\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/DSC00654.jpg\" data-orig-size=\"1319,879\" data-comments-opened=\"0\" data-image-title=\"La Fiesta de la Galleta con masiva asistencia en Tom\u00e1s Jofr\u00e9\" data-image-description=\"&lt;p&gt;La Fiesta de la Galleta con masiva asistencia en Tom\u00e1s Jofr\u00e9&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;La Fiesta de la Galleta con masiva asistencia en Tom\u00e1s Jofr\u00e9&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/DSC00654-1024x682.jpg\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/DSC00654-1024x682.jpg\" alt=\"La Fiesta de la Galleta con masiva asistencia en Tom\u00e1s Jofr\u00e9\" class=\"wp-image-177697\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/DSC00654-1024x682.jpg 1024w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/DSC00654-630x420.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/DSC00654-150x100.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/DSC00654-700x465.jpg 700w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/DSC00654.jpg 1319w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Reconocimientos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hubo reconocimiento para la panader\u00eda \u201cLa espiga de oro\u201d entregado por <strong>Mart\u00edn Boragno<\/strong> y el jefe comunal. Tambi\u00e9n a <strong>Minino Silvano<\/strong> por parte de la Asociaci\u00f3n Empresaria Hotelera Gastron\u00f3mica y Pastelera de la Ciudad de La Plata y su Zona de Influencia por el centenario de su restaurante en Jofr\u00e9 que el s\u00e1bado pr\u00f3ximo tendr\u00e1 su gran fiesta recibiendo tambi\u00e9n de los Amigos del Restaurante Silvano, un grupo de personas que reconoce la tarea de la familia Silvano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Gran ganador<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con 116 puntos el segundo lugar fue para <strong>\u201cEl Triunfo\u201d <\/strong>de Tom\u00e1s Jofr\u00e9 mientras que con 148 el primer premio fue para <strong>\u201cLa Dulce Anita\u201d<\/strong> quienes con emoci\u00f3n celebraron sobre el escenario el reconocimiento.<br><br><strong>Miguel Huici,<\/strong> a la hora de tomar la palabra, representando a su familia, coment\u00f3 que \u201cestamos muy felices\u201d y \u201cno hay nada m\u00e1s lindo que en el d\u00eda del panadero recibir este reconocimiento\u201d dijo y \u201cagradezco a mi familia que me acompa\u00f1a, a todos los que est\u00e1n en la panader\u00eda, es un honor recibir este reconocimiento. Quiero agradecer a Juani, nuestro intendente por el apoyo, a Fran, porque tenemos esta fiesta los que trabajamos tradicionalmente\u201d expres\u00f3.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-attachment-id=\"177698\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2024\/08\/05\/la-fiesta-de-la-galleta-con-masiva-asistencia-en-tomas-jofre\/dsc00606\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/DSC00606.jpg\" data-orig-size=\"1319,879\" data-comments-opened=\"0\" data-image-title=\"La Fiesta de la Galleta con masiva asistencia en Tom\u00e1s Jofr\u00e9\" data-image-description=\"&lt;p&gt;La Fiesta de la Galleta con masiva asistencia en Tom\u00e1s Jofr\u00e9&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;La Fiesta de la Galleta con masiva asistencia en Tom\u00e1s Jofr\u00e9&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/DSC00606-1024x682.jpg\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/DSC00606-1024x682.jpg\" alt=\"La Fiesta de la Galleta con masiva asistencia en Tom\u00e1s Jofr\u00e9\" class=\"wp-image-177698\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/DSC00606-1024x682.jpg 1024w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/DSC00606-630x420.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/DSC00606-150x100.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/DSC00606-700x465.jpg 700w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/DSC00606.jpg 1319w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Multitud<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tanto el ingreso como el egreso del pueblo fueron lento. La gran cantidad de turistas y vecinos presentes dieron un marco magn\u00edfico. En los restaurantes el lleno era total, con largas colas incluso hasta muy entrada la tarde, donde nadie quer\u00eda irse sin probar la gastronom\u00eda local. Los locales todos llenos y el paseo con incesante andar de p\u00fablico.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-attachment-id=\"177699\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2024\/08\/05\/la-fiesta-de-la-galleta-con-masiva-asistencia-en-tomas-jofre\/sja_8877\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/SJA_8877.jpg\" data-orig-size=\"1319,879\" data-comments-opened=\"0\" data-image-title=\"La Fiesta de la Galleta con masiva asistencia en Tom\u00e1s Jofr\u00e9\" data-image-description=\"&lt;p&gt;La Fiesta de la Galleta con masiva asistencia en Tom\u00e1s Jofr\u00e9&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;La Fiesta de la Galleta con masiva asistencia en Tom\u00e1s Jofr\u00e9&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/SJA_8877-1024x682.jpg\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/SJA_8877-1024x682.jpg\" alt=\"La Fiesta de la Galleta con masiva asistencia en Tom\u00e1s Jofr\u00e9\" class=\"wp-image-177699\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/SJA_8877-1024x682.jpg 1024w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/SJA_8877-630x420.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/SJA_8877-150x100.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/SJA_8877-700x465.jpg 700w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/SJA_8877.jpg 1319w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-attachment-id=\"177701\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2024\/08\/05\/la-fiesta-de-la-galleta-con-masiva-asistencia-en-tomas-jofre\/dsc00622\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/DSC00622.jpg\" data-orig-size=\"1319,879\" data-comments-opened=\"0\" data-image-title=\"La Fiesta de la Galleta con masiva asistencia en Tom\u00e1s Jofr\u00e9\" data-image-description=\"&lt;p&gt;La Fiesta de la Galleta con masiva asistencia en Tom\u00e1s Jofr\u00e9&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;La Fiesta de la Galleta con masiva asistencia en Tom\u00e1s Jofr\u00e9&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/DSC00622-1024x682.jpg\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/DSC00622-1024x682.jpg\" alt=\"La Fiesta de la Galleta con masiva asistencia en Tom\u00e1s Jofr\u00e9\" class=\"wp-image-177701\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/DSC00622-1024x682.jpg 1024w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/DSC00622-630x420.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/DSC00622-150x100.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/DSC00622-700x465.jpg 700w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/DSC00622.jpg 1319w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La Fiesta de la galleta de Campo convoc\u00f3 a miles de turistas. Fue en la plaza Domingo Silvano, en Tom\u00e1s &#8230; <a title=\"La Fiesta de la Galleta con masiva asistencia en Tom\u00e1s Jofr\u00e9\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2024\/08\/05\/la-fiesta-de-la-galleta-con-masiva-asistencia-en-tomas-jofre\/\" aria-label=\"Leer m\u00e1s sobre La Fiesta de la Galleta con masiva asistencia en Tom\u00e1s Jofr\u00e9\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":177695,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[30],"tags":[9912,19547,405],"class_list":["post-177694","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipio","tag-fiesta-de-la-galleta","tag-fiestas-populares-en-mercedes","tag-turismo-en-mercedes","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"wps_subtitle":"Fiestas Populares","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2024\/08\/SJA_9048.jpg","_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/177694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=177694"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/177694\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/177695"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=177694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=177694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=177694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}