{"id":182019,"date":"2025-01-21T12:45:00","date_gmt":"2025-01-21T15:45:00","guid":{"rendered":"https:\/\/www.hoymercedes.com.ar\/principal\/?p=182019"},"modified":"2025-01-21T12:45:02","modified_gmt":"2025-01-21T15:45:02","slug":"salud-servicios-publicos-y-asuntos-viales-los-principales-reclamos-en-la-defensoria-durante-2024","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2025\/01\/21\/salud-servicios-publicos-y-asuntos-viales-los-principales-reclamos-en-la-defensoria-durante-2024\/","title":{"rendered":"Salud, servicios p\u00fablicos y asuntos viales, los principales reclamos en la Defensor\u00eda durante 2024"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-attachment-id=\"182020\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2025\/01\/21\/salud-servicios-publicos-y-asuntos-viales-los-principales-reclamos-en-la-defensoria-durante-2024\/defensoria-reclamos\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2025\/01\/Defensoria-Reclamos.jpg\" data-orig-size=\"1600,1600\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Defensoria-Reclamos\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2025\/01\/Defensoria-Reclamos-1024x1024.jpg\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2025\/01\/Defensoria-Reclamos-1024x1024.jpg\" alt=\"\" class=\"wp-image-182020\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2025\/01\/Defensoria-Reclamos-1024x1024.jpg 1024w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2025\/01\/Defensoria-Reclamos-620x620.jpg 620w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2025\/01\/Defensoria-Reclamos-150x150.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2025\/01\/Defensoria-Reclamos-1536x1536.jpg 1536w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2025\/01\/Defensoria-Reclamos.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>La Defensor\u00eda del Pueblo bonaerense cerr\u00f3 2024 con los reclamos relacionados a la salud, los servicios p\u00fablicos y los asuntos viales al tope del ranking de consultas realizadas por las y los bonaerenses durante el a\u00f1o pasado.<br>El organismo que conduce Guido Lorenzino recibi\u00f3 quejas vinculadas a las m\u00faltiples tem\u00e1ticas que trabaja, por medio de las distintas bocas de reclamos que posee: su Sede Central, las delegaciones, sus v\u00edas de comunicaci\u00f3n tradicionales y las redes sociales.<\/p>\n\n\n\n<p><br>De esta manera, el podio de reclamos qued\u00f3 formado por las consultas relacionadas a la salud (26,01%), los servicios p\u00fablicos (18,41%) y los asuntos viales (12,51%). M\u00e1s atr\u00e1s quedaron los que tienen que ver con los bienes de consumo y servicios privados (8,56%), asociaciones civiles (7,72%) y el trabajo y seguridad social (4,14%).<\/p>\n\n\n\n<p><br>En relaci\u00f3n a las v\u00edas de contacto, las delegaciones fueron quienes m\u00e1s reclamos recibieron, con un 29,36%. El ranking se completa con las recibidas por tel\u00e9fono (27,74%) y por WhatsApp (17,85%).<\/p>\n\n\n\n<p><br>\u201cUno de los pilares de nuestra gesti\u00f3n es estar cada vez m\u00e1s presentes en el territorio. Hoy tenemos 63 delegaciones en toda la Provincia que recibieron un 20% m\u00e1s de reclamos que en 2023. Consideramos central acercarnos cada vez m\u00e1s a la gente para que puedan resolver sus problemas\u201d, expres\u00f3 Lorenzino.<\/p>\n\n\n\n<p><br>La Defensor\u00eda cuenta con un contact center en el cual personal especializado atiende todos los d\u00edas las 24 horas a trav\u00e9s del WhatsApp 221 358-1323, de la l\u00ednea gratuita 0800-222-5262, por redes sociales buscando @defensoriaPBA, y tambi\u00e9n por la p\u00e1gina web www.defensorba.org.ar.<\/p>\n\n\n\n<p><br>Tambi\u00e9n se atienden reclamos presencialmente en la sede central de La Plata, en calle 50 N\u00b0687 entre 8 y 9, o en cualquiera de las m\u00e1s de 60 delegaciones que el organismo tiene en distintos puntos de la Provincia y cuya ubicaci\u00f3n se puede consultar en la web.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Defensor\u00eda del Pueblo bonaerense cerr\u00f3 2024 con los reclamos relacionados a la salud, los servicios p\u00fablicos y los asuntos &#8230; <a title=\"Salud, servicios p\u00fablicos y asuntos viales, los principales reclamos en la Defensor\u00eda durante 2024\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2025\/01\/21\/salud-servicios-publicos-y-asuntos-viales-los-principales-reclamos-en-la-defensoria-durante-2024\/\" aria-label=\"Leer m\u00e1s sobre Salud, servicios p\u00fablicos y asuntos viales, los principales reclamos en la Defensor\u00eda durante 2024\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":182020,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[8881],"tags":[20183],"class_list":["post-182019","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-defensoria-del-pueblo-2","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2025\/01\/Defensoria-Reclamos.jpg","wps_subtitle":"Bonaerenses","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/182019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=182019"}],"version-history":[{"count":2,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/182019\/revisions"}],"predecessor-version":[{"id":182022,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/182019\/revisions\/182022"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/182020"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=182019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=182019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=182019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}