{"id":189387,"date":"2025-11-04T08:15:32","date_gmt":"2025-11-04T11:15:32","guid":{"rendered":"https:\/\/www.hoymercedes.com.ar\/principal\/?p=189387"},"modified":"2025-11-04T08:15:35","modified_gmt":"2025-11-04T11:15:35","slug":"finalizo-una-nueva-edicion-de-octubre-mes-del-grabado","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2025\/11\/04\/finalizo-una-nueva-edicion-de-octubre-mes-del-grabado\/","title":{"rendered":"Finaliz\u00f3 una nueva edici\u00f3n de \u00abOctubre, mes del grabado\u00bb"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-attachment-id=\"189388\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2025\/11\/04\/finalizo-una-nueva-edicion-de-octubre-mes-del-grabado\/aa1\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2025\/11\/AA1.jpg\" data-orig-size=\"1319,879\" data-comments-opened=\"0\" data-image-title=\"Finaliz\u00f3 una nueva edici\u00f3n de \u00abOctubre, mes del grabado\u00bb\" data-image-description=\"&lt;p&gt;Finaliz\u00f3 una nueva edici\u00f3n de \u00abOctubre, mes del grabado\u00bb&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Finaliz\u00f3 una nueva edici\u00f3n de \u00abOctubre, mes del grabado\u00bb&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2025\/11\/AA1-1024x682.jpg\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2025\/11\/AA1-1024x682.jpg\" alt=\"\" class=\"wp-image-189388\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2025\/11\/AA1-1024x682.jpg 1024w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2025\/11\/AA1-630x420.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2025\/11\/AA1-150x100.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2025\/11\/AA1-700x465.jpg 700w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2025\/11\/AA1.jpg 1319w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Se entregaron los premios del certamen xilogr\u00e1fico en el Honorable Concejo Deliberante. El primer premio se fue para Campana y dos mercedinas estuvieron en el podio. Ya se piensa en la edici\u00f3n del pr\u00f3ximo a\u00f1o con nuevas propuestas. \u201cEstamos muy felices de c\u00f3mo se vivi\u00f3 todo el mes, con la asistencia, la calidad y creatividad art\u00edstica, con el compromiso de todas y todos los que lo hicieron posible\u201d dijo la directora de cultura, <\/em><strong><em>Jimena Rivas<\/em><\/strong><em> quien reiter\u00f3 \u201cha sido un proceso muy gratificante y esperamos con ansias volvamos pronto a vivirlo\u201d<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Finaliz\u00f3<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Culmin\u00f3 octubre y con \u00e9l, el mes del grabado en Mercedes. El evento cuenta con siete ediciones en las que siempre fue aumentando la calidad y cantidad de contenidos, los participantes en sus talleres y charlas y la masiva aceptaci\u00f3n por parte del p\u00fablico amante del arte visual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El s\u00e1bado se cerraron las puertas de la etapa 2025 en el Honorable Concejo Deliberante con la entrega de premios del certamen de xilograf\u00eda que se llev\u00f3 a cabo a mediados de mes con una veintena de participantes de distintos puntos de la Provincia de Buenos Aires que salieron a la calle a captar sensaciones, geograf\u00edas, estructuras y caracter\u00edsticas esenciales de la ciudad de acobija la t\u00e9cnica del taco y la tinta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La entrega de premios cont\u00f3 con la presencia de los participantes y las autoridades que dieron forma al mes del grabado: Jimena Rivas, Directora de Cultura, Pablo Russo e Ismael moyano, responsables del Movimiento Cultural El Limonero y Anabella Coluccio, Coordinadora del Museo de Arte; todos recibidos afectuosamente por la edil y presidenta del HCD, Dra. Mariana San Mart\u00edn, quien agradeci\u00f3 a todos por estar y visitar el espacio que est\u00e1 tan cerca del coraz\u00f3n de todos los mercedinos y mercedinas. Por su parte, la titular de Cultura tambi\u00e9n destac\u00f3 el trabajo de los mentores y promotores del mes del grabado y celebr\u00f3 la importancia que tienen estos eventos en un escenario cotidiano dif\u00edcil a nivel nacional: \u201cque estas propuestas puedan suceder y que haya tanta direccionalidad a la promoci\u00f3n del desarrollo art\u00edstico es gracias a todas las partes interesadas en que as\u00ed deba ser. Nosotros estamos para escuchar, facilitar y promover todas estas manifestaciones\u201d, <strong>expres\u00f3 Rivas.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-attachment-id=\"189389\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2025\/11\/04\/finalizo-una-nueva-edicion-de-octubre-mes-del-grabado\/aaa\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2025\/11\/AAA.jpg\" data-orig-size=\"1319,879\" data-comments-opened=\"0\" data-image-title=\"AAA\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2025\/11\/AAA-1024x682.jpg\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2025\/11\/AAA-1024x682.jpg\" alt=\"Finaliz\u00f3 una nueva edici\u00f3n de &quot;Octubre, mes del grabado&quot;\" class=\"wp-image-189389\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2025\/11\/AAA-1024x682.jpg 1024w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2025\/11\/AAA-630x420.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2025\/11\/AAA-150x100.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2025\/11\/AAA-700x465.jpg 700w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2025\/11\/AAA.jpg 1319w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">De inmediato, el artista Pablo Russo tambi\u00e9n reconoci\u00f3 la importancia de esta edici\u00f3n en Mercedes teniendo en cuenta que tuvo la particular distinci\u00f3n por parte de la Honorable C\u00e1mara de Diputados de declarar al evento de inter\u00e9s cultural&nbsp; a trav\u00e9s de la Diputada Sabrina Selva. Adem\u00e1s, aprovech\u00f3 para reconocer el trabajo desinteresado de todos los actores que fueron parte de esta edici\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un clima festivo, se entregaron las menciones especiales y los premios m\u00e1s importantes que tuvieron a dos mercedinas ubicadas entre los tres mejores trabajos: Laura Gianfrini, con el 2do puesto y Araceli Mar\u00edn, en el tercer lugar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ganadora del certamen de xilograf\u00eda fue la campanense Carolina Pisetta, quien mostr\u00f3 su felicidad al poder estar en el concurso despu\u00e9s de tantos a\u00f1os sin poder lograrlo: \u201cEstoy feliz porque recorrimos los lugares m\u00e1s t\u00edpicos de la ciudad y con eso pude trabajar en una composici\u00f3n que habla del oficio del grabado y adem\u00e1s pude reflejar la pulper\u00eda en la obra junto con la flor de cardo, algo que no pod\u00eda dejar afuera de mi trabajo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Octubre, mes del grabado fue posible gracias al esfuerzo f\u00edsico e intelectual de muchos agentes p\u00fablicos y privados que se unieron para continuar con el legado que se est\u00e1 replicando en muchos puntos del pa\u00eds a partir de lo que a\u00f1o tras a\u00f1o sucede en Mercedes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La pr\u00f3xima edici\u00f3n 2026 ser\u00e1 la octava y con ella llegar\u00e1n m\u00e1s propuestas de charlas y talleres, adem\u00e1s de nuevas muestras y concursos que seguramente traer\u00e1n nuevos participantes y un n\u00famero a\u00fan mayor de artistas presentes en cada propuesta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se entregaron los premios del certamen xilogr\u00e1fico en el Honorable Concejo Deliberante. El primer premio se fue para Campana y &#8230; <a title=\"Finaliz\u00f3 una nueva edici\u00f3n de \u00abOctubre, mes del grabado\u00bb\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2025\/11\/04\/finalizo-una-nueva-edicion-de-octubre-mes-del-grabado\/\" aria-label=\"Leer m\u00e1s sobre Finaliz\u00f3 una nueva edici\u00f3n de \u00abOctubre, mes del grabado\u00bb\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":189388,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[104],"tags":[522,19279,8442,20813,2558],"class_list":["post-189387","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","tag-el-limonero","tag-jimena-rivas","tag-mariana-san-martin","tag-octubre-mes-del-grabado","tag-pablo-russo","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"wps_subtitle":"","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2025\/11\/AA1.jpg","_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/189387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=189387"}],"version-history":[{"count":1,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/189387\/revisions"}],"predecessor-version":[{"id":189390,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/189387\/revisions\/189390"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/189388"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=189387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=189387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=189387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}