{"id":195804,"date":"2026-05-07T21:15:00","date_gmt":"2026-05-08T00:15:00","guid":{"rendered":"https:\/\/www.hoymercedes.com.ar\/principal\/?p=195804"},"modified":"2026-05-07T20:56:57","modified_gmt":"2026-05-07T23:56:57","slug":"el-peronismo-de-mercedes-recordo-a-evita","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2026\/05\/07\/el-peronismo-de-mercedes-recordo-a-evita\/","title":{"rendered":"El peronismo de Mercedes record\u00f3 a Evita"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-attachment-id=\"195805\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2026\/05\/07\/el-peronismo-de-mercedes-recordo-a-evita\/dsc02648-2\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/DSC02648.jpg\" data-orig-size=\"1319,879\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"El peronismo de Mercedes record\u00f3 a Evita con un fuerte llamado a la unidad y la movilizaci\u00f3n\" data-image-description=\"&lt;p&gt;El peronismo de Mercedes record\u00f3 a Evita con un fuerte llamado a la unidad y la movilizaci\u00f3n&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;El peronismo de Mercedes record\u00f3 a Evita con un fuerte llamado a la unidad y la movilizaci\u00f3n&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/DSC02648-1024x682.jpg\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/DSC02648-1024x682.jpg\" alt=\"\" class=\"wp-image-195805\" style=\"width:1040px;height:auto\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/DSC02648-1024x682.jpg 1024w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/DSC02648-630x420.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/DSC02648-150x100.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/DSC02648.jpg 1319w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>En un emotivo acto frente a su busto referentes de diversas agrupaciones peronistas conmemoraron el natalicio de Eva Per\u00f3n.<\/p>\n\n\n\n<p>Durante la actividad, se criticaron las pol\u00edticas del gobierno nacional y se anunci\u00f3 un gran encuentro partidario para el pr\u00f3ximo 30 de mayo.<\/p>\n\n\n\n<p>Bajo la consigna de que \u00abEvita es presente y futuro\u00bb, la militancia peronista de Mercedes se congreg\u00f3 este jueves para homenajear a la \u00abAbanderada de los Humildes\u00bb en un nuevo aniversario de su nacimiento. El encuentro, que logr\u00f3 reunir a las distintas l\u00edneas y agrupaciones que componen el movimiento local, estuvo marcado por un clima de reflexi\u00f3n frente a la coyuntura pol\u00edtica actual y una fuerte impronta art\u00edstica.<\/p>\n\n\n\n<p>La propuesta cont\u00f3 con un intermedio musical que aport\u00f3 calidez y sensibilidad al homenaje, de la mano de las presentaciones de Jo Marcel, Franco Ram\u00edrez y Piti, quienes interpretaron temas que resonaron con la identidad del campo nacional y popular.<\/p>\n\n\n\n<p>El presidente del Partido, Juani Ustarroz sostuvo: \u00abLa justicia social es una realidad que hoy quieren deplorar\u00bb leyendo un mensaje escrito por una \u00abcompa\u00f1era que no pudo venir\u00bb<\/p>\n\n\n\n<p>En un gesto que destac\u00f3 la calidad de la militancia local, inici\u00f3 su discurso leyendo un texto escrito por una compa\u00f1era que no pudo asistir por razones familiares. \u00abEva Per\u00f3n fue la voz de quienes durante mucho tiempo no fueron escuchados. Su amor por los humildes y su convicci\u00f3n siguen siendo bandera de quienes creen en una patria m\u00e1s justa\u00bb, ley\u00f3 el mandatario.<\/p>\n\n\n\n<p>Al tomar la palabra con sus propias reflexiones, Ustarroz defendi\u00f3 el legado hist\u00f3rico del peronismo frente a los ataques de la actual gesti\u00f3n nacional: \u00abEsa historia de hacer realidad la justicia social, hoy es deplorada por la extrema derecha. Pero, la justicia social fue una realidad en la Argentina a trav\u00e9s de los planes quinquenales, las universidades gratuitas y los planes de vivienda\u00bb, afirm\u00f3.<\/p>\n\n\n\n<p>Aprovech\u00f3 el marco del homenaje para lanzar una convocatoria pol\u00edtica clave: \u00abPara luchar los peronistas nos organizamos. Por eso, este 30 de mayo vamos a hacer un gran encuentro peronista en Mercedes, donde todas las agrupaciones coincidimos y trabajamos en unidad\u00bb. Seg\u00fan Ustarroz, la unidad es \u00abel mejor homenaje que le podemos hacer a Evita y a Per\u00f3n\u00bb.<\/p>\n\n\n\n<p>Nora Alvarado expres\u00f3 que: \u00abSi estuviera Evita, nos dir\u00eda que reclamemos y lo hagamos con fuerza e incluso en las calles\u00bb<\/p>\n\n\n\n<p>Por su parte, \u00abNorita\u00bb, brind\u00f3 un discurso cargado de vehemencia, apelando a la hist\u00f3rica \u00abgarra\u00bb de las mujeres peronistas. Alvarado no ahorr\u00f3 cr\u00edticas hacia el contexto actual, calificando al gobierno como \u00abun t\u00edtere de la derecha\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-attachment-id=\"195806\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2026\/05\/07\/el-peronismo-de-mercedes-recordo-a-evita\/dsc02527-2\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/DSC02527.jpg\" data-orig-size=\"1319,879\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"El peronismo de Mercedes record\u00f3 a Evita con un fuerte llamado a la unidad y la movilizaci\u00f3n\" data-image-description=\"&lt;p&gt;El peronismo de Mercedes record\u00f3 a Evita con un fuerte llamado a la unidad y la movilizaci\u00f3n&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;El peronismo de Mercedes record\u00f3 a Evita con un fuerte llamado a la unidad y la movilizaci\u00f3n&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/DSC02527-1024x682.jpg\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/DSC02527-1024x682.jpg\" alt=\"\" class=\"wp-image-195806\" style=\"width:1060px;height:auto\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/DSC02527-1024x682.jpg 1024w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/DSC02527-630x420.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/DSC02527-150x100.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/DSC02527.jpg 1319w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>\u00abEs doloroso ver lo que pasa con los abuelos y los ni\u00f1os, todo lo que ella amaba\u00bb, expres\u00f3 conmovida. En un llamado directo a la acci\u00f3n militante, Alvarado sentenci\u00f3: \u00abSi estuviera Evita, \u00bfsaben qu\u00e9 har\u00eda? Dir\u00eda: &#8216;Mujeres, tomemos las calles. Hombres, salgan a la calle&#8217;. En nombre de Eva, de Per\u00f3n, de N\u00e9stor y de Cristina, salgamos a luchar y no nos callemos\u00bb.<\/p>\n\n\n\n<p>El acto concluy\u00f3 con la tradicional marcha partidaria, reafirmando el compromiso de las distintas agrupaciones de Mercedes de trabajar de manera conjunta. La conmemoraci\u00f3n no solo sirvi\u00f3 para recordar el pasado, sino para trazar una hoja de ruta hacia el encuentro del 30 de mayo, con el objetivo de \u00abforjar el presente y el futuro que el pueblo necesita\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-attachment-id=\"195807\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2026\/05\/07\/el-peronismo-de-mercedes-recordo-a-evita\/dsc02572\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/DSC02572.jpg\" data-orig-size=\"1319,879\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"El peronismo de Mercedes record\u00f3 a Evita con un fuerte llamado a la unidad y la movilizaci\u00f3n\" data-image-description=\"&lt;p&gt;El peronismo de Mercedes record\u00f3 a Evita con un fuerte llamado a la unidad y la movilizaci\u00f3n&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;El peronismo de Mercedes record\u00f3 a Evita con un fuerte llamado a la unidad y la movilizaci\u00f3n&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/DSC02572-1024x682.jpg\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/DSC02572-1024x682.jpg\" alt=\"\" class=\"wp-image-195807\" style=\"width:1059px;height:auto\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/DSC02572-1024x682.jpg 1024w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/DSC02572-630x420.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/DSC02572-150x100.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/DSC02572.jpg 1319w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-attachment-id=\"195808\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2026\/05\/07\/el-peronismo-de-mercedes-recordo-a-evita\/dsc02659\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/DSC02659.jpg\" data-orig-size=\"1319,879\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"El peronismo de Mercedes record\u00f3 a Evita con un fuerte llamado a la unidad y la movilizaci\u00f3n\" data-image-description=\"&lt;p&gt;El peronismo de Mercedes record\u00f3 a Evita con un fuerte llamado a la unidad y la movilizaci\u00f3n&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;El peronismo de Mercedes record\u00f3 a Evita con un fuerte llamado a la unidad y la movilizaci\u00f3n&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/DSC02659-1024x682.jpg\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/DSC02659-1024x682.jpg\" alt=\"\" class=\"wp-image-195808\" style=\"width:1057px;height:auto\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/DSC02659-1024x682.jpg 1024w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/DSC02659-630x420.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/DSC02659-150x100.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/DSC02659.jpg 1319w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-attachment-id=\"195809\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2026\/05\/07\/el-peronismo-de-mercedes-recordo-a-evita\/dsc02544\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/DSC02544.jpg\" data-orig-size=\"1319,879\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"El peronismo de Mercedes record\u00f3 a Evita con un fuerte llamado a la unidad y la movilizaci\u00f3n\" data-image-description=\"&lt;p&gt;El peronismo de Mercedes record\u00f3 a Evita con un fuerte llamado a la unidad y la movilizaci\u00f3n&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;El peronismo de Mercedes record\u00f3 a Evita con un fuerte llamado a la unidad y la movilizaci\u00f3n&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/DSC02544-1024x682.jpg\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/DSC02544-1024x682.jpg\" alt=\"\" class=\"wp-image-195809\" style=\"width:1051px;height:auto\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/DSC02544-1024x682.jpg 1024w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/DSC02544-630x420.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/DSC02544-150x100.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/DSC02544.jpg 1319w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>En un emotivo acto frente a su busto referentes de diversas agrupaciones peronistas conmemoraron el natalicio de Eva Per\u00f3n. Durante &#8230; <a title=\"El peronismo de Mercedes record\u00f3 a Evita\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2026\/05\/07\/el-peronismo-de-mercedes-recordo-a-evita\/\" aria-label=\"Leer m\u00e1s sobre El peronismo de Mercedes record\u00f3 a Evita\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":195805,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[5],"tags":[2158,585,563],"class_list":["post-195804","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-acto-eva-peron","tag-juan-ustarroz","tag-partido-justicialista","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/DSC02648.jpg","wps_subtitle":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/195804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=195804"}],"version-history":[{"count":1,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/195804\/revisions"}],"predecessor-version":[{"id":195810,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/195804\/revisions\/195810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/195805"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=195804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=195804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=195804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}