{"id":195811,"date":"2026-05-07T21:45:59","date_gmt":"2026-05-08T00:45:59","guid":{"rendered":"https:\/\/www.hoymercedes.com.ar\/principal\/?p=195811"},"modified":"2026-05-07T21:46:02","modified_gmt":"2026-05-08T00:46:02","slug":"el-diablo-suma-a-mortal-kombat","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2026\/05\/07\/el-diablo-suma-a-mortal-kombat\/","title":{"rendered":"El Diablo suma a Mortal Kombat"},"content":{"rendered":"\n<p>El Cine Mercedes contin\u00faa con el \u00e9xito de \u00abEl Diablo Viste a la Moda 2\u00bb y suma en la cartelera del fin de semana a \u00abMortal Kombat 2\u00bb. Las funciones son desde el viernes 8 al martes 12 de mayo. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"827\" height=\"817\" data-attachment-id=\"195812\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2026\/05\/07\/el-diablo-suma-a-mortal-kombat\/gacetilla-cine-mercedes-56-2\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/Gacetilla-Cine-Mercedes-56.png\" data-orig-size=\"827,817\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Gacetilla Cine Mercedes (56)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/Gacetilla-Cine-Mercedes-56.png\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/Gacetilla-Cine-Mercedes-56.png\" alt=\"\" class=\"wp-image-195812\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/Gacetilla-Cine-Mercedes-56.png 827w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/Gacetilla-Cine-Mercedes-56-628x620.png 628w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/Gacetilla-Cine-Mercedes-56-150x148.png 150w\" sizes=\"auto, (max-width: 827px) 100vw, 827px\" \/><\/figure>\n\n\n\n<p>Sinopsis \u00abEl Diablo Viste a la Moda 2\u00bb: La lucha de Miranda Priestly contra Emily Charlton, su exasistente convertida en ejecutiva rival, mientras compiten por los ingresos por publicidad en medio de la decadencia de los medios impresos y Miranda se acerca a la jubilaci\u00f3n. (FILMAFFINITY)<\/p>\n\n\n\n<p>Sinopsis \u00abMortal Kombat 2\u00bb: Los campeones favoritos de los fans, ahora acompa\u00f1ados por el propio Johnny Cage, se enfrentan cara a cara en la definitiva y sangrienta batalla a muerte para vencer al oscuro r\u00e9gimen de Shao Kahn, que amenaza la existencia del Reino de la Tierra y a sus defensores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Cine Mercedes contin\u00faa con el \u00e9xito de \u00abEl Diablo Viste a la Moda 2\u00bb y suma en la cartelera &#8230; <a title=\"El Diablo suma a Mortal Kombat\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2026\/05\/07\/el-diablo-suma-a-mortal-kombat\/\" aria-label=\"Leer m\u00e1s sobre El Diablo suma a Mortal Kombat\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":195813,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[104],"tags":[8770,984,7805],"class_list":["post-195811","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","tag-cartelera","tag-cine-mercedes","tag-cultura","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/05\/mortalcombat2-819x1024-1.jpg","wps_subtitle":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/195811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=195811"}],"version-history":[{"count":1,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/195811\/revisions"}],"predecessor-version":[{"id":195814,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/195811\/revisions\/195814"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/195813"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=195811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=195811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=195811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}