{"id":199047,"date":"2026-07-17T12:00:01","date_gmt":"2026-07-17T15:00:01","guid":{"rendered":"https:\/\/www.hoymercedes.com.ar\/principal\/?p=199047"},"modified":"2026-07-17T12:00:05","modified_gmt":"2026-07-17T15:00:05","slug":"areco-volco-colectivo-por-la-tormenta-con-20-heridos-video","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2026\/07\/17\/areco-volco-colectivo-por-la-tormenta-con-20-heridos-video\/","title":{"rendered":"Areco: volc\u00f3 colectivo por la tormenta con 20 heridos (Video)"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"992\" height=\"537\" data-attachment-id=\"199048\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2026\/07\/17\/areco-volco-colectivo-por-la-tormenta-con-20-heridos-video\/micro-volco-areco-4\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/07\/Micro-volco-Areco-4.avif\" data-orig-size=\"992,537\" data-comments-opened=\"0\" data-image-title=\"Micro volc\u00f3 &amp;#8211; Areco &amp;#8211; 4\" data-image-description=\"&lt;p&gt;Carmen de Areco: un micro cay\u00f3 de un puente en la ruta 7 y hay varios heridos&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Carmen de Areco: un micro cay\u00f3 de un puente en la ruta 7 y hay varios heridos&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/07\/Micro-volco-Areco-4.avif\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/07\/Micro-volco-Areco-4.avif\" alt=\"\" class=\"wp-image-199048\" style=\"width:1052px;height:auto\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/07\/Micro-volco-Areco-4.avif 992w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/07\/Micro-volco-Areco-4-630x341.avif 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/07\/Micro-volco-Areco-4-150x81.avif 150w\" sizes=\"auto, (max-width: 992px) 100vw, 992px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Una madrugada dificil se vivi\u00f3 a pocos kil\u00f3metros de nuestra ciudad. Un colectivo de larga distancia de la empresa V\u00eda TAC despist\u00f3, choc\u00f3 y cay\u00f3 desde un puente sobre la Ruta Nacional N\u00b0 7, en la vecina localidad de <strong>Carmen de Areco<\/strong>. El siniestro dej\u00f3 un saldo de al menos 20 personas heridas, entre ellas un beb\u00e9 y una mujer mayor que debi\u00f3 ser rescatada tras quedar atrapada entre las chapas del veh\u00edculo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El accidente ocurri\u00f3 alrededor de las 4:00 de este viernes en el kil\u00f3metro 135 de la mencionada autov\u00eda, en sentido hacia la Ciudad de Buenos Aires. En ese punto, bajo las intensas lluvias y r\u00e1fagas que azotan a la regi\u00f3n, el micro perdi\u00f3 el control justo cuando sub\u00eda al puente que cruza sobre el Arroyo La Guardia, cayendo varios metros al vac\u00edo.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/1e5-H-y1T3I?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=es-ES&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Fabi\u00e1n Maira, jefe de Defensa Civil de San Antonio de Areco, confirm\u00f3 que el operativo de emergencia funcion\u00f3 con rapidez: <em>\u00abPor suerte no se tuvo que lamentar v\u00edctimas fatales\u00bb<\/em>, detall\u00f3, precisando que 19 de los heridos fueron trasladados de urgencia al hospital de la zona para recibir asistencia inmediata por politraumatismos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El micro hab\u00eda iniciado su recorrido en las provincias de San Luis y C\u00f3rdoba (con procedencia de la ciudad de Laboulaye) y ten\u00eda como destino final la localidad bonaerense de Avellaneda.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"992\" height=\"537\" data-attachment-id=\"199049\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2026\/07\/17\/areco-volco-colectivo-por-la-tormenta-con-20-heridos-video\/micro-volco-areco-4-2\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/07\/Micro-volco-Areco-4-1.avif\" data-orig-size=\"992,537\" data-comments-opened=\"0\" data-image-title=\"Micro volc\u00f3 &amp;#8211; Areco &amp;#8211; 4\" data-image-description=\"&lt;p&gt;Carmen de Areco: un micro cay\u00f3 de un puente en la ruta 7 y hay varios heridos&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Carmen de Areco: un micro cay\u00f3 de un puente en la ruta 7 y hay varios heridos&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/07\/Micro-volco-Areco-4-1.avif\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/07\/Micro-volco-Areco-4-1.avif\" alt=\"\" class=\"wp-image-199049\" style=\"width:1061px;height:auto\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/07\/Micro-volco-Areco-4-1.avif 992w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/07\/Micro-volco-Areco-4-1-630x341.avif 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/07\/Micro-volco-Areco-4-1-150x81.avif 150w\" sizes=\"auto, (max-width: 992px) 100vw, 992px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Maximiliano, uno de los pasajeros que viajaba en la unidad, relat\u00f3 el caos en primera persona para el canal de noticias <em>TN<\/em>: <em>\u201cEst\u00e1bamos subiendo el puente cuando aparentemente una r\u00e1faga de viento nos hizo volcar. Fueron segundos de p\u00e1nico\u201d<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, el dato m\u00e1s impactante del siniestro involucra a uno de los conductores del \u00f3mnibus. De acuerdo con el testimonio del mismo pasajero \u2014quien convers\u00f3 con el chofer que iba al volante tras el vuelco\u2014, el segundo conductor advirti\u00f3 la inminencia del desastre y tom\u00f3 una dr\u00e1stica decisi\u00f3n: <em>\u00abSe dio cuenta de que iba a pasar algo, abri\u00f3 la puerta lateral en marcha e intent\u00f3 saltar justo antes del impacto. Ahora no lo encuentran\u00bb<\/em>, asegur\u00f3 el testigo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"992\" height=\"558\" data-attachment-id=\"199050\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2026\/07\/17\/areco-volco-colectivo-por-la-tormenta-con-20-heridos-video\/micro-volco-areco\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/07\/Micro-volco-Areco.avif\" data-orig-size=\"992,558\" data-comments-opened=\"0\" data-image-title=\"Micro volc\u00f3 &amp;#8211; Areco\" data-image-description=\"&lt;p&gt;Carmen de Areco: un micro cay\u00f3 de un puente en la ruta 7 y hay varios heridos&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Carmen de Areco: un micro cay\u00f3 de un puente en la ruta 7 y hay varios heridos&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/07\/Micro-volco-Areco.avif\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/07\/Micro-volco-Areco.avif\" alt=\"\" class=\"wp-image-199050\" style=\"width:1072px;height:auto\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/07\/Micro-volco-Areco.avif 992w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/07\/Micro-volco-Areco-630x354.avif 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/07\/Micro-volco-Areco-150x84.avif 150w\" sizes=\"auto, (max-width: 992px) 100vw, 992px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Las fuerzas de seguridad y personal de la Polic\u00eda de la provincia de Buenos Aires montaron un rastrillaje intensivo en los alrededores del Arroyo La Guardia para localizar al tripulante, de quien a\u00fan se desconoce el estado de salud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el lugar trabajaron intensamente dotaciones de bomberos voluntarios de la zona, personal de la Polic\u00eda Vial de San Andr\u00e9s de Giles y equipos log\u00edsticos de Corredores Viales. Debido a la magnitud del vuelco y a las tareas necesarias para remover la pesada carrocer\u00eda, el tr\u00e1nsito sobre la Ruta 7 permaneci\u00f3 totalmente interrumpido a primeras horas de la ma\u00f1ana, gener\u00e1ndose importantes desv\u00edos y demoras bajo una persistente alerta meteorol\u00f3gica que afecta a toda la regi\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una madrugada dificil se vivi\u00f3 a pocos kil\u00f3metros de nuestra ciudad. Un colectivo de larga distancia de la empresa V\u00eda &#8230; <a title=\"Areco: volc\u00f3 colectivo por la tormenta con 20 heridos (Video)\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2026\/07\/17\/areco-volco-colectivo-por-la-tormenta-con-20-heridos-video\/\" aria-label=\"Leer m\u00e1s sobre Areco: volc\u00f3 colectivo por la tormenta con 20 heridos (Video)\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":199050,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[5501],"tags":[3169,21281,21282],"class_list":["post-199047","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-region","tag-carmen-de-areco","tag-carmen-de-areco-un-micro-cayo-de-un-puente-en-la-ruta-7-y-hay-varios-heridos","tag-volco-colectivo","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"wps_subtitle":"Susto","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2026\/07\/Micro-volco-Areco.avif","_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/199047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=199047"}],"version-history":[{"count":2,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/199047\/revisions"}],"predecessor-version":[{"id":199052,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/199047\/revisions\/199052"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/199050"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=199047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=199047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=199047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}