{"id":21265,"date":"2013-04-05T12:58:21","date_gmt":"2013-04-05T12:58:21","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=21265"},"modified":"2013-04-05T13:04:56","modified_gmt":"2013-04-05T13:04:56","slug":"solidaridad-variadas-instituciones-y-comercios-son-puntos-de-encuentro","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2013\/04\/05\/solidaridad-variadas-instituciones-y-comercios-son-puntos-de-encuentro\/","title":{"rendered":"Solidaridad: variadas instituciones y comercios son puntos de encuentro"},"content":{"rendered":"<p>En la ciudad son m\u00faltiples los puntos de encuentro para quienes deseen colaborar solidariamente con los afectados del grave temporal que vivi\u00f3 la ciudad de La Plata.<\/p>\n<p>Varias instituciones de diversos \u00e1mbitos invitan a los mercedinos a ser parte de la gran movida solidaria que se vive.<\/p>\n<p>Las necesidades son variadas y no se agotan en los alimentos. Solicitan tambi\u00e9n: cloro, trapos de piso, secadores, desinfectantes, ropa seca, etc.<\/p>\n<p>En el pun \u201cInfamia\u201d llevar\u00e1n a cabo un recital a beneficio este domingo a las 14.00hs con bandas de rock local como Atrapados en libertad, Los Lyngera, Uglys, Senorar y Ladg. En Casa del Pueblo estar\u00e1n present\u00e1ndose<\/p>\n<p>Algunos lugares para colaborar:<\/p>\n<p>Bomberos Mercedes \u2013 Calle 22 y 15.<\/p>\n<p>&#8211; Club Quilmes. \u2013 Calle 12 esq. 15.<\/p>\n<p>-Oxi Mercedes &#8211; \u00a031, 12 y 14 de 14.30 a 19 Hs.<\/p>\n<p>&#8211; Librer\u00eda \u00abLa Esquina\u00bb. &#8211; 24 esq. 19 de 16 a 20.30Hs<\/p>\n<p>. Casa Joven. &#8211; 33 y 14.<\/p>\n<p>&#8211; Frente Mercedino &#8211; \u00a025 e\/ 16 y 18.<\/p>\n<p>&#8211; Colegio Misericordia en horario d clases. Calle 29 y 28.<\/p>\n<p>&#8211; Partido Obrero y Polo Obrero \u2013 Calle 17 entre 12 y 14.<\/p>\n<p>&#8211; Sindicato de Trabajadores Municipales \u2013 Calle 10 entre 29 y 31.<\/p>\n<p>&#8211; UEB calle 31 entre 4 y 16.<\/p>\n<p>&#8211; Colegio Agron\u00f3mico: realizar\u00e1n una caminata con uniformes y elementos identificatorios el s\u00e1bado por la ma\u00f1ana.<\/p>\n<p>&#8211; Casa del Pueblo en calle 35 entre 22 y 24. Domingo. Ciclo Cronopios con diversas expresiones art\u00edsticas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la ciudad son m\u00faltiples los puntos de encuentro para quienes deseen colaborar solidariamente con los afectados del grave temporal &#8230; <a title=\"Solidaridad: variadas instituciones y comercios son puntos de encuentro\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2013\/04\/05\/solidaridad-variadas-instituciones-y-comercios-son-puntos-de-encuentro\/\" aria-label=\"Leer m\u00e1s sobre Solidaridad: variadas instituciones y comercios son puntos de encuentro\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[8],"tags":[3361],"class_list":["post-21265","post","type-post","status-publish","format-standard","hentry","category-sociedad","tag-solidaridad","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","wps_subtitle":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/21265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=21265"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/21265\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=21265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=21265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=21265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}