{"id":21291,"date":"2013-04-07T03:43:36","date_gmt":"2013-04-07T03:43:36","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=21291"},"modified":"2013-04-07T03:47:44","modified_gmt":"2013-04-07T03:47:44","slug":"fmpv-lanza-campana-de-alfabetizacion","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2013\/04\/07\/fmpv-lanza-campana-de-alfabetizacion\/","title":{"rendered":"FMPV lanza campa\u00f1a de alfabetizaci\u00f3n"},"content":{"rendered":"<p>&nbsp;<\/p>\n<figure id=\"attachment_21293\" aria-describedby=\"caption-attachment-21293\" style=\"width: 608px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/04\/Altafetizacion-MatalobosLeticia.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"21293\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2013\/04\/07\/fmpv-lanza-campana-de-alfabetizacion\/altafetizacion-matalobosleticia\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/04\/Altafetizacion-MatalobosLeticia.jpg\" data-orig-size=\"618,464\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;GT-B5510L&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1365104051&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;2.79&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.090909090909091&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Altafetizacion-MatalobosLeticia\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Leticia Matalobos &amp;#8211; Campa\u00f1a de Alfabetizaci\u00f3n&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/04\/Altafetizacion-MatalobosLeticia.jpg\" class=\"size-full wp-image-21293 \" alt=\"Leticia Matalobos - Campa\u00f1a de Alfabetizaci\u00f3n\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/04\/Altafetizacion-MatalobosLeticia.jpg\" width=\"618\" height=\"464\" \/><\/a><figcaption id=\"caption-attachment-21293\" class=\"wp-caption-text\">Leticia Matalobos &#8211; Campa\u00f1a de Alfabetizaci\u00f3n<\/figcaption><\/figure>\n<p><em><strong>La ciudad contar\u00e1 con una nueva campa\u00f1a de alfabetizaci\u00f3n. La misma se confirma tras una reuni\u00f3n efectuada en el \u00e1mbito del Frente Mercedino para la Victoria que cont\u00f3 con la presencia de 15 nuevos alfabetizadores.<\/strong><\/em><\/p>\n<p>La medida se aplicar\u00e1 en diversas barriadas de nuestra ciudad siendo una propuesta que tiene su ra\u00edz en el a\u00f1o pasado y que en este 2013 a sumado nuevas voluntades para la tarea.<\/p>\n<p>Habr\u00e1 una previa capacitaci\u00f3n.<\/p>\n<p>Una de las referentes de la tarea, Leticia Matalobos, afirm\u00f3\u00a0<em>\u201cLa tarea de alfabetizar solamente es posible si se genera un v\u00ednculo de confianza, y si fue mucha la gente que se acerc\u00f3 el a\u00f1o pasado con el deseo de aprender a leer y a escribir, es por el trabajo militante del Frente Mercedino \u00a0que camina los barrios, escucha las necesidades de los vecinos, trata de resolverles los problemas. Y hay que decirlo: nada de esto ser\u00eda posible sin la labor incansable de los referentes barriales, sin el trabajo desinteresado de los alfabetizadores y sin el apoyo incondicional de Juani\u201d<\/em>.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; La ciudad contar\u00e1 con una nueva campa\u00f1a de alfabetizaci\u00f3n. La misma se confirma tras una reuni\u00f3n efectuada en el &#8230; <a title=\"FMPV lanza campa\u00f1a de alfabetizaci\u00f3n\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2013\/04\/07\/fmpv-lanza-campana-de-alfabetizacion\/\" aria-label=\"Leer m\u00e1s sobre FMPV lanza campa\u00f1a de alfabetizaci\u00f3n\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[23],"tags":[],"class_list":["post-21291","post","type-post","status-publish","format-standard","hentry","category-educacion","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","wps_subtitle":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/21291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=21291"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/21291\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=21291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=21291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=21291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}