{"id":21303,"date":"2013-04-07T23:39:25","date_gmt":"2013-04-07T23:39:25","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=21303"},"modified":"2013-04-07T23:39:42","modified_gmt":"2013-04-07T23:39:42","slug":"recitales-y-arte-a-beneficio-de-los-inundados-de-la-plata","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2013\/04\/07\/recitales-y-arte-a-beneficio-de-los-inundados-de-la-plata\/","title":{"rendered":"Recitales y arte a beneficio de los inundados de La Plata"},"content":{"rendered":"<figure id=\"attachment_21305\" aria-describedby=\"caption-attachment-21305\" style=\"width: 608px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/04\/papelonrock.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"21305\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2013\/04\/07\/recitales-y-arte-a-beneficio-de-los-inundados-de-la-plata\/papelonrock\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/04\/papelonrock.jpg\" data-orig-size=\"618,464\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;3.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;COOLPIX L310&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1365444794&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;10.2&quot;,&quot;iso&quot;:&quot;560&quot;,&quot;shutter_speed&quot;:&quot;0.02&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"papelonrock\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Recita a beneficio&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/04\/papelonrock.jpg\" class=\"size-full wp-image-21305 \" alt=\"Recita a beneficio\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/04\/papelonrock.jpg\" width=\"618\" height=\"464\" \/><\/a><figcaption id=\"caption-attachment-21305\" class=\"wp-caption-text\">Recita a beneficio<\/figcaption><\/figure>\n<p>Durante la jornada de este domingo la ciudad tuvo encuentros solidarios pensando en los que m\u00e1s lo necesitan que se encuentran en estos momentos en la ciudad de La Plata como gran epicentro cr\u00edtico.<\/p>\n<p>Dos lugares tuvieron este fin de semana mayores actividades en cuento a presentaciones art\u00edsticas.<\/p>\n<figure id=\"attachment_21306\" aria-describedby=\"caption-attachment-21306\" style=\"width: 608px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/04\/Infamia-Rock.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"21306\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2013\/04\/07\/recitales-y-arte-a-beneficio-de-los-inundados-de-la-plata\/infamia-rock\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/04\/Infamia-Rock.jpg\" data-orig-size=\"618,464\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;3.1&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;COOLPIX L310&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1365446949&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.5&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.033333333333333&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Infamia-Rock\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Recitan a beneficio&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/04\/Infamia-Rock.jpg\" class=\"size-full wp-image-21306 \" alt=\"Recitan a beneficio\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/04\/Infamia-Rock.jpg\" width=\"618\" height=\"464\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/04\/Infamia-Rock.jpg 618w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/04\/Infamia-Rock-300x225.jpg 300w\" sizes=\"auto, (max-width: 618px) 100vw, 618px\" \/><\/a><figcaption id=\"caption-attachment-21306\" class=\"wp-caption-text\">Recitan a beneficio<\/figcaption><\/figure>\n<p>En 27 entre 26 y 28 un buen n\u00famero de mercedinos, en especial j\u00f3venes, se congregaron solidariamente para escuchar a las bandas locales que actuaron bajo la idea de recolectar bienes para los afectados en La Plata. Fue frente al boliche-pub \u201cInfamia\u201d<\/p>\n<p>En \u201cCasa del Pueblo\u201d tambi\u00e9n se vio un momento de arte y cultura buscando aportar a los m\u00e1s necesitados. Desde la tarde en el local de calle 35 entre 22 y 24 vio a los mercedinos actuar solidariamente.<\/p>\n<p>En Infamia la programaci\u00f3n inclu\u00eda: Atrapados en libertad, Los Lyngera, Uglys, Senorar, Ladg y Papel\u00f3n Rock. En Casa del Pueblo estaba programado: Lado B, Netaspi Butotri y \u201cNuestra m\u00fasica\u201d con Gast\u00f3n Cartasegna, Eliana Ramponi, Magali Ramponi y Patt Yamella.<\/p>\n<p>Los mercedinos tendr\u00e1n durante toda la semana muchos otros espacios donde aportar como Suteba, Direcci\u00f3n de Desarrollo Social, Casa Joven, Frente Mercedino, Bomberos y Club Quilmes.<\/p>\n<p><a href=\"http:\/\/www.facebook.com\/media\/set\/?set=a.10151587681611323.1073741839.339192141322&amp;type=1\" target=\"_blank\" rel=\"noopener\">M\u00e1s im\u00e1genes: VER<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante la jornada de este domingo la ciudad tuvo encuentros solidarios pensando en los que m\u00e1s lo necesitan que se &#8230; <a title=\"Recitales y arte a beneficio de los inundados de La Plata\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2013\/04\/07\/recitales-y-arte-a-beneficio-de-los-inundados-de-la-plata\/\" aria-label=\"Leer m\u00e1s sobre Recitales y arte a beneficio de los inundados de La Plata\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[8],"tags":[3364,3363],"class_list":["post-21303","post","type-post","status-publish","format-standard","hentry","category-sociedad","tag-casa-del-pueblo-mercedes","tag-infamia-recital","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","wps_subtitle":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/21303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=21303"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/21303\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=21303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=21303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=21303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}