{"id":21887,"date":"2013-04-26T13:25:09","date_gmt":"2013-04-26T13:25:09","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=21887"},"modified":"2013-04-26T19:22:34","modified_gmt":"2013-04-26T19:22:34","slug":"abrieron-sobre-de-licitacion-para-importante-obra-cloacal-en-mercedes","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2013\/04\/26\/abrieron-sobre-de-licitacion-para-importante-obra-cloacal-en-mercedes\/","title":{"rendered":"Abrieron sobres de licitaci\u00f3n para importante obra cloacal en Mercedes"},"content":{"rendered":"<figure id=\"attachment_21889\" aria-describedby=\"caption-attachment-21889\" style=\"width: 610px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/04\/Sobres-Colector.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"21889\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2013\/04\/26\/abrieron-sobre-de-licitacion-para-importante-obra-cloacal-en-mercedes\/sobres-colector\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/04\/Sobres-Colector.jpg\" data-orig-size=\"620,403\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;GT-I9300&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1366891203&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.7&quot;,&quot;iso&quot;:&quot;320&quot;,&quot;shutter_speed&quot;:&quot;0.066666666666667&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Sobres-Colector\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Colector Cloacal &amp;#8211; Apertura de sobres de licitaci\u00f3n. &lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/04\/Sobres-Colector.jpg\" class=\"size-full wp-image-21889\" alt=\"Colector Cloacal - Apertura de sobres de licitaci\u00f3n. \" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/04\/Sobres-Colector.jpg\" width=\"620\" height=\"403\" \/><\/a><figcaption id=\"caption-attachment-21889\" class=\"wp-caption-text\">Colector Cloacal &#8211; Apertura de sobres de licitaci\u00f3n.<\/figcaption><\/figure>\n<p><em><strong>Por medio de un acto llevado a cabo en el Ameghino Mar\u00edn se llev\u00f3 adelante la apertura de sobres con las ofertas para realizar la construcci\u00f3n del colector cloacal que dar\u00e1 el servicio a un importante n\u00famero de vecinos.<\/strong><\/em><\/p>\n<p>Se ver\u00e1n beneficiados vecinos de varios barrios, entre ellos Par\u00eds Gianinni, San Francisco, Luz y Fuerza, Villa Industrial Este y Seminario: las cloacas.<\/p>\n<p>El acto estuvo encabezado por el intendente Carlos Selva, junto con el titular provincial del Servicio Provincial de Agua Potable y Saneamiento Rural, Juan Mar\u00eda Vi\u00f1ales, abrieron los sobres con las ofertas para la construcci\u00f3n del colector cloacal que brindar\u00e1 servicio cloacal a una vasta zona de la ciudad.<\/p>\n<p>El presupuesto oficial para la obra de construcci\u00f3n del colector cloacal es de 6.738.117,98 y hubo cuatro empresas que se presentaron: HUGHES Y MORRIS ARQUITECTOS SRL. con una oferta de 5.504.424,16 pesos; BYMO S.A con 5.907.396,85; ARR-CA S.R.L con 6.538.494,28 y SOC.SUD DE ARQUITECTURA S.R.L con 6.719.739,78.<\/p>\n<p>Con una obra total de 2,200 km. colector cloacal de 400 metros de di\u00e1metro de PVC y 20 c\u00e1maras de inspecci\u00f3n de esquinas. El recorrido de la obra comprende de calle 1 de 2 a 108, de 108 y 1 a 5, de 5 y 108 a 114, de 114 y 5 a 23. Los barrios beneficiados con esta obra son: Par\u00eds Giannini, San Francisco, Luz y Fuerza y Villa Industrial Este.<\/p>\n<p><span style=\"color: #888888;\">Fuente: MM<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por medio de un acto llevado a cabo en el Ameghino Mar\u00edn se llev\u00f3 adelante la apertura de sobres con &#8230; <a title=\"Abrieron sobres de licitaci\u00f3n para importante obra cloacal en Mercedes\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2013\/04\/26\/abrieron-sobre-de-licitacion-para-importante-obra-cloacal-en-mercedes\/\" aria-label=\"Leer m\u00e1s sobre Abrieron sobres de licitaci\u00f3n para importante obra cloacal en Mercedes\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[30],"tags":[3421],"class_list":["post-21887","post","type-post","status-publish","format-standard","hentry","category-municipio","tag-licitacion-cloacal","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","wps_subtitle":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/21887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=21887"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/21887\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=21887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=21887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=21887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}