{"id":22070,"date":"2013-05-06T12:04:47","date_gmt":"2013-05-06T12:04:47","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=22070"},"modified":"2013-05-06T12:22:59","modified_gmt":"2013-05-06T12:22:59","slug":"presentaron-lista-rosa-para-elecciones-en-suteba-resquin-sostuvo-lista-rosa-es-una-corriente-de-oposicion-que-busca-mantener-su-perfil-de-denuncia-de-aquellas-practicas-sindicales-burocraticas","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2013\/05\/06\/presentaron-lista-rosa-para-elecciones-en-suteba-resquin-sostuvo-lista-rosa-es-una-corriente-de-oposicion-que-busca-mantener-su-perfil-de-denuncia-de-aquellas-practicas-sindicales-burocraticas\/","title":{"rendered":"Elecciones en Suteba: presentaron \u00abLista Rosa\u00bb. Resqu\u00edn:\u00bbes una corriente de oposici\u00f3n\u00bb"},"content":{"rendered":"<figure id=\"attachment_22072\" aria-describedby=\"caption-attachment-22072\" style=\"width: 610px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/05\/ListaRosa.Suteba.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"22072\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2013\/05\/06\/presentaron-lista-rosa-para-elecciones-en-suteba-resquin-sostuvo-lista-rosa-es-una-corriente-de-oposicion-que-busca-mantener-su-perfil-de-denuncia-de-aquellas-practicas-sindicales-burocraticas\/listarosa-suteba\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/05\/ListaRosa.Suteba.jpg\" data-orig-size=\"620,232\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;GT-B5510L&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1367585251&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;2.79&quot;,&quot;iso&quot;:&quot;320&quot;,&quot;shutter_speed&quot;:&quot;0.125&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"ListaRosa.Suteba\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;\u00abLista Rosa\u00bb, candidata a conducir Suteba&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/05\/ListaRosa.Suteba.jpg\" class=\"size-full wp-image-22072\" alt=\"&quot;Lista Rosa&quot;, candidata a conducir Suteba\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/05\/ListaRosa.Suteba.jpg\" width=\"620\" height=\"232\" \/><\/a><figcaption id=\"caption-attachment-22072\" class=\"wp-caption-text\">\u00abLista Rosa\u00bb, candidata a conducir Suteba<\/figcaption><\/figure>\n<p><strong>Durante el mediod\u00eda de este viernes se present\u00f3\u00a0 oficialmente la Lista Rosa que participar\u00e1\u00a0en las pr\u00f3ximas elecciones de las elecciones de Suteba a realizarse el pr\u00f3ximo 22 de mayo del corriente. La lista est\u00e1 encabezada por Patricia Bojorge y Sergio Resqu\u00edn. Hablaron de su rol opositor, de las diferencias con la lista Celeste y de las propuestas que poseen en su mirada sobre la situaci\u00f3n docente.<\/strong><\/p>\n<p>Sergio Resqu\u00edn sostuvo al respecto: <em>\u201cLista Rosa es una corriente de oposici\u00f3n que busca mantener su perfil de denuncia de aquellas practicas sindicales burocr\u00e1ticas, que tanto perjudican a los trabajadores. En esta oportunidad la lista Rosa constituida por hist\u00f3ricos luchadores docentes que reconocen su origen en la pelea contra la nefasta ley Federal de Educaci\u00f3n, enfrenta varios desaf\u00edos.<\/em><\/p>\n<p><em>En el orden provincial nos toca esclarecer algo que para muchos ha sido la pol\u00edtica acostumbrada de la lista celeste en los \u00faltimos a\u00f1os. Cacarear un plan de lucha, paros domingueros, y despu\u00e9s negociar regidos por su alineamiento con el Gobierno Nacional. Claro que este a\u00f1o esa pol\u00edtica quedo tan en evidencia que casi no hace falta abundar demasiado. Baradel, quien sabe a cambio de que, se sent\u00f3 a convalidar el 22,6 % en c\u00f3modas cuotas, que el Frente Gremial hab\u00eda rechazado varias veces, pero que siguiendo la l\u00ednea de Cristina, de cerrar paritarias a la baja, impuso a la docencia bonaerense sin siquiera consultar en una miserable asamblea .Esto no es nuevo, es la pol\u00edtica habitual de la celeste que prioriza siempre no complicarle la vida al Gobierno Nacional con el que esta alineado. Lo llamativo esa vez fue que se agarraron de cualquier excusa para levantar todo y no consultar a las bases luego que se hab\u00edan llenado la boca con que rechazaban la propuesta miserable del gobierno.<\/em><\/p>\n<p><em>En Mercedes en el 2010, luego de 11 a\u00f1os de intervenci\u00f3n \u00abceleste \u00ab, ganaron la seccionalizacion por solo 4 votos .Pero hete aqu\u00ed que a poco de asumir las contradicciones internas de diversos camarillas del aparato kirchnerista provocaron la salida de Seis de los siete cargos que encabezaron la Lista Celeste .El representante del Movimiento Evita , Jorge Arturo Montaldo en pocos meses de gesti\u00f3n \u00ablimpi\u00f3\u00bb a varios de los que no comulgaban con su ultrakirchnerismo a la vez que aparec\u00eda como inspector de Adultos y a fines de ese a\u00f1o como funcionario selvista .El hombre parece, pod\u00eda atender a uno y otro lado del mostrador. Finalmente denunciado en varias asambleas pidi\u00f3 licencia para luego renunciar antes de protagonizar un papel\u00f3n pol\u00edtico de proporciones abandonando el selvismo veinte d\u00edas antes de las elecciones generales de octubre, abrazando el camporismo, luego derrotado.<\/em><\/p>\n<p><em>Los compa\u00f1eros deben sacar sus conclusiones de una Celeste que como \u00fanico eje de campa\u00f1a instalo la critica a la militancia pol\u00edtica de algunos dirigentes de Tribuna Docentes, las camarillas internas K se enfrentaban dentro del SUTEBA.<\/em><\/p>\n<p><em>Hoy la Celeste pretende\u00bb haberse lavado la cara\u00bb pero la matriz de un lista que aline\u00f3 el sindicato al Gobierno Nacional esta presente para defender lo indefendible: la entrega de Baradel .Los Celestes locales han sido tan verticalistas y macartistas que no seria raro que el propio Montaldo actu\u00e9 en las sombras.<\/em><\/p>\n<p><em>Por \u00faltimo, dej\u00f3 una invitaci\u00f3n a los afiliados: \u201cPor un sindicato recuperado para los trabajadores; Basta de alineamiento con el gobierno y el estado; Abajo el acuerdo Baradel- Scioli;Por un 30% de b\u00e1sico. Basta de sumas en negro; Vota a la multicolor en la provincia y a la Rosa en Mercedes; Patricia Bojorge Secretaria General\u201d.<\/em><\/p>\n<p><strong>La lista completa es la siguiente.<\/strong><\/p>\n<p>Sec. General: Bojorge, Patricia<\/p>\n<p>Sec. General Adjunto y Form. Pol. Sindical: Resquin, Sergio<\/p>\n<p>Sec. Gremial y de Jubilaci\u00f3n: Ivaldi, Daniela<\/p>\n<p>Sec. de Organizaci\u00f3n: Zunino, Nora<\/p>\n<p>Sec. de Salud y Promoci\u00f3n Social: Carrera, Susana<\/p>\n<p>Sec. Administrativa y actas: Altavista, Walter<\/p>\n<p>Sec. de finanzas: Zunino, Maria<\/p>\n<p>Sec. de Cultura, Educ. y DDHH: Ciro, Jos\u00e9<\/p>\n<p><strong>Vocales<\/strong><\/p>\n<p>Lombardo, Alejandro<\/p>\n<p>Areco, Ver\u00f3nica<\/p>\n<p>Leyes, Mirta<\/p>\n<p><strong>Congresales a Suteba<\/strong><\/p>\n<p>Bojorge, Elizabet<\/p>\n<p>Resquin, Sergio<\/p>\n<p><strong>Comisi\u00f3n revisora de cuentas<\/strong><\/p>\n<p>Vivas, Luis<\/p>\n<p>Ghignone, Jos\u00e9<\/p>\n<p>S\u00e1nchez, Vanesa<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante el mediod\u00eda de este viernes se present\u00f3\u00a0 oficialmente la Lista Rosa que participar\u00e1\u00a0en las pr\u00f3ximas elecciones de las elecciones &#8230; <a title=\"Elecciones en Suteba: presentaron \u00abLista Rosa\u00bb. Resqu\u00edn:\u00bbes una corriente de oposici\u00f3n\u00bb\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2013\/05\/06\/presentaron-lista-rosa-para-elecciones-en-suteba-resquin-sostuvo-lista-rosa-es-una-corriente-de-oposicion-que-busca-mantener-su-perfil-de-denuncia-de-aquellas-practicas-sindicales-burocraticas\/\" aria-label=\"Leer m\u00e1s sobre Elecciones en Suteba: presentaron \u00abLista Rosa\u00bb. Resqu\u00edn:\u00bbes una corriente de oposici\u00f3n\u00bb\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[8],"tags":[3440,1151,3394],"class_list":["post-22070","post","type-post","status-publish","format-standard","hentry","category-sociedad","tag-elecciones-subeta","tag-resquin","tag-sergio-resquin","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","wps_subtitle":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/22070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=22070"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/22070\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=22070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=22070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=22070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}