{"id":22087,"date":"2013-05-06T22:57:59","date_gmt":"2013-05-06T22:57:59","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=22087"},"modified":"2013-05-07T13:11:08","modified_gmt":"2013-05-07T13:11:08","slug":"sutefa-informa-que-docentes-continuaran-negociando-evaluando-medidas-a-seguir","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2013\/05\/06\/sutefa-informa-que-docentes-continuaran-negociando-evaluando-medidas-a-seguir\/","title":{"rendered":"Suteba informa que docentes continuar\u00e1n negociando evaluando medidas a seguir"},"content":{"rendered":"<p><em><strong>El\u00a0denominado\u00a0\u00abconflicto docente\u00bb entre espacios de defensa del trabajor de la educaci\u00f3n y la admintraci\u00f3n provincial de Daniel Scioli contin\u00faa, a pesar del cede de medidas de fuerza. Es por ello que Suteba dio a conocer las \u00faltimas acciones vividas en las mesas de negociaciones.<\/strong><\/em><\/p>\n<p>Al respecto la entidad gremial inform\u00f3:<em>\u00ablas entidades gremiales que integramos el Frente Gremial Docente Bonaerense concurrimos a una mesa de trabajo con las autoridades de la DGCyE, en el marco de la Conciliaci\u00f3n Obligatoria resuelta por el Ministerio de Trabajo Provincial.<\/em><\/p>\n<p><em>Se abord\u00f3 como tema prioritario la cuesti\u00f3n salarial y, asimismo, reiteramos el reclamo por el mal funcionamiento de las prestatarias, los sueldos adeudados, la crisis prestacional del IOMA e infraestructura escolar, entre otros.<\/em><\/p>\n<p><em>Ante el reclamo que efectu\u00e1ramos por la dificultades relacionadas a las asignaciones familiares, la DGCyE prorrog\u00f3 el plazo en que operaba el vencimiento de ingreso de datos hasta el 30 de mayo del corriente a\u00f1o.<\/em><\/p>\n<p><em>Finalmente, se pas\u00f3 a un cuarto intermedio para el d\u00eda 09 de mayo del corriente a\u00f1o.\u00bb<\/em><\/p>\n<p>De esta manera de da cuente del momento que se vive en el cual las cuestiones no est\u00e1n cerradas y se esperan\u00a0novedades\u00a0en el corto plazo,<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El\u00a0denominado\u00a0\u00abconflicto docente\u00bb entre espacios de defensa del trabajor de la educaci\u00f3n y la admintraci\u00f3n provincial de Daniel Scioli contin\u00faa, a &#8230; <a title=\"Suteba informa que docentes continuar\u00e1n negociando evaluando medidas a seguir\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2013\/05\/06\/sutefa-informa-que-docentes-continuaran-negociando-evaluando-medidas-a-seguir\/\" aria-label=\"Leer m\u00e1s sobre Suteba informa que docentes continuar\u00e1n negociando evaluando medidas a seguir\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[23],"tags":[484,37],"class_list":["post-22087","post","type-post","status-publish","format-standard","hentry","category-educacion","tag-docentes","tag-suteba","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","wps_subtitle":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/22087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=22087"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/22087\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=22087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=22087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=22087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}