{"id":2336,"date":"2011-02-23T03:17:27","date_gmt":"2011-02-23T03:17:27","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=2336"},"modified":"2011-02-23T03:17:27","modified_gmt":"2011-02-23T03:17:27","slug":"agencia-pami-fuertes-rumores-de-cambios","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2011\/02\/23\/agencia-pami-fuertes-rumores-de-cambios\/","title":{"rendered":"Agencia PAMI: Fuertes rumores de cambios"},"content":{"rendered":"<p>Durante toda la jornada del martes se pudo escuchar en diferentes sectores de la ciudad el rumor relacionado con la posible sustituci\u00f3n del Dr. Carlos Nerio Calloni como titular de la Agencia PAMI ubicada en nuestra ciudad por el joven cntador Pablo Perazzo, nieto del ex intendente Julio Cesar Gioscio quien como se sabe hace muy pocos d\u00edas concret\u00f3 la incorporaci\u00f3n de la Agrupaci\u00f3n Justicialista que lidera junto a Eduardo Cerulli \u00abLeales a Peron\u00bb al Movimiento Mercedino para la Victoria que encabezan Eduardo Wado De Pedro y Juan Ignacio Uztarroz.<\/p>\n<p>Los tel\u00e9fonos de muchos amigos y ex correligionarios enla UCR no dejaron de llamar de manera insistente a cuanta persona conocieran para saber si la informaci\u00f3n era real pero todos recib\u00edan la misma respuesta \u00abhace tiempo que dicho rumor se viene escuchando pero al menos hasta el momento Carlos (Calloni) no ha sido informado absolutamente de nada por sus superiores. Las consultas llegaron hasta el propio jefe comunal quien segun dicen, habria respondido \u00abno me hab\u00eda enterado que cambiaba na a Lauria del ANSES as\u00ed que mucho menos puedo enterarme de un hombre del radicalismo\u00bb<\/p>\n<p>Recordamos que en un momento dado se hab\u00eda dicho que los representantes de La Campora en nuestra ciudad, ahora transformado\u00a0 pol\u00edticamente en el Mhabian expresado tras el cambio realizado en el ANSES donde en lugar de Lauria asumi\u00f3 Uztarroz, iban a buscar tambi\u00e9n quedarse con las jefaturas del PAMI y luego de laDelegaci\u00f3n Mercedes del Ministerio de Trabajo de la Provincia aunque dicha versi\u00f3n nunca fue cnfirmada oficialmente,<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante toda la jornada del martes se pudo escuchar en diferentes sectores de la ciudad el rumor relacionado con la &#8230; <a title=\"Agencia PAMI: Fuertes rumores de cambios\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2011\/02\/23\/agencia-pami-fuertes-rumores-de-cambios\/\" aria-label=\"Leer m\u00e1s sobre Agencia PAMI: Fuertes rumores de cambios\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-2336","post","type-post","status-publish","format-standard","hentry","category-opinion","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","wps_subtitle":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/2336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=2336"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/2336\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=2336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=2336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=2336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}