{"id":24443,"date":"2013-08-02T00:35:44","date_gmt":"2013-08-02T00:35:44","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=24443"},"modified":"2013-08-02T00:35:44","modified_gmt":"2013-08-02T00:35:44","slug":"leandro-lopez-nuevo-director-de-turismo-en-mercedes","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2013\/08\/02\/leandro-lopez-nuevo-director-de-turismo-en-mercedes\/","title":{"rendered":"Leandro L\u00f3pez nuevo Director de Turismo en Mercedes"},"content":{"rendered":"<p><em><strong>Tras el alejamiento del cargo de Director de Marcelo Melo se conoce el nombre de qui\u00e9n ser\u00e1 el reemplazante desde este mes. Se trata de Leandro L\u00f3pez. Un hombre que ya fue presentado al personal del \u00e1rea. Melo seguir\u00e1 en funciones dentro de la comuna.\u00a0<\/strong><\/em><\/p>\n<p>La decisi\u00f3n de dar un paso al costado de la cartera tur\u00edstica dej\u00f3 lugar a que alguien m\u00e1s tome la conducci\u00f3n de dicha \u00e1rea y ya se conoce dicho nombre. Se trata de Leandro L\u00f3pez, alguien que cuenta con experiencia en gesti\u00f3n y que ha trabajado en el \u00e1mbito privado.<\/p>\n<p>Por su parte, Marcelo Melo, no deja de ser funcionario del selvismo dado que ir\u00e1 pronto a continuar con la conducci\u00f3n del espacio de Derechos Humanos que se encuentra por ahora bajo la \u00f3rbita de Turismo, pero, que cambiar\u00e1 de sede y ampliar\u00e1 su perfil teniendo la necesaria separaci\u00f3n de carteras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras el alejamiento del cargo de Director de Marcelo Melo se conoce el nombre de qui\u00e9n ser\u00e1 el reemplazante desde &#8230; <a title=\"Leandro L\u00f3pez nuevo Director de Turismo en Mercedes\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2013\/08\/02\/leandro-lopez-nuevo-director-de-turismo-en-mercedes\/\" aria-label=\"Leer m\u00e1s sobre Leandro L\u00f3pez nuevo Director de Turismo en Mercedes\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[30],"tags":[1653,986,403],"class_list":["post-24443","post","type-post","status-publish","format-standard","hentry","category-municipio","tag-derechos-humanos-mercedes","tag-direccion-de-turismo","tag-marcelo-melo","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","wps_subtitle":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/24443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=24443"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/24443\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=24443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=24443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=24443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}