{"id":26405,"date":"2013-10-09T01:05:10","date_gmt":"2013-10-09T01:05:10","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=26405"},"modified":"2013-10-09T01:05:10","modified_gmt":"2013-10-09T01:05:10","slug":"duro-traspie-de-las-albitas-en-el-debut","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2013\/10\/09\/duro-traspie-de-las-albitas-en-el-debut\/","title":{"rendered":"Duro traspi\u00e9 de las Albitas en el debut"},"content":{"rendered":"<p><strong>Por Juanito Men\u00e9ndez \u00a0<\/strong><br \/>\n(producci\u00f3n y fotos)<a href=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/10\/albitas-I.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"26408\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2013\/10\/09\/duro-traspie-de-las-albitas-en-el-debut\/albitas-i-4\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/10\/albitas-I.jpg\" data-orig-size=\"620,465\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"albitas-I\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/10\/albitas-I.jpg\" class=\"aligncenter size-full wp-image-26408\" alt=\"albitas-I\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/10\/albitas-I.jpg\" width=\"620\" height=\"465\" \/><\/a><\/p>\n<p><em><strong>En Villa Lynch, el equipo de V\u00e9lez-All Boys, se vio ampliamente superado por la UAI Urquiza desde el primer minuto de juego y se trajo una derrota por 22 a 0, en condici\u00f3n de visitante, en lo que marc\u00f3 el comienzo del Torneo Inicial 2013, correspondiente a la Primera Divisi\u00f3n del F\u00fatbol femenino organizado por AFA.<\/strong><\/em><\/p>\n<p>Con esperanzas renovadas viajaba el equipo de nuestra ciudad a disputar este encuentro, postergado del d\u00eda S\u00e1bado, ante un siempre dif\u00edcil UAI Urquiza que anima a\u00f1o a a\u00f1o dicho Torneo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"26410\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2013\/10\/09\/duro-traspie-de-las-albitas-en-el-debut\/albitas-iii-4\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/10\/albitas-III.jpg\" data-orig-size=\"620,465\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"albitas-III\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/10\/albitas-III.jpg\" class=\"aligncenter size-full wp-image-26410\" alt=\"albitas-III\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/10\/albitas-III.jpg\" width=\"620\" height=\"465\" \/><\/p>\n<p>Con algunas bajas, pero ya con las \u201crefuerzos\u201d a disposici\u00f3n, Mart\u00edn Blanco par\u00f3 en el arco a Karen G\u00f3mez; en el fondo, de derecha a izquierda, estuvieron Noelia Pollero, Lorena Cepeda, Carina Maciel y Marianela Pereyra; la zona media tambi\u00e9n la compusieron cuatro jugadoras, que fueron, Fiama Silva, Milagros Trejo, Mar\u00eda Jes\u00fas Lopardo y Soledad Sosa; para que Marcia Fern\u00e1ndez y \u00c1ngeles Guerrero compartan la dupla de ataque. Ingresaron Mariana Vergara por Mar\u00eda Jes\u00fas Lopardo, Julieta Olivieri por Soledad Sosa y Macarena Fern\u00e1ndez por MilagrosTrejo. Quedaron en el banco a la espera de su oportunidad las jugadoras Magal\u00ed Ramos y Lucila Navarreta.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"26411\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2013\/10\/09\/duro-traspie-de-las-albitas-en-el-debut\/albitas-iv-2\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/10\/albitas-IV.jpg\" data-orig-size=\"620,465\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"albitas-IV\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/10\/albitas-IV.jpg\" class=\"aligncenter size-full wp-image-26411\" alt=\"albitas-IV\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/10\/albitas-IV.jpg\" width=\"620\" height=\"465\" \/><\/p>\n<p>El partido fue un mon\u00f3logo de las dirigidas por Diego Guacci. Al minuto de juego, la UAI Urquiza, ya ganaba 1 a 0 con gol de Florencia Bonsegundo. A los cuatro estiraron la ventaja con el tanto de Paula Ugarte y a los diez Mercedes Pereyra puso el 3 a 0. A los 12 lleg\u00f3 el gol de Ail\u00e9n Acevedo. Un minuto despu\u00e9s Mariana Gait\u00e1n ampli\u00f3 la goleada. A los 17 minutos, nuevamente, Florencia Bonsegundo se anotaba en la red para marcar el 6 a 0.<\/p>\n<p>Los \u00faltimos cuatro goles, de la parte inicial, llegaron a los 23 y 34 minutos en los pies de Ail\u00e9n Acevedo y, luego, Florencia Bonsegundo a los 35 y Mariana Gait\u00e1n a los 37 cerraron los primeros 45 minutos con un 10 a 0 a favor del Furg\u00f3n.<\/p>\n<p><a href=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/10\/albitas-II.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"26409\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2013\/10\/09\/duro-traspie-de-las-albitas-en-el-debut\/albitas-ii-5\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/10\/albitas-II.jpg\" data-orig-size=\"620,465\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"albitas-II\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/10\/albitas-II.jpg\" class=\"aligncenter size-full wp-image-26409\" alt=\"albitas-II\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/10\/albitas-II.jpg\" width=\"620\" height=\"465\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>De ese primer tiempo poco y nada de All Boys que no encontraba respuestas y le costaba mantener la pelota debido a la presi\u00f3n ejercida por las Universitarias, que parec\u00edan que el resultado parcial les quedaba corto y el segundo tiempo fueron por m\u00e1s, y valla que lo lograron.<\/p>\n<p>R\u00e1pidamente, a los 5 minutos del complemento, Macarena S\u00e1nchez marc\u00f3 su primer tanto y el n\u00famero 11 para el local, mientras que tres minutos despu\u00e9s Tamara G\u00f3mez aument\u00f3 la cuenta a 12 goles. La goleada continu\u00f3 con otros dos goles de la ingresada Macarena S\u00e1nchez a los 10 y 14 minutos. Un minuto luego Gait\u00e1n marc\u00f3 su tercer tanto a nivel personal y el n\u00famero 15 del equipo de UAI Urquiza.<\/p>\n<p>Siguiendo con su olfato de gol Macarena S\u00e1nchez, a los 16, 28 y 32 minutos, volvi\u00f3 a hacerse presente en el marcador y, a falta de diez minutos para el final, Pereyra puso el gol n\u00famero 19 para las de Guacci.<\/p>\n<p>Cerraron la faena de goles en la tarde del Lunes Macarena S\u00e1nchez, a los 40 minutos, Florencia Bonsegundo, a los 42, y, a los 42, Agustina Barroso Basualdo puso cifras definitivas al partido.<\/p>\n<p>&nbsp;<\/p>\n<p>Flojo debut de las Albitas que en ning\u00fan momento del encuentro lograron entrar en la sinton\u00eda del partido y deber\u00e1n trabajar mucho para no volver a sufrir esta clase de derrotas, sin dejar de lado el gran nivel que presentan las jugadoras de UAI que, nuevamente, buscaran hacerle frente a River y Boca en la cima del Torneo Inicial.<\/p>\n<p>La segunda fecha, All Boys, ser\u00e1 local el d\u00eda S\u00e1bado en cancha de la Liga Mercedina frente a Platense en un choque de cuadros de similares urgencias. De cara a lo que viene habr\u00e1 que esperar las recuperaciones de Lopardo, Sosa, Trejo y Silva que debieron abandonar el juego por diferentes lesiones musculares u golpes en el juego. A su vez se espera contar con la recientemente convocada al Seleccionado Nacional Sub 20, la jugadora, Lourdes Castro que, debido a un golpe recibido la pasada semana frente a Excursionistas, no pudo ser de la partida.<\/p>\n<p>&nbsp;<\/p>\n<h2><span style=\"color: #000080;\"><strong>Declaraciones<\/strong><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"26407\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2013\/10\/09\/duro-traspie-de-las-albitas-en-el-debut\/albita\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/10\/albita.jpg\" data-orig-size=\"620,924\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"albita\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/10\/albita.jpg\" class=\"aligncenter size-full wp-image-26407\" alt=\"albita\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/10\/albita.jpg\" width=\"620\" height=\"924\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/10\/albita.jpg 620w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/10\/albita-416x620.jpg 416w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p><span style=\"color: #000080;\"><strong>Milagros Trejo (All Boys)<\/strong><\/span><\/p>\n<p>La volante del cuadro local, que debi\u00f3 abandonar el campo por un golpe, nos dejo estas frases:<\/p>\n<p>\u201cSab\u00edamos la dimensi\u00f3n del rival que ten\u00edamos enfrente, sin embargo, hab\u00edamos planteado un partido para lograr abastecer r\u00e1pido a nuestras delanteros pero la jerarqu\u00eda de esta clase de rivales hace dif\u00edcil imponer tu estilo, m\u00e1s a\u00fan, si te convierten tan r\u00e1pido y no reaccionas al instante\u201d.<\/p>\n<p>\u201c Frente a Platense nos jugamos mucho en lo an\u00edmico, es decir, ver si somos capaces de dar vuelta la p\u00e1gina y mostrar que el resultado frente a UAI es mentiroso y nosotras podemos estar m\u00e1s arriba, es cuesti\u00f3n de propon\u00e9rselo a nivel grupal y ponerlo en pr\u00e1ctica en la cancha. Confi\u00f3 plenamente en el equipo y vamos a lograrlo, tenemos con que\u201d<\/p>\n<p>\u201c Ya ven\u00eda golpeada del tobillo del juego pasado frente a Excursionistas y , durante el primer tiempo, recib\u00ed un golpe en la misma zona que provoc\u00f3 que r\u00e1pidamente se me hinche la zona afectada. Esto no me permit\u00eda trasladarme c\u00f3modamente en la cancha, por lo que, el cambio fue para prevenir una \u201clesi\u00f3n\u201d m\u00e1s complicada. Igualmente el dolor ya ha calmado y quiero estar el pr\u00f3ximo partido contra Platense\u201d<\/p>\n<h2><span style=\"color: #000080;\"><strong>Otros resultados de la Primera Fecha del Torneo Inicial<\/strong><\/span><\/h2>\n<p>Boca 18. &#8211;\u00a0San Carlos 1<\/p>\n<p>Independiente 2. -Ferro 0.<\/p>\n<p>Sociedad Hebraica 1. -Excursionistas 3.<\/p>\n<p>Puerto Nuevo 0.-\u00a0Estudiantes 2.<\/p>\n<p>River Plate 5. &#8211;\u00a0UBA 1.<\/p>\n<p>Platense 0. &#8211;\u00a0Hurac\u00e1n 3.<\/p>\n<p>Libre: San Lorenzo de Almagro<\/p>\n<h2><span style=\"color: #000080;\"><b>Posiciones<\/b><\/span><\/h2>\n<table width=\"537\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td valign=\"bottom\" width=\"193\">\n<p align=\"center\">EQUIPOS<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"57\">\n<p align=\"center\">PTS<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">J<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">G<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">E<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">P<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"43\">\n<p align=\"center\">GF<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"43\">\n<p align=\"center\">GC<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"47\">\n<p align=\"center\">Dif<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"bottom\" width=\"193\">UAI Urquiza<\/td>\n<td valign=\"bottom\" width=\"57\">\n<p align=\"center\">3<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">1<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">1<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"43\">\n<p align=\"center\">22<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"43\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"47\">\n<p align=\"center\">22<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"bottom\" width=\"193\">Boca<\/td>\n<td valign=\"bottom\" width=\"57\">\n<p align=\"center\">3<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">1<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">1<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"43\">\n<p align=\"center\">18<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"43\">\n<p align=\"center\">1<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"47\">\n<p align=\"center\">17<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"bottom\" width=\"193\">River<\/td>\n<td valign=\"bottom\" width=\"57\">\n<p align=\"center\">3<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">1<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">1<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"43\">\n<p align=\"center\">5<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"43\">\n<p align=\"center\">1<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"47\">\n<p align=\"center\">4<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"bottom\" width=\"193\">Hurac\u00e1n<\/td>\n<td valign=\"bottom\" width=\"57\">\n<p align=\"center\">3<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">1<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">1<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"43\">\n<p align=\"center\">3<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"43\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"47\">\n<p align=\"center\">3<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"bottom\" width=\"193\">Excursionistas<\/td>\n<td valign=\"bottom\" width=\"57\">\n<p align=\"center\">3<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">1<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">1<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"43\">\n<p align=\"center\">3<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"43\">\n<p align=\"center\">1<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"47\">\n<p align=\"center\">2<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"bottom\" width=\"193\">Estudiantes LP<\/td>\n<td valign=\"bottom\" width=\"57\">\n<p align=\"center\">3<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">1<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">1<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"43\">\n<p align=\"center\">2<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"43\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"47\">\n<p align=\"center\">2<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"bottom\" width=\"193\">Independiente<\/td>\n<td valign=\"bottom\" width=\"57\">\n<p align=\"center\">3<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">1<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">1<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"43\">\n<p align=\"center\">2<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"43\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"47\">\n<p align=\"center\">2<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"bottom\" width=\"193\">Puerto Nuevo<\/td>\n<td valign=\"bottom\" width=\"57\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">1<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">1<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"43\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"43\">\n<p align=\"center\">2<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"47\">\n<p align=\"center\">-2<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"bottom\" width=\"193\">Ferro<\/td>\n<td valign=\"bottom\" width=\"57\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">1<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">1<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"43\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"43\">\n<p align=\"center\">2<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"47\">\n<p align=\"center\">-2<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"bottom\" width=\"193\">Soc.Hebraica Arg.<\/td>\n<td valign=\"bottom\" width=\"57\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">1<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">1<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"43\">\n<p align=\"center\">1<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"43\">\n<p align=\"center\">3<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"47\">\n<p align=\"center\">-2<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"bottom\" width=\"193\">Platense<\/td>\n<td valign=\"bottom\" width=\"57\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">1<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">1<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"43\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"43\">\n<p align=\"center\">3<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"47\">\n<p align=\"center\">-3<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"bottom\" width=\"193\">UBA<\/td>\n<td valign=\"bottom\" width=\"57\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">1<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">1<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"43\">\n<p align=\"center\">1<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"43\">\n<p align=\"center\">5<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"47\">\n<p align=\"center\">-4<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"bottom\" width=\"193\">Villa San Carlos<\/td>\n<td valign=\"bottom\" width=\"57\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">1<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">1<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"43\">\n<p align=\"center\">1<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"43\">\n<p align=\"center\">18<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"47\">\n<p align=\"center\">-17<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"bottom\" width=\"193\">V\u00e9lez de Mercedes<\/td>\n<td valign=\"bottom\" width=\"57\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">1<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">1<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"43\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"43\">\n<p align=\"center\">22<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"47\">\n<p align=\"center\">-22<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"bottom\" width=\"193\">San Lorenzo<\/td>\n<td valign=\"bottom\" width=\"57\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"38\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"43\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"43\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"bottom\" width=\"47\">\n<p align=\"center\">0<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Por Juanito Men\u00e9ndez \u00a0 (producci\u00f3n y fotos) En Villa Lynch, el equipo de V\u00e9lez-All Boys, se vio ampliamente superado por &#8230; <a title=\"Duro traspi\u00e9 de las Albitas en el debut\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2013\/10\/09\/duro-traspie-de-las-albitas-en-el-debut\/\" aria-label=\"Leer m\u00e1s sobre Duro traspi\u00e9 de las Albitas en el debut\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[21],"tags":[1554,1026,3988,3533],"class_list":["post-26405","post","type-post","status-publish","format-standard","hentry","category-deportes","tag-albitas","tag-all-boys-femenino","tag-duro-traspie-de-las-albitas-en-el-debut","tag-juanito-menendez","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","wps_subtitle":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/26405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=26405"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/26405\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=26405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=26405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=26405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}