{"id":28083,"date":"2013-12-09T00:17:39","date_gmt":"2013-12-09T00:17:39","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=28083"},"modified":"2013-12-09T13:54:30","modified_gmt":"2013-12-09T13:54:30","slug":"policia-detienen-a-ladores-de-motos-y-bicicletas","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2013\/12\/09\/policia-detienen-a-ladores-de-motos-y-bicicletas\/","title":{"rendered":"Polic\u00eda detienen a ladrones de motos y bicicletas"},"content":{"rendered":"<p><a href=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/12\/policia-bonaerense1.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"28085\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2013\/12\/09\/policia-detienen-a-ladores-de-motos-y-bicicletas\/policia-bonaerense1\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/12\/policia-bonaerense1.jpg\" data-orig-size=\"620,158\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;DCR-DVD403&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1219921809&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.2&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.011111111111111&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"policia-bonaerense1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/12\/policia-bonaerense1.jpg\" class=\"aligncenter size-full wp-image-28085\" alt=\"policia-bonaerense1\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2013\/12\/policia-bonaerense1.jpg\" width=\"620\" height=\"158\" \/><\/a><\/p>\n<p><em><strong>La polic\u00eda local detuvo a personas vinculadas al robo de motocicletas y bicicletas, dos de los elementos que m\u00e1s se sustraen por su facilidad de movimiento, rapidez de ejecuci\u00f3n y f\u00e1cil desprendimiento para los delincuentes. Es siempre una cuesti\u00f3n de acci\u00f3n para los efectivos que en esta ocasi\u00f3n realizaron detenciones.<\/strong><\/em><\/p>\n<p>Si bien puede considerarse normal ya a esta altura el robo y recuperaci\u00f3n de motos y bicicletas, no caben dudas que se trata de una buena noticia para los propietarios y, l\u00f3gicamente, en extensi\u00f3n para la ciudadan\u00eda<\/p>\n<h2>Motos<\/h2>\n<p>El pasado d\u00eda 23 de noviembre la Polic\u00eda logr\u00f3 detener en inmediaciones de calles 24 y 45 a un sujeto de 22 a\u00f1os, quien instantes antes hab\u00eda robado de la puerta de la casa ubicada en calle 24 entre 45 y 47, una motocicleta Mondial 110, propiedad de un joven que estaba visitando a una amiga que se domicilia en el lugar. La moto fue devuelta a su propietario.<\/p>\n<h2>Bicicletas<\/h2>\n<p>El reconocimiento de la bicicleta lo hicieron los vecinos. Todo ocurri\u00f3 cuando una se\u00f1ora pasa caminando junto a su marido por un local de bicicleter\u00eda ubicado en la calle 15 y 50, y al mirar el interior del local observa que la bicicleta de su hija (color rosa y rodado 16), la que el d\u00eda anterior le hab\u00eda sido robada del patio de su casa, se encontraba junto a otros rodados de ese tipo, por eso se entrevist\u00f3 con el propietario del comercio quien le dijo que a ese rodado hab\u00eda sido llevado para ser mejorado por dos \u201cmuchachitos\u201d que se domicilian muy cerca del lugar. \u00a0A partir de all\u00ed la due\u00f1a de la bicicleta se hizo presente en la Comisaria y, de esta forma, se inici\u00f3 una causa con intervenci\u00f3n de la Fiscal\u00eda en turno. Fuentes Policiales informaron que este tipo de hechos ocurre habitualmente, y lo que se recomienda es dar aviso en forma inmediata al 911 para lograr un r\u00e1pido esclarecimiento del hecho.<\/p>\n<h2>Desde Moreno<\/h2>\n<p>D\u00edas atr\u00e1s fue denunciado en la Comisaria local el robo de una bicicleta que se encontraba estacionada en zona c\u00e9ntrica; es as\u00ed que luego de tomar nota de las caracter\u00edsticas del rodado, los m\u00f3viles que recorren la ciudad iniciaron su b\u00fasqueda, logrando dar en calle 10 y 25 con la misma y, l\u00f3gico, con quien la hab\u00eda robado, trat\u00e1ndose de Carlos G\u00f3mez, de 54 a\u00f1os, domiciliado en la ciudad de Moreno. Es por eso que se trata de determinar si este delincuente cometi\u00f3 hechos similares en esta ciudad y en localidades vecinas, ya que se determin\u00f3 que el mismo se hab\u00eda hecho presente a Mercedes, en tren de la l\u00ednea Sarmiento. Por otro lado, el rodado, de alto valor econ\u00f3mico, fue devuelto a su propietario, quien muy feliz lo recibi\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La polic\u00eda local detuvo a personas vinculadas al robo de motocicletas y bicicletas, dos de los elementos que m\u00e1s se &#8230; <a title=\"Polic\u00eda detienen a ladrones de motos y bicicletas\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2013\/12\/09\/policia-detienen-a-ladores-de-motos-y-bicicletas\/\" aria-label=\"Leer m\u00e1s sobre Polic\u00eda detienen a ladrones de motos y bicicletas\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[85],"tags":[126,4304,4305],"class_list":["post-28083","post","type-post","status-publish","format-standard","hentry","category-policial","tag-policia-mercedes","tag-robo-bicicletas","tag-robo-motocicletas","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","wps_subtitle":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/28083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=28083"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/28083\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=28083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=28083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=28083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}