{"id":29568,"date":"2014-02-02T05:01:16","date_gmt":"2014-02-02T05:01:16","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=29568"},"modified":"2014-02-02T05:06:46","modified_gmt":"2014-02-02T05:06:46","slug":"mic-se-manifiesta-e-informa-sobre-linea-57-y-trenes-publicos","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2014\/02\/02\/mic-se-manifiesta-e-informa-sobre-linea-57-y-trenes-publicos\/","title":{"rendered":"MIC se manifiesta e informa sobre L\u00ednea 57 y Trenes P\u00fablicos"},"content":{"rendered":"<p><em><strong>Por MIC Mercedes \/ El Eje vertebrador del MIC es la Educaci\u00f3n, el acceso a la informaci\u00f3n para que el ciudadano tenga un mejor conocimiento de la realidad social. Consecuentemente nuestra metodolog\u00eda de trabajo es ir al territorio, ver la problem\u00e1tica, dialogar con los vecinos y los organismos y\/o instituciones vinculadas a la problem\u00e1tica social.<\/strong><\/em><\/p>\n<p>En este primer mes del a\u00f1o deton\u00f3, entre otras problem\u00e1ticas sociales que afectan a los mercedinos, el aumento de las tarifas de los servicios p\u00fablicos de automotores para pasajeros. Creemos que no tenemos que quedarnos con la mirada puesta en un solo servicio de transporte p\u00fablico, sino que debemos analizar el sistema de transporte en general.<\/p>\n<p>El mayor flujo de transporte de nuestra ciudad es hacia el Este Mercedes, Luj\u00e1n, Moreno, Ciudad Aut\u00f3noma de Buenos Aires.<\/p>\n<p>No vamos a escribir la historia del transporte p\u00fablico en Mercedes, ni vamos a recordar que a fines del a\u00f1o 2010 vino la actual Presidenta de la Rep\u00fablica Argentina, que junto al actual Intendente Municipal inauguraron simb\u00f3licamente (ya que estaba en funcionamiento) un servicio ferroviario diferencial Mercedes \u2013 Once, que lamentablemente para los mercedinos no tuvo \u00e9xito.<\/p>\n<h2><strong>\u00bfQu\u00e9 ocurri\u00f3 en los \u00faltimos tiempos?<\/strong><\/h2>\n<p>El funcionamiento del servicio de trenes de pasajeros Mercedes \u2013 Moreno es responsabilidad de SOFSE (Operadora Ferroviaria Sociedad del Estado) que depende del Ministerio del Interior y Transporte de la Naci\u00f3n, cuyo titular es Florencio Randazzo.<\/p>\n<p>A partir del 16 de diciembre de 2013 se habilitaron 17 servicios ferroviarios diarios de ida y vuelta Mercedes \u2013 Moreno, seguramente para tratar de ofrecer una alternativa ante el inminente aumento significativo de tarifas del servicio p\u00fablico automotor. Pero \u00bfla infraestructura ferroviaria y la cantidad y el estado de los veh\u00edculos eran \u00f3ptimos para brindar un servicio eficiente a los mercedinos?<\/p>\n<p>Las tarifas del servicio ferroviario de SOFSE no sufrieron aumentos, hoy se abona con tarjeta SUBE:<\/p>\n<p>Mercedes \u2013 Luj\u00e1n $ 1,75.<\/p>\n<p>Mercedes \u2013 Moreno $ 3,10.<\/p>\n<p>Mercedes \u2013 Once $ 5,10.<\/p>\n<p>Pero comprobamos que algunos servicios se cancelan o no cumplen con el recorrido total.<\/p>\n<p>Por Resoluci\u00f3n 1609\/13 del Ministerio del Interior y Transporte de la Naci\u00f3n modificatoria de la Resoluci\u00f3n 975\/2012, se habilita a aplicar un aumento tarifario, a partir del 1 de enero de 2014, a las l\u00edneas suburbanas Grupo II entre las que se encuentra la L\u00ednea 57 de la Empresa Transportes Atl\u00e1ntida S.A.<\/p>\n<p>En el Anexo I el aumento tarifario supera el 66 % respecto a la Resoluci\u00f3n anterior.<\/p>\n<p>Hoy se abona con tarjeta SUBE;<\/p>\n<p>Mercedes \u2013 Luj\u00e1n $ 12,50.<\/p>\n<p>Mercedes \u2013 Moreno $ 22,20.<\/p>\n<p>Mercedes \u2013 Once $ 42,50.<\/p>\n<p>Mercedes \u2013 Palermo $ 39,00.<\/p>\n<p>El tiempo transcurrido entre ambas Resoluciones es de 12 meses y el aumento salarial en general, en ese per\u00edodo, es muy inferior al porcentaje del incremento de tarifas.<\/p>\n<p>En Mercedes se realizaron Asambleas P\u00fablicas y se juntaron firmas contra el tarifazo del 57, de las que particip\u00f3 el MIc a trav\u00e9s del Concejal Juan Carlos Badano.<\/p>\n<p>Los concejales del MIC Jos\u00e9 Cestari y Juan Carlos Badano se reunieron con el intendente interino Marcelo Den\u00e1pole para interiorizarse del di\u00e1logo que hab\u00eda mantenido con el Presidente de la Empresa Transportes Atl\u00e1ntida SA, Pablo Cross y el Jefe de Servicios Ren\u00e9 Pancardi.<\/p>\n<p>Se dialog\u00f3 con usuarios y empleados de los servicios p\u00fablicos de pasajeros, ferroviario y automotor.<\/p>\n<h2><strong>Conclusiones.<\/strong><\/h2>\n<p>&#8211; El MIC rechaza el aumento que supera el 66 % de las tarifas de la L\u00ednea 57 de la Empresa Transportes Atl\u00e1ntida S A, que incide fundamentalmente en trabajadores y estudiantes.<\/p>\n<p>&#8211; Ante el hecho consumado de la autorizaci\u00f3n del aumento tarifario por parte del Ministerio del Interior y Transporte de la Naci\u00f3n, hay que controlar, a trav\u00e9s de la CNRT (Comisi\u00f3n Nacional de Regulaci\u00f3n del Transporte) que la Empresa Privada brinde la prestaci\u00f3n del servicio automotor acorde a la legislaci\u00f3n vigente.<\/p>\n<p>&#8211; Hay que controlar que el transporte ferroviario estatal mejore y que preste un servicio alternativo y \u00f3ptimo, que no sea una tortura o incertidumbre viajar en tren para el usuario.<\/p>\n<p>Entonces el Bloque MiC present\u00f3 los siguientes Proyectos:<\/p>\n<p>1) RESOLUCI\u00d3N<\/p>\n<p>Art 1\u00b0. El HCD se dirige al Presidente de la Empresa Transportes Atl\u00e1ntida S.A. y a la Gerencia de Calidad y Prestaci\u00f3n de Servicios de la CNRT (Comisi\u00f3n Nacional de Regulaci\u00f3n del Transporte) para que informen:<\/p>\n<p>1) Si el servicio de transporte p\u00fablico de pasajeros de la L\u00ednea 57 de la Empresa Transportes Atl\u00e1ntida S.A. en su recorrido Mercedes \u2013 Palermo (CABA) y Mercedes \u2013 Once (CABA) aplica los siguientes descuentos tarifarios seg\u00fan la legislaci\u00f3n vigente:<\/p>\n<p>a) 40 % jubilados y\/o pensionados.<\/p>\n<p>b) 40 % Veteranos de Guerra de Malvinas.<\/p>\n<p>c) 40 % Personal de Trabajo Dom\u00e9stico.<\/p>\n<p>d) 40 % Asignaci\u00f3n Universal por hijo.<\/p>\n<p>e) 20 % Estudiantes Universitarios, Terciarios y Docentes.<\/p>\n<p>f) Boleto estudiantil para estudiantes del nivel primario y secundario.<\/p>\n<p>2) En caso de no aplicarse algunos de los incisos del punto 1) especificar los motivos.<\/p>\n<p>2) RESOLUCI\u00d3N<\/p>\n<p>Art. 1\u00b0. El HCD se dirige al Ministro del Interior y Transporte de la Rep\u00fablica Argentina y al responsable del SOFSE (Operadora Ferroviaria Sociedad del Estado) del recorrido Mercedes \u2013 Moreno para que informen:<\/p>\n<p>a) De los 17 servicios ferroviarios diarios de ida y vuelta Mercedes \u2013 Moreno, del 16 de diciembre de 2013 al 31 de enero de 2014:<\/p>\n<p>\u00bfCu\u00e1ntos se cancelaron por d\u00eda?<\/p>\n<p>\u00bfCu\u00e1les fueron los motivos?<\/p>\n<p>\u00bfCu\u00e1ntos no terminaron su recorrido total por d\u00eda?<\/p>\n<p>\u00bfCu\u00e1les fueron los motivos?<\/p>\n<p><span style=\"line-height: 1.5em;\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por MIC Mercedes \/ El Eje vertebrador del MIC es la Educaci\u00f3n, el acceso a la informaci\u00f3n para que el &#8230; <a title=\"MIC se manifiesta e informa sobre L\u00ednea 57 y Trenes P\u00fablicos\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2014\/02\/02\/mic-se-manifiesta-e-informa-sobre-linea-57-y-trenes-publicos\/\" aria-label=\"Leer m\u00e1s sobre MIC se manifiesta e informa sobre L\u00ednea 57 y Trenes P\u00fablicos\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[5],"tags":[4115,321,1956],"class_list":["post-29568","post","type-post","status-publish","format-standard","hentry","category-politica","tag-carlos-badano","tag-jose-cestari","tag-mic-mercedes","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","wps_subtitle":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/29568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=29568"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/29568\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=29568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=29568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=29568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}