{"id":29701,"date":"2014-02-06T23:24:27","date_gmt":"2014-02-06T23:24:27","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=29701"},"modified":"2014-02-06T23:24:27","modified_gmt":"2014-02-06T23:24:27","slug":"frente-gremial-docente-exige-la-convocatoria-de-paritarias","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2014\/02\/06\/frente-gremial-docente-exige-la-convocatoria-de-paritarias\/","title":{"rendered":"Frente Gremial docente exige la convocatoria de paritarias"},"content":{"rendered":"<p><a href=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2014\/02\/suteba-frentegremialdocente.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"29705\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2014\/02\/06\/frente-gremial-docente-exige-la-convocatoria-de-paritarias\/suteba-frentegremialdocente\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2014\/02\/suteba-frentegremialdocente.jpg\" data-orig-size=\"620,416\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;NIKON D7000&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1384449048&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;18&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.005&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"suteba-frentegremialdocente\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2014\/02\/suteba-frentegremialdocente.jpg\" class=\"aligncenter size-full wp-image-29705\" alt=\"suteba-frentegremialdocente\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2014\/02\/suteba-frentegremialdocente.jpg\" width=\"620\" height=\"416\" \/><\/a><\/p>\n<p><em><strong>El Frente Gremial Docente Bonaerense (FGDB), reunido en el d\u00eda de la fecha en la sede del SUTEBA, resolvi\u00f3 exigir al Gobierno de la Provincia de Buenos Aires la urgente convocatoria a paritarias docentes para discutir aumentos de salarios y condiciones de trabajo.<\/strong><\/em><\/p>\n<p>La falta de convocatoria para discutir estos temas y otros que afectan a los trabajadores de la Educaci\u00f3n de la Provincia de Buenos Aires, como la falta en tiempo y forma del pago del salario y de las Asignaciones Familiares, la par\u00e1lisis en el \u00e1rea de infraestructura, las irregularidades en las prestaciones del IOMA, el congelamiento de cargos docentes, entre otros; marca un horizonte de conflicto.<\/p>\n<p>El Gobierno debe entender que en la Educaci\u00f3n las problem\u00e1ticas no son una cuesti\u00f3n coyuntural ni de resoluci\u00f3n unilateral, sino que deben abordarse en forma integral y con di\u00e1logo permanente para resolver los conflictos educativos.<\/p>\n<p>AMET \u2013 FEB \u2013 SADOP \u2013 SUTEBA \u2013 UDA<\/p>\n<p><span style=\"color: #888888;\">Fuente: Frente Gremial Docente<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Frente Gremial Docente Bonaerense (FGDB), reunido en el d\u00eda de la fecha en la sede del SUTEBA, resolvi\u00f3 exigir &#8230; <a title=\"Frente Gremial docente exige la convocatoria de paritarias\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2014\/02\/06\/frente-gremial-docente-exige-la-convocatoria-de-paritarias\/\" aria-label=\"Leer m\u00e1s sobre Frente Gremial docente exige la convocatoria de paritarias\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[23],"tags":[4603,37],"class_list":["post-29701","post","type-post","status-publish","format-standard","hentry","category-educacion","tag-frente-gremial","tag-suteba","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","wps_subtitle":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/29701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=29701"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/29701\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=29701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=29701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=29701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}