{"id":3100,"date":"2011-03-30T05:06:33","date_gmt":"2011-03-30T05:06:33","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=3100"},"modified":"2011-03-30T05:07:53","modified_gmt":"2011-03-30T05:07:53","slug":"judiciales-tensa-espera-con-asamblea-hasta-las-11-00","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2011\/03\/30\/judiciales-tensa-espera-con-asamblea-hasta-las-11-00\/","title":{"rendered":"Judiciales: Tensa espera con asamblea hasta las 11.00"},"content":{"rendered":"<p>La jornada de este mi\u00e9rcoles seguramente ser\u00e1 muy importante para el futuro de la Asociaci\u00f3n Judicial Bonaerense y sus reclamos salariales ya que desde la 9.00 se llevar\u00e1 a cabo en La Plata un nuevo encuentro entre representantes del gremio e integrantes del Gobierno de Daniel Scioli para acordar un nuevo porcentaje de incremento salarial debido a que el 21% oportunamente ofrecido desde el Ejecutivo provincial fue rechazado de plano por insuficiente por los trabajadores quienes luego en diferentes asambleas decidieron retornar a la aplicaci\u00f3n de medidas de fuerza.<\/p>\n<p>Tras haber fracasado el encuentro previsto para el lunes \u00faltimo, hoy la mesa provincial de la AJB resolvi\u00f3 que en cada una de las Departamentales se hagan asambleas en los lugares de trabajo desde las 8.00 hasta las 11.00, hora que se estima estar\u00eda finalizando la reuni\u00f3n de partes en la capital bonaerense.<\/p>\n<p>Alberto Igoldi, titular de la AJB Mercedes sostuvo \u00abnosotros vamos a permanecer en La Plata hasta que se pueda decir que existe una definici\u00f3n, ya sea porque se presenta una nueva propuesta o bien porque directamente las conversaciones llegaron a un punto tal de estancamiento que hace virtualmente imposible intentar al menos un nuevo di\u00e1logo con el gobierno provincial debido a que las diferencias son realmente muy importantes.<\/p>\n<p>Nosotros vamos a estar en permanente comunicaci\u00f3n con la asamblea que se realiza en el Palacio de Tribunales de nuestra ciudad y seg\u00fan el resultado que se obtenga, ser\u00e1 la asamblea la que disponga que medidas se van a adoptar\u00bb<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La jornada de este mi\u00e9rcoles seguramente ser\u00e1 muy importante para el futuro de la Asociaci\u00f3n Judicial Bonaerense y sus reclamos &#8230; <a title=\"Judiciales: Tensa espera con asamblea hasta las 11.00\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2011\/03\/30\/judiciales-tensa-espera-con-asamblea-hasta-las-11-00\/\" aria-label=\"Leer m\u00e1s sobre Judiciales: Tensa espera con asamblea hasta las 11.00\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-3100","post","type-post","status-publish","format-standard","hentry","category-opinion","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","wps_subtitle":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/3100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=3100"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/3100\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=3100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=3100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=3100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}