{"id":33039,"date":"2014-05-19T22:42:39","date_gmt":"2014-05-20T01:42:39","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=33039"},"modified":"2014-05-20T08:48:05","modified_gmt":"2014-05-20T11:48:05","slug":"rmp-se-prepara-con-todo-para-el-mundial-de-brasil-y-seguir-a-lucas-biglia","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2014\/05\/19\/rmp-se-prepara-con-todo-para-el-mundial-de-brasil-y-seguir-a-lucas-biglia\/","title":{"rendered":"RPM se prepara con todo para el mundial de Brasil y seguir a Lucas Biglia"},"content":{"rendered":"<p><a href=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2014\/05\/rpmmundial.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"33040\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2014\/05\/19\/rmp-se-prepara-con-todo-para-el-mundial-de-brasil-y-seguir-a-lucas-biglia\/rpmmundial\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2014\/05\/rpmmundial.jpg\" data-orig-size=\"620,876\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"rpmmundial\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2014\/05\/rpmmundial.jpg\" class=\"aligncenter size-full wp-image-33040\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2014\/05\/rpmmundial.jpg\" alt=\"rpmmundial\" width=\"620\" height=\"876\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2014\/05\/rpmmundial.jpg 620w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2014\/05\/rpmmundial-438x620.jpg 438w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/a><\/p>\n<p><em><strong>(RMP) La Radio P\u00fablica arranca desde el 2 de junio con \u201cRPM Mundial\u201d, dedicado exclusivamente a la gran cita del mundo futbol\u00edstico que se dar\u00e1 en Brasil.<\/strong><\/em><\/p>\n<p>Esta iniciativa tiene como finalidad acompa\u00f1ar al mercedino Lucas Biglia, quien ser\u00e1 el primer futbolista de esta ciudad en jugar un Mundial de f\u00fatbol en mayores con la camiseta argentina. Hoy Lucas es parte de la preselecci\u00f3n de 30 jugadores y seguramente quedar\u00e1 entre los 23 convocados porque es del gusto del entrenador Alejandro Sabella.<\/p>\n<p>\u201cRPM Mundial\u201d arrancar\u00e1 en el 88.5 del dial este lunes 2 de junio de 19 a 20 horas y ser\u00e1 un programa diario. Todos los d\u00edas los mercedinos estar\u00e1n al tanto de lo que suceda en Brasil con enviados especiales, y adem\u00e1s con informaci\u00f3n al instante desde la producci\u00f3n del programa.<\/p>\n<p>El espacio en el cual se desarrollar\u00e1 RPM Mundial es el que habitualmente ocupa Agust\u00edn Cufr\u00e9 con su \u201cVuelta a casa\u201d, pero que durante junio le dar\u00e1 lugar a esta nueva propuesta de la Radio P\u00fablica. La conducci\u00f3n estar\u00e1 a cargo de Agust\u00edn, junto con Mariano P\u00e9rez, Juanito Men\u00e9ndez y Caroliona Galeano y contar\u00e1 con columnas especializadas de Juli\u00e1n Inzaugarat (DT de Ateneo), Fernando Moner, Andr\u00e9s Monferrand (historia y an\u00e9cdotas mundialistas), Julio Boccalatte, Juan Ferrnadis y la producci\u00f3n general de Pablo Vera.<\/p>\n<p>El programa hablar\u00e1 de la actualidad de los equipos mundialistas, se har\u00e1 historia y adem\u00e1s contar\u00e1 con concursos para los oyentes, con numerosos premios, entre ellos libros de la editorial \u201cAl arco\u201d, especializada en material bibliogr\u00e1fico deportivo.<\/p>\n<p>La Radio P\u00fablica Mercedes vivir\u00e1 a pleno el Mundial siguiendo de cerca los pasos del mercedinos que har\u00e1 historia con la albiceleste: Lucas Biglia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(RMP) La Radio P\u00fablica arranca desde el 2 de junio con \u201cRPM Mundial\u201d, dedicado exclusivamente a la gran cita del &#8230; <a title=\"RPM se prepara con todo para el mundial de Brasil y seguir a Lucas Biglia\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2014\/05\/19\/rmp-se-prepara-con-todo-para-el-mundial-de-brasil-y-seguir-a-lucas-biglia\/\" aria-label=\"Leer m\u00e1s sobre RPM se prepara con todo para el mundial de Brasil y seguir a Lucas Biglia\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[30],"tags":[305,2917,4142,5264],"class_list":["post-33039","post","type-post","status-publish","format-standard","hentry","category-municipio","tag-lucas-biglia","tag-radio-publica-mercedes","tag-rpm","tag-rpmn","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","wps_subtitle":"Siguiendo al primer mercedino en jugar un mundial","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/33039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=33039"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/33039\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=33039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=33039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=33039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}