{"id":3822,"date":"2011-04-28T00:47:45","date_gmt":"2011-04-28T00:47:45","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=3822"},"modified":"2011-04-28T00:47:45","modified_gmt":"2011-04-28T00:47:45","slug":"en-casa-anus-juan-carlos-benitez-lanza-su-candidatura-a-intendente-por-unidad-y-lealtad-2","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2011\/04\/28\/en-casa-anus-juan-carlos-benitez-lanza-su-candidatura-a-intendente-por-unidad-y-lealtad-2\/","title":{"rendered":"En Casa An\u00fas Juan Carlos Ben\u00edtez lanza su candidatura a Intendente por Unidad y Lealtad"},"content":{"rendered":"<figure id=\"attachment_1483\" aria-describedby=\"caption-attachment-1483\" style=\"width: 199px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2011\/01\/benitezII.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"1483\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2011\/01\/06\/benitez-en-mercedes-hay-una-importante-cantidad-de-votos-no-kirchneristas\/benitezii\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2011\/01\/benitezII.jpg\" data-orig-size=\"298,300\" data-comments-opened=\"1\" data-image-title=\"Juan Carlos Ben\u00edtez\" data-image-description=\"&lt;p&gt;Juan Carlos Ben\u00edtez&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Juan Carlos Ben\u00edtez&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2011\/01\/benitezII.jpg\" class=\"size-full wp-image-1483 \" title=\"Juan Carlos Ben\u00edtez\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2011\/01\/benitezII.jpg\" alt=\"Juan Carlos Ben\u00edtez\" width=\"209\" height=\"210\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2011\/01\/benitezII.jpg 298w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2011\/01\/benitezII-150x150.jpg 150w\" sizes=\"auto, (max-width: 209px) 100vw, 209px\" \/><\/a><figcaption id=\"caption-attachment-1483\" class=\"wp-caption-text\">Juan Carlos Ben\u00edtez<\/figcaption><\/figure>\n<p>Este jueves 28 a partir de las 21.00 se llevar\u00e1 a cabo una cena en el local de Jorge An\u00fas en calle 20 en la cual el hoy concejal de Uni\u00f3n Pro, Juan Carlos Ben\u00edtez, lanzar\u00e1 oficialmente su candidatura a Intendente Municipal de Mercedes por Unidad y Lealtad.<br \/>\nLos organizadores sostuvieron que:<br \/>\n<em>\u201cpor el momento preferimos decir candidato a intendente de Unidad y Lealtad porque no sabemos en definitiva como van a quedar las cosas en la provincia en torno al comentado Frente que tanto se la publicitado a lo largo de los \u00faltimos d\u00edas entre Francisco De Narv\u00e1ez y otras fuerzas pol\u00edticas bonaerenses. De cualquier manera cualquiera sea el resultado de dichos intentos nosotros entendemos que ya en nuestra ciudad hay un grupo perfectamente definido que est\u00e1 trabajando en apoyo directo del actual concejal y como en definitiva es el mismo grupo que nos lev\u00f3 a imponernos en el 2009 no deber\u00edamos tener mayores inconvenientes para repetir la conformaci\u00f3n del mismo\u201d.<\/em><\/p>\n<p><em> <\/em><br \/>\nDe esta manera tendremos ya confirmado un candidato m\u00e1s a ocupar el m\u00e1ximo sill\u00f3n de gesti\u00f3n comunal de la ciudad.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este jueves 28 a partir de las 21.00 se llevar\u00e1 a cabo una cena en el local de Jorge An\u00fas &#8230; <a title=\"En Casa An\u00fas Juan Carlos Ben\u00edtez lanza su candidatura a Intendente por Unidad y Lealtad\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2011\/04\/28\/en-casa-anus-juan-carlos-benitez-lanza-su-candidatura-a-intendente-por-unidad-y-lealtad-2\/\" aria-label=\"Leer m\u00e1s sobre En Casa An\u00fas Juan Carlos Ben\u00edtez lanza su candidatura a Intendente por Unidad y Lealtad\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-3822","post","type-post","status-publish","format-standard","hentry","category-opinion","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","wps_subtitle":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/3822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=3822"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/3822\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=3822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=3822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=3822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}