{"id":41130,"date":"2015-04-26T17:18:50","date_gmt":"2015-04-26T20:18:50","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=41130"},"modified":"2015-04-27T11:51:28","modified_gmt":"2015-04-27T14:51:28","slug":"dos-escritores-mercedinos-en-la-feria-del-libro-tito-sanguinetti-y-oscar-dinova","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2015\/04\/26\/dos-escritores-mercedinos-en-la-feria-del-libro-tito-sanguinetti-y-oscar-dinova\/","title":{"rendered":"Dos escritores mercedinos en la 41\u00b0 Feria Internacional del Libro: \u00abTito\u00bb Sanguinetti y Oscar Dinova"},"content":{"rendered":"<p><a href=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2015\/04\/Sanguinetti-Dinova.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"41131\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2015\/04\/26\/dos-escritores-mercedinos-en-la-feria-del-libro-tito-sanguinetti-y-oscar-dinova\/sanguinetti-dinova\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2015\/04\/Sanguinetti-Dinova.jpg\" data-orig-size=\"620,429\" data-comments-opened=\"1\" data-image-title=\"Sanguinetti-Dinova\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2015\/04\/Sanguinetti-Dinova.jpg\" class=\"Img2014 aligncenter wp-image-41131 size-full\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2015\/04\/Sanguinetti-Dinova.jpg\" alt=\"Sanguinetti-Dinova\" width=\"620\" height=\"429\" \/><\/a><\/p>\n<p><em><strong>El s\u00e1bado 25 de Abril era el primer gran d\u00eda de este monumental encuentro de la literatura argentina y latinoamericana en Buenos Aires. Se congregan en ella las m\u00e1s importantes editoriales de habla hispana, autores renombrados, novedades y exposiciones.<\/strong><\/em><\/p>\n<p>Es el punto m\u00e1s alto de las letras y para confirmar su importancia un mundo de gente, venidos de toda la Argentina y pa\u00edses vecinos, que hormiguea curiosa en busca de cl\u00e1sicos y de primicias, de viejos e inolvidables libros y de sorpresas agradables.<\/p>\n<p>En ese marco, dos mercedinos. Elegidos en la oportunidad por la Direcci\u00f3n de Cultura de Mercedes para representarnos.<\/p>\n<p><strong>Alberto \u201cTito\u201d Sanguinetti\u00a0 y Oscar Alberto Dinova.<\/strong><\/p>\n<p>Los dos para representar a Mercedes en el espacio previsto por la Provincia de Buenos Aires, el segundo, adem\u00e1s, para firmar ejemplares en la editorial Dunken.<\/p>\n<p>El primer momento fue pleno de emociones. Nuestros escritores se dirigieron al p\u00fablico presente presentando sus materiales y contando sus experiencias. Tito narr\u00f3 a los presentes la comuni\u00f3n creada entre el arte de las letras y de la m\u00fasica, sus libros y sus discos. En definitiva sus logros.<\/p>\n<p>Y obsequi\u00f3 a los presentes una poes\u00eda que carg\u00f3 de emoci\u00f3n a la tarde capitalina.<\/p>\n<p>Oscar Dinova, les cont\u00f3 como un Abuelo decide un d\u00eda contar a sus nietos sus propias vivencias y las de su comunidad a trav\u00e9s de sus conocidos \u201cCuentos del Abuelo I y II\u201d. Tambi\u00e9n obsequi\u00f3 a los presentes un tramo de las Cr\u00f3nicas de Gardel en Mercedes y la poes\u00eda Cien A\u00f1os no es Nada.<\/p>\n<p>Un aplauso cerrado para nuestros dos representantes que fueron recompensados con dos hermosos certificados y el pedido de fotos del entusiasta p\u00fablico que se iba con el esp\u00edritu pleno.<\/p>\n<p>Oscar Dinova cumpli\u00f3 luego con el compromiso de firmar ejemplares en Dunken y la delegaci\u00f3n parti\u00f3 de regreso a Mercedes, feliz de haber dejado tan bien representado a Mercedes.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El s\u00e1bado 25 de Abril era el primer gran d\u00eda de este monumental encuentro de la literatura argentina y latinoamericana &#8230; <a title=\"Dos escritores mercedinos en la 41\u00b0 Feria Internacional del Libro: \u00abTito\u00bb Sanguinetti y Oscar Dinova\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2015\/04\/26\/dos-escritores-mercedinos-en-la-feria-del-libro-tito-sanguinetti-y-oscar-dinova\/\" aria-label=\"Leer m\u00e1s sobre Dos escritores mercedinos en la 41\u00b0 Feria Internacional del Libro: \u00abTito\u00bb Sanguinetti y Oscar Dinova\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":41131,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[104],"tags":[7232],"class_list":["post-41130","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","tag-tito-sanguinetti-y-oscar-dinova","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2015\/04\/Sanguinetti-Dinova.jpg","wps_subtitle":"Prosa mercedina","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/41130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=41130"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/41130\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/41131"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=41130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=41130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=41130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}