{"id":42700,"date":"2015-06-29T08:27:03","date_gmt":"2015-06-29T11:27:03","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=42700"},"modified":"2015-06-29T08:27:03","modified_gmt":"2015-06-29T11:27:03","slug":"real-madrid-ofrecio-22-millones-por-biglia-aseguraron-en-espana","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2015\/06\/29\/real-madrid-ofrecio-22-millones-por-biglia-aseguraron-en-espana\/","title":{"rendered":"Real Madrid ofreci\u00f3 22 millones por Biglia aseguraron en Espa\u00f1a"},"content":{"rendered":"<p><em><strong>Parece que el Real Madrid ya ha decidido a qu\u00e9 mediocentro quiere para reforzar el equipo. Despu\u00e9s de deshojar la margarita los blancos se lanzan a por el argentino Lucas Biglia o al menos, as\u00ed lo asegura el agente FIFA Alessio Scalera.<\/strong><\/em><\/p>\n<p>En palabras\u00a0al programa Radiosei italiano asegur\u00f3 que la <strong>Lazio<\/strong> le ha dicho de manera formal que \u201cel<strong>Real\u00a0Madrid<\/strong> ha realizado una oferta de <strong>22 millones de euros <\/strong>por <strong>Biglia<\/strong> en los \u00faltimos d\u00edas\u201d.<\/p>\n<p>Adem\u00e1s, dio m\u00e1s detalles de la oferta, ya que la cantidad aumentar\u00eda si el Madrid gana la <strong>Liga o la Liga de Campeones.<\/strong><\/p>\n<p><strong>Lucas Biglia<\/strong> se ha asentado en la <strong>Lazio<\/strong> tras varias temporadas a buen nivel en el Anderlecht y realiz\u00f3 un gran Mundial de Brasil con la selecci\u00f3n de Argentina. Comenz\u00f3 el torneo como suplente pero termin\u00f3 imponi\u00e9ndose a Gago y consolid\u00e1ndose en el once al lado de <strong>Javier Mascherano.\u00a0<\/strong>Tambi\u00e9n est\u00e1 siendo titular en la <a href=\"http:\/\/www.diario-bernabeu.com\/torneos-selecciones\/copa-america\" target=\"_blank\" rel=\"noopener\">Copa Am\u00e9rica<\/a> con el Tata Martino.<\/p>\n<p>Biglia es un <strong>mediocentro equilibrado<\/strong>, que puede actuar como pivote y que da mucha c<strong>onsistencia al centro del campo<\/strong>. Tiene calidad, <strong>buena salida de bal\u00f3n<\/strong> y su paso por el Calcio le ha hecho ganar mayor capacidad de trabajo y brega. Es un centrocampista inteligente y que<strong>trabaja para el colectivo<\/strong>.<\/p>\n<p><a href=\"http:\/\/www.diario-bernabeu.com\/2015\/06\/28\/real-madrid-oferta-biglia-lazio\/31234\" target=\"_blank\" rel=\"noopener\">Fuente:\u00a0www.diario-bernabeu.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Parece que el Real Madrid ya ha decidido a qu\u00e9 mediocentro quiere para reforzar el equipo. Despu\u00e9s de deshojar la &#8230; <a title=\"Real Madrid ofreci\u00f3 22 millones por Biglia aseguraron en Espa\u00f1a\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2015\/06\/29\/real-madrid-ofrecio-22-millones-por-biglia-aseguraron-en-espana\/\" aria-label=\"Leer m\u00e1s sobre Real Madrid ofreci\u00f3 22 millones por Biglia aseguraron en Espa\u00f1a\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":42406,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[21],"tags":[305,7507],"class_list":["post-42700","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","tag-lucas-biglia","tag-mediocampo-lucas-biglia","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2015\/06\/biglialazio.jpg","wps_subtitle":"El gran mediocampista mercedino","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/42700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=42700"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/42700\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/42406"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=42700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=42700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=42700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}