{"id":43423,"date":"2015-07-27T22:29:17","date_gmt":"2015-07-28T01:29:17","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=43423"},"modified":"2015-07-29T00:02:32","modified_gmt":"2015-07-29T03:02:32","slug":"mas-de-300-ninos-disfrutaron-ofertas-culturales-en-vacaciones","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2015\/07\/27\/mas-de-300-ninos-disfrutaron-ofertas-culturales-en-vacaciones\/","title":{"rendered":"M\u00e1s de 300 ni\u00f1os disfrutaron ofertas culturales en vacaciones"},"content":{"rendered":"<p><a href=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2015\/07\/museo-vacaciones.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"43424\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2015\/07\/27\/mas-de-300-ninos-disfrutaron-ofertas-culturales-en-vacaciones\/museo-vacaciones\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2015\/07\/museo-vacaciones.jpg\" data-orig-size=\"620,465\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"museo-vacaciones\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2015\/07\/museo-vacaciones.jpg\" class=\"Img2014 aligncenter wp-image-43424 size-full\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2015\/07\/museo-vacaciones.jpg\" alt=\"museo-vacaciones\" width=\"620\" height=\"465\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2015\/07\/museo-vacaciones.jpg 620w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2015\/07\/museo-vacaciones-150x113.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2015\/07\/museo-vacaciones-290x218.jpg 290w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2015\/07\/museo-vacaciones-50x38.jpg 50w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/a><\/p>\n<p><em><strong>El receso invernal es una excelente oportunidad para disfrutar de los distintos espacios de la ciudad, y estas vacaciones no son la excepci\u00f3n. Grandes y chicos disfrutan de esta primer semana de actividades con una gran convocatoria en los espacios de arte y recreativos.<\/strong><\/em><\/p>\n<p>El gobierno del intendente Carlos Selva, a trav\u00e9s de las distintas \u00e1reas municipales, viene trabajando hace m\u00e1s de diez a\u00f1os para ofrecer a los chicos actividades gratuitas en los Museos de la ciudad, teatro y dem\u00e1s espacios de esparcimiento. Cada vez m\u00e1s, los vecinos recurren a la agenda cultural municipal para disfrutar de los d\u00edas de receso escolar.<\/p>\n<p>\u201cM\u00e1s de 300 pibes participaron de las actividades de cada museo municipal tan s\u00f3lo en esta primera semana de vacaciones. Fue impresionante la convocatoria en la bicicleteada por la calle 26 con los Bicisaurios, la actividad de fotograf\u00eda Estenotopo, y los talleres que llevamos a cabo con la gente de Giro Did\u00e1ctico; entre otras actividades que se desarrollaron a lo largo de las jornadas. Tambi\u00e9n son continuas las visitas a las exposiciones de los Museos y el Foyer del Teatro\u201d, destac\u00f3 Gerardo Caballero, director de Cultura.<\/p>\n<p>El Complejo Cultural ex Teatro Argentino, es el escenario obligado para ver obras teatrales. Algunas de ellas son gratuitas y otras con entradas a valores populares. Desde hace a\u00f1os los padres cuentan con la posibilidad de hacer disfrutar a sus hijos de una obra teatral en Mercedes sin tener que partir hacia la Ciudad de Buenos Aires u otros destinos. Para estos \u00faltimos d\u00edas de vacaciones, la cartelera del Teatro propone las siguientes obras: Lunes 27 a las 16 horas \u201cRapunzel\u201d; martes 28 a las 15 y 17 \u201cDos payasos en acci\u00f3n\u201d; mi\u00e9rcoles 29 a las 16 \u201cCazador de Hadas y Piratas\u201d; jueves 30 a las \u00a016 \u201cBlanca Nieves y Peter Pan\u201d.<\/p>\n<p>\u201cCon las actividades de este a\u00f1o, hemos reconfirmado el \u00e9xito de las pol\u00edticas<\/p>\n<p>culturales del municipio a partir de la gesti\u00f3n de Carlos Selva. Es muy importante y significativo el aprovechamiento del espacio p\u00fablico como los museos, el Observatorio Municipal y el Teatro, donde ya son habituales las actividades a trav\u00e9s de la organizaci\u00f3n de la marat\u00f3n infantil\u201d, concluy\u00f3 el director de Cultura.<\/p>\n<p>Museos abiertos<\/p>\n<p>El Complejo Ameghino \u2013 Mar\u00edn tambi\u00e9n ha recibido a muchos chicos y grandes, sobre todo, a aquellos fan\u00e1ticos de los dinosaurios que vieron pel\u00edculas y participaron de una actividad especial donde pudieron desterrar f\u00f3siles.\u00a0 Adem\u00e1s, esta tarde, el mi\u00e9rcoles y el viernes, de 14 a 16 horas, habr\u00e1 Bicisaurios frente al Museo, en calle 26 entre 23 y 21. Tambi\u00e9n, habr\u00e1 juegos, disfraces y otras actividades tem\u00e1ticas de martes a viernes de 10 a 17; s\u00e1bados y domingos de 13 a 17. El Ameghino est\u00e1 abierto de martes a viernes de 8:00 a 17:00; s\u00e1bados y domingos de 13:00 a 17:00.<\/p>\n<p>Por su parte, el nuevo Museo de Arte Municipalidad de Mercedes , que abre sus puertas de martes a viernes de 08:00 a 14:00; s\u00e1bados y domingos de 09:00 a 12:00, y de 16:00 a 19:00.<\/p>\n<p>Los SUM multiplican actividades en vacaciones<\/p>\n<p>Los Salones de Usos M\u00faltiples de los diferentes barrios de la ciudad ofrecen talleres y actividades diversas en estas semanas. Tambi\u00e9n llegan a los SUM de Gowland y Tom\u00e1s Jofr\u00e9.<\/p>\n<p>Los Salones de Usos M\u00faltiples de gesti\u00f3n municipal tendr\u00e1n durante estas vacaciones de invierno una notoria cantidad de actividades recreativas para los m\u00e1s chicos en los diferentes barrios de Mercedes.<\/p>\n<p>En el barrio San Mart\u00edn, ma\u00f1ana habr\u00e1 un taller de recreaci\u00f3n de 14 a 16 ; el mi\u00e9rcoles se llevar\u00e1 a cabo una jornada recreativa de 15 a 17 con inflables, juegos, merienda y golosinas; y el viernes taller de manualidades y art\u00edstica de 14 a 16.<\/p>\n<p>Por su parte, el SUM del barrio Blandengues hoy y el viernes habr\u00e1 taller de recreaci\u00f3n; martes jornada recreativa de 14 a 16, y el mi\u00e9rcoles taller de manualidades de 17.30 \u00a0a \u00a018.30.<\/p>\n<p>En el barrio Ravello \u00a0hoy habr\u00e1 taller de arte de 14 a 16 ; martes taller de deporte de 14 a 15,30; mi\u00e9rcoles jornada recreativa de 14 a 16 y el jueves taller de deporte de 14 a 16.<\/p>\n<p>En el Villa Industrial Oeste hoy, ma\u00f1ana, jueves y viernes actividades recreativas, manualidades, reciclado de 15 a 17; el mi\u00e9rcoles jornada recreativa de 15 a 17 con inflables, merienda y golosinas.<\/p>\n<p>En el barrio Almafuerte \u00a0ma\u00f1ana se ofrecer\u00e1 un taller de manualidades de 16,30 a 17,30, y el jueves jornada recreativa de \u00a014 a 16. Los SUM de la zona rural tambi\u00e9n tendr\u00e1 actividades gratuitas y abiertas. En Gowland, el martes taller de manualidades de 14 a 15 hs y el mi\u00e9rcoles jornada recreativa de 14 a 16. Y en Tom\u00e1s Jofr\u00e9, los horarios ser\u00e1n los siguientes: Hoy, taller de recreaci\u00f3n de 14 a 16; martes taller de manualidades de 15 a 16 hs; jueves jornada recreativa de 14 a 16; y viernes taller de reciclado de 14 a 16 horas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El receso invernal es una excelente oportunidad para disfrutar de los distintos espacios de la ciudad, y estas vacaciones no &#8230; <a title=\"M\u00e1s de 300 ni\u00f1os disfrutaron ofertas culturales en vacaciones\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2015\/07\/27\/mas-de-300-ninos-disfrutaron-ofertas-culturales-en-vacaciones\/\" aria-label=\"Leer m\u00e1s sobre M\u00e1s de 300 ni\u00f1os disfrutaron ofertas culturales en vacaciones\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":43424,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[104],"tags":[7688],"class_list":["post-43423","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","tag-vacaciones-en-mercedes","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2015\/07\/museo-vacaciones.jpg","wps_subtitle":"Durante la primera semana","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/43423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=43423"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/43423\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/43424"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=43423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=43423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=43423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}