{"id":46611,"date":"2015-12-27T14:13:29","date_gmt":"2015-12-27T17:13:29","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=46611"},"modified":"2016-01-10T19:56:04","modified_gmt":"2016-01-10T22:56:04","slug":"izamal-o-el-magico-perdon","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2015\/12\/27\/izamal-o-el-magico-perdon\/","title":{"rendered":"Izamal o el m\u00e1gico perd\u00f3n"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"46612\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2015\/12\/27\/izamal-o-el-magico-perdon\/dinova-yucatan\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2015\/12\/dinova-yucatan.jpg\" data-orig-size=\"630,841\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"dinova-yucatan\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2015\/12\/dinova-yucatan.jpg\" class=\"aligncenter wp-image-46612\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2015\/12\/dinova-yucatan.jpg\" alt=\"dinova-yucatan\" width=\"620\" height=\"828\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2015\/12\/dinova-yucatan.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2015\/12\/dinova-yucatan-112x150.jpg 112w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2015\/12\/dinova-yucatan-464x620.jpg 464w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p><strong>Por Oscar Dinova \/<\/strong><\/p>\n<p>El color ocre invade los techos y las casas de este pueblo m\u00e1gico. No es un tinte vivaz pero s\u00ed penetrante, no hay resquicio que se salve de su invasiva presencia. No podr\u00edan haber elegido mejor tonalidad para otorgarle una particular identidad a este pueblo que nos espera en las cercan\u00edas de la espa\u00f1ol\u00edsima M\u00e9rida del Yucat\u00e1n.<\/p>\n<p>Es que Izamal es, como pocos, la representaci\u00f3n de la invasi\u00f3n hispana en Am\u00e9rica. Al llegar a este lugar encontraron las construcciones de una de las tantas Ciudades-Estado de la naci\u00f3n maya. Y como ocurriera en Tenochtitl\u00e1n, la capital azteca, la avanzada ib\u00e9rica se dedic\u00f3 a hacer demoler pieza por pieza las pir\u00e1mides, observatorios y casas de gobiernos mayas para construir, con esas mismas piedras, el convento de San Antonio de Padua y el Templo de la Pur\u00edsima Concepci\u00f3n.<\/p>\n<p>El color ocre que se confunde con el atardecer del d\u00eda no es alegre. Es que no hubo felicidad en la refundaci\u00f3n de esta comarca. No existe crueldad ni tristeza m\u00e1s grande sobre la tierra, que la de un pueblo, que se vio obligado a desarmar con sus propias manos los altares de sus dioses de la lluvia y del sol para levantar el gran altar de un Dios barbado que no compart\u00eda la adoraci\u00f3n de los mortales con ning\u00fan otro Dios, por venerado que este fuera.<\/p>\n<p>Con las piedras removidas, las decoraciones destruidas y los m\u00faltiples dioses de la naturaleza y el infinito prohibidos, fue su propia cultura que vieron desvanecerse y mutar en nuevos ritos y mandamientos, hasta entonces desconocidos.<\/p>\n<p>Y m\u00e1s, uno de los primeros obispos de Am\u00e9rica, Diego de Landa, no encontr\u00f3 mejor recurso, para disciplinar a las revoltosas poblaciones mayas expuestas a los encomenderos espa\u00f1oles, que procesarlos con la Santa Inquisici\u00f3n y adem\u00e1s quemar, en un auto de fe, la mayor parte de los c\u00f3dices mayas, libros hechos en un suave papel de la corteza del higo silvestre y escrito en vivos colores. En el fin de sus d\u00edas y buscando quiz\u00e1s una imposible expiaci\u00f3n a sus pecados, Diego de Landa redacta sus memorias, que constituyen un exquisito testimonio de la historia maya. Pero era una copia filtrada por su mirada, los originales estaban carbonizados.<\/p>\n<p>Izamal tambi\u00e9n es una suerte de copia, su verdadero nombre era Zamn\u00e1, \u201croc\u00edo del cielo\u201d, en homenaje a un m\u00edtico personaje, formador del pueblo maya. A estos confines y hace poco tiempo se acerc\u00f3 el m\u00e1ximo representante de la iglesia cat\u00f3lica, el Papa Juan Pablo II. En 1992 ofici\u00f3 una misa por la Virgen y los pueblos originarios.<\/p>\n<p>Pero no pidi\u00f3 perd\u00f3n. No se hinc\u00f3, arrepentido, frente a la sustituci\u00f3n forzada de una cultura por otra, no por haber puesto a campesinos libres en manos de un sistema de esclavitud, disimulada en conversi\u00f3n cristiana, no en haberles prohibido el acceso al humilde pueblo local al mism\u00edsimo encinto de la iglesia, debiendo conformarse con orar en un patio externo, a la sombra misericordiosa de un \u00e1rbol nativo.<\/p>\n<p>Pero el pueblo maya ha obrado un extra\u00f1o milagro. Ha perdonado a sus usurpadores de creencias. Y lo ha hecho de la mejor manera. Llenando de identidad propia las liturgias ajenas. As\u00ed, una cruz verde, emulando a la ceiba, -\u00e1rbol sagrado maya que daba origen a su historia- recoge el cuerpo de un Jes\u00fas sufriente, o haciendo suya a la Virgen de la Guadalupe y recorriendo por ella, centenares de kil\u00f3metros para venerarla, a pie o en humeantes bicicletas que d\u00eda y noche circulan por los caminos del Yucat\u00e1n, buscando un atrio donde depositar una cruz de flores de papel, trenzadas por las mujeres del lugar.<\/p>\n<p>O con un mar de velas encendidas en los altares ind\u00edgenas, que iluminan la noche atiborrada de estrellas, haciendo titilar al mismo tiempo el cielo de dioses perdidos y una tierra sedienta de paz.<\/p>\n<p>Se parece presenciar la redenci\u00f3n de una iglesia opulenta y poderosa en manos de los m\u00e1s humildes. Cristo es sostenido finalmente por los pobres de un pueblo, que nunca desapareci\u00f3, ni perdi\u00f3 su lengua y sus costumbres, aunque les impusieran hasta los nombres for\u00e1neos en los bautizos.<\/p>\n<p>En Izamal se ha tejido, en silencio y con manos \u00e1speras de trabajo y sufrimiento el m\u00e1gico perd\u00f3n. Aquel que s\u00f3lo puede dar quien ha sufrido p\u00e9rdidas lacerantes pero sigue en pie, firmes en sus convicciones y sus or\u00edgenes, algo m\u00e1s bien brillante y esperanzador, aunque las paredes reflejen, obstinadamente, un color ocre, que irremediablemente entristezca el alma.<\/p>\n<p><strong>Por Oscar Dinova, Cr\u00f3nicas de Viaje por el Yucat\u00e1n<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Oscar Dinova \/ El color ocre invade los techos y las casas de este pueblo m\u00e1gico. No es un &#8230; <a title=\"Izamal o el m\u00e1gico perd\u00f3n\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2015\/12\/27\/izamal-o-el-magico-perdon\/\" aria-label=\"Leer m\u00e1s sobre Izamal o el m\u00e1gico perd\u00f3n\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":46612,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[1],"tags":[8352,1288],"class_list":["post-46611","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opinion","tag-cronicas-de-yucatan","tag-oscar-dinova","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2015\/12\/dinova-yucatan.jpg","wps_subtitle":"Cr\u00f3nicas del viaje a Yucat\u00e1n","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/46611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=46611"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/46611\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/46612"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=46611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=46611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=46611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}