{"id":47692,"date":"2016-03-10T23:33:47","date_gmt":"2016-03-11T02:33:47","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=47692"},"modified":"2016-03-10T23:33:47","modified_gmt":"2016-03-11T02:33:47","slug":"comienza-el-torneo-apertura-de-la-liga-mercedina","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2016\/03\/10\/comienza-el-torneo-apertura-de-la-liga-mercedina\/","title":{"rendered":"Comienza el torneo Apertura de la Liga Mercedina"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"46317\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2015\/12\/08\/por-penales-trocha-gano-el-clausura\/musante-ariel-2\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2015\/12\/musante-ariel.png\" data-orig-size=\"630,100\" data-comments-opened=\"1\" data-image-title=\"musante-ariel\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2015\/12\/musante-ariel.png\" class=\"aligncenter size-medium wp-image-46317\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2015\/12\/musante-ariel-630x100.png\" alt=\"musante-ariel\" width=\"630\" height=\"100\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2015\/12\/musante-ariel.png 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2015\/12\/musante-ariel-150x24.png 150w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><\/p>\n<p><em><strong>El certamen de Primera Divisi\u00f3n y Reserva dar\u00e1 inicio este s\u00e1bado con algunos partidos suspendidos por la participaci\u00f3n de Quilmes y El Front\u00f3n en los regionales. En la mayor habr\u00e1 zona \u00fanica, mientras que en la menor los equipos se dividir\u00e1n en tres zonas.<\/strong><\/em><\/p>\n<p>El f\u00fatbol grande la ciudad de Mercedes comenzar\u00e1 este fin de semana con sus torneos de Primera Divisi\u00f3n y Reserva, con la novedad del ingreso de N\u00e1utico El Tim\u00f3n de J\u00e1uregui en ambas divisionales y de Uni\u00f3n en tercera, lo que generar\u00e1 que, al ser impar la cantidad de instituciones participantes, en la mayor haya dos conjuntos libres por fecha mientras que en la menor ser\u00e1 solo uno.<\/p>\n<p>Si bien los dos torneos jugar\u00e1n en la modalidad todos contra todos, en Primera Divisi\u00f3n habr\u00e1 una tabla \u00fanica, mientras que en Reserva los clubes se dividir\u00e1n en tres zonas. La A compuesta por Comunicaciones, Estudiantes, Pabell\u00f3n Argentino, San Marcos FC y Costa Brava; la B por El Front\u00f3n, Trocha, Los Palometas, El Tim\u00f3n y Mercedes; y la C por Juventud, Ateneo, V\u00e9lez Sarsfield, Quilmes y Uni\u00f3n, que jugar\u00e1 con muchos futbolistas provenientes de sus divisiones inferiores y habr\u00e1 un campe\u00f3n por semestre, mientras que en Primera ser\u00e1 el del a\u00f1o.<\/p>\n<p>Fixture de Primera y Reserva (en la mayor quedar\u00e1 libre el que en la tercera enfrente a Uni\u00f3n, adem\u00e1s del que queda libre en la fecha).<\/p>\n<h3>Fecha 1<\/h3>\n<p>V\u00e9lez Sarsfield VS. Pabellon Argentino<\/p>\n<p>Los Palometas VS. Mercedes<\/p>\n<p>El Front\u00f3n VS. Trocha<\/p>\n<p>Costa Brava VS. El Tim\u00f3n<\/p>\n<p>Ateneo VS. Quilmes<\/p>\n<p>San Marcos VS. Estudiantes<\/p>\n<p>Comunicaciones Vs. Uni\u00f3n<\/p>\n<p>Libres: Juventud.<\/p>\n<h3>Fecha 2<\/h3>\n<p>San Marcos VS. V\u00e9lez Sarsfield<\/p>\n<p>Estudiantes VS. Ateneo<\/p>\n<p>Quilmes\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 VS. Costa Brava<\/p>\n<p>El Tim\u00f3n VS. Comunicaciones<\/p>\n<p>Juventud VS. El Front\u00f3n<\/p>\n<p>Trocha VS. Los Palometas<\/p>\n<p>Mercedes VS. Pabellon Argentino<\/p>\n<p>Libre: Uni\u00f3n<\/p>\n<h3>Fecha 3<\/h3>\n<p>V\u00e9lez Sarsfield VS. Mercedes<\/p>\n<p>Pabellon VS. Trocha<\/p>\n<p>Los Palometas VS. Juventud<\/p>\n<p>Comunicaciones VS. Quilmes<\/p>\n<p>Costa Brava VS. Estudiantes<\/p>\n<p>Ateneo VS. San Marcos<\/p>\n<p>El Front\u00f3n Vs. Uni\u00f3n<\/p>\n<p>Libre: El Tim\u00f3n<\/p>\n<h3>Fecha 4<\/h3>\n<p>Ateneo VS. V\u00e9lez Sarsfield<\/p>\n<p>San Marcos VS. Costa Brava<\/p>\n<p>Estudiantes VS. Comunicaciones<\/p>\n<p>El Tim\u00f3n VS. El Front\u00f3n<\/p>\n<p>Juventud VS. Pabellon Argentino<\/p>\n<p>Trocha VS. Mercedes<\/p>\n<p>Uni\u00f3n Vs. Los Palometas<\/p>\n<p>Libres: Quilmes.<\/p>\n<h3>Fecha 5<\/h3>\n<p>V\u00e9lez Sarsfield VS. Trocha<\/p>\n<p>Mercedes VS. Juventud<\/p>\n<p>Los Palometas VS. El Tim\u00f3n<\/p>\n<p>El Front\u00f3n VS. Quilmes<\/p>\n<p>Comunicaciones VS. San Marcos<\/p>\n<p>Costa Brava VS. Ateneo<\/p>\n<p>Pabell\u00f3n Argentino Vs. Uni\u00f3n<\/p>\n<p>Libres: Estudiantes.<\/p>\n<h3>Fecha 6<\/h3>\n<p>Costa Brava VS. V\u00e9lez Sarsfield<\/p>\n<p>Ateneo VS. Comunicaciones<\/p>\n<p>Estudiantes VS. El Front\u00f3n<\/p>\n<p>Quilmes VS. Los Palometas<\/p>\n<p>El Tim\u00f3n VS. Pabellon Argentino<\/p>\n<p>Juventud VS. Trocha<\/p>\n<p>Uni\u00f3n Vs.<\/p>\n<p>Libres: San Marcos FC.<\/p>\n<h3>Fecha 7<\/h3>\n<p>V\u00e9lez Sarsfield VS. Juventud<\/p>\n<p>Mercedes VS. El Tim\u00f3n<\/p>\n<p>Pabellon Argentino VS. Quilmes<\/p>\n<p>Los Palometas VS. Estudiantes<\/p>\n<p>El Front\u00f3n VS. San Marcos<\/p>\n<p>Comunicaciones VS. Costa Brava<\/p>\n<p>Trocha Vs. Uni\u00f3n<\/p>\n<p>Libres: Ateneo.<\/p>\n<h3>Fecha 8<\/h3>\n<p>Comunicaciones VS. V\u00e9lez Sarsfield<\/p>\n<p>Ateneo VS. El Front\u00f3n<\/p>\n<p>San Marcos VS. Los Palometas<\/p>\n<p>Estudiantes VS. Pabellon Argentino<\/p>\n<p>Quilmes VS. Mercedes<\/p>\n<p>El Tim\u00f3n VS. Trocha<\/p>\n<p>Uni\u00f3n Vs. Juventud<\/p>\n<p>Libres:Costa Brava<\/p>\n<h3>Fecha 9<\/h3>\n<p>Juventud VS. El Tim\u00f3n<\/p>\n<p>Trocha VS. Quilmes<\/p>\n<p>Mercedes VS. Estudiantes<\/p>\n<p>Pabellon Argentino VS. San Marcos<\/p>\n<p>Los Palometas VS. Ateneo<\/p>\n<p>El Front\u00f3n VS. Costa Brava<\/p>\n<p>V\u00e9lez Sarsfield Vs. Uni\u00f3n<\/p>\n<p>Libres: Comunicaciones.<\/p>\n<h3>Fecha 10<\/h3>\n<p>Comunicaciones VS. El Front\u00f3n<\/p>\n<p>Costa Brava VS. Los Palometas<\/p>\n<p>Ateneo VS. Pabellon Argentino<\/p>\n<p>San Marcos VS. Mercedes<\/p>\n<p>Estudiantes VS. Trocha<\/p>\n<p>Quilmes \u00a0VS. Juventud<\/p>\n<p>El Tim\u00f3n Vs. Uni\u00f3n<\/p>\n<p>Libres: V\u00e9lez<\/p>\n<h3>Fecha 11<\/h3>\n<p>V\u00e9lez Sarsfield\u00a0 VS. El Tim\u00f3n<\/p>\n<p>Juventud VS. Estudiantes<\/p>\n<p>Trocha VS. San Marcos<\/p>\n<p>Mercedes VS. Ateneo<\/p>\n<p>Pabellon Argentino VS. Costa Brava<\/p>\n<p>Los Palometas VS. Comunicaciones<\/p>\n<p>Uni\u00f3n Vs. Quilmes<\/p>\n<p>Libres: El Front\u00f3n<\/p>\n<h3>Fecha 12<\/h3>\n<p>El Front\u00f3n VS. V\u00e9lez Sarsfield<\/p>\n<p>Comunicaciones VS. Pabellon Argentino<\/p>\n<p>Costa Brava VS. Mercedes<\/p>\n<p>Ateneo VS. Trocha<\/p>\n<p>San Marcos VS. Juventud<\/p>\n<p>Quilmes VS. El Tim\u00f3n<\/p>\n<p>Estudiantes Vs. Uni\u00f3n<\/p>\n<p>Libres: Los Palometas.<\/p>\n<h3>Fecha 13<\/h3>\n<p>V\u00e9lez Sarsfield VS. Quilmes<\/p>\n<p>El Tim\u00f3n VS. Estudiantes<\/p>\n<p>Juventud VS. Ateneo<\/p>\n<p>Trocha VS. Costa Brava<\/p>\n<p>Mercedes VS. Comunicaciones<\/p>\n<p>Los Palometas VS. El Front\u00f3n<\/p>\n<p>Uni\u00f3n Vs. San Marcos<\/p>\n<p>Libres: Pabell\u00f3n Argentino<\/p>\n<h3>Fecha 14<\/h3>\n<p>Los Palometas VS. V\u00e9lez Sarsfield<\/p>\n<p>El Front\u00f3n VS. Pabellon Argentino<\/p>\n<p>Comunicaciones VS. Trocha<\/p>\n<p>Costa Brava VS. Juventud<\/p>\n<p>San Marcos VS. El Tim\u00f3n<\/p>\n<p>Estudiantes VS. Quilmes<\/p>\n<p>Ateneo Vs. Uni\u00f3n<\/p>\n<p>Libres: Mercedes.<\/p>\n<h3>Fecha 15<\/h3>\n<p>V\u00e9lez Sarsfield VS. Estudiantes<\/p>\n<p>Quilmes VS. San Marcos<\/p>\n<p>El Tim\u00f3n VS. Ateneo<\/p>\n<p>Juventud VS. Comunicaciones<\/p>\n<p>Mercedes VS. El Front\u00f3n<\/p>\n<p>Pabellon Argentino VS. Los Palometas<\/p>\n<p>Uni\u00f3n Vs. Costa Brava<\/p>\n<p>Libres: Trocha<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El certamen de Primera Divisi\u00f3n y Reserva dar\u00e1 inicio este s\u00e1bado con algunos partidos suspendidos por la participaci\u00f3n de Quilmes &#8230; <a title=\"Comienza el torneo Apertura de la Liga Mercedina\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2016\/03\/10\/comienza-el-torneo-apertura-de-la-liga-mercedina\/\" aria-label=\"Leer m\u00e1s sobre Comienza el torneo Apertura de la Liga Mercedina\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":47693,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[21],"tags":[8590,1901],"class_list":["post-47692","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","tag-fixture-liga-mercedina","tag-liga-mercedina","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/03\/fultbol.ligamercedina.jpg","wps_subtitle":"Con 15 fechas","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/47692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=47692"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/47692\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/47693"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=47692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=47692"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=47692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}