{"id":4798,"date":"2011-06-06T02:06:40","date_gmt":"2011-06-06T02:06:40","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=4798"},"modified":"2011-06-06T02:06:40","modified_gmt":"2011-06-06T02:06:40","slug":"un-radical-a-la-derecha","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2011\/06\/06\/un-radical-a-la-derecha\/","title":{"rendered":"Un radical a la derecha"},"content":{"rendered":"<p><strong><span style=\"color: #003366;\">Por Luciano Demergasso<br \/>\n<\/span><\/strong><span style=\"color: #000000;\">ldemer@educ.ar <\/span><\/p>\n<p>La Uni\u00f3n C\u00edvica Radical dio su m\u00e1ximo giro hist\u00f3rico a la derecha a partir de tres medias que unidas hacen una sola. Se distancia de los aliados hist\u00f3ricos socialistas y progresistas encarnados en Binner y Stolbizer. Se une al representante del espacio del campo y empresarial De Narv\u00e1ez y suma como candidato a vicepresidente al ex menemista, duhaldista y hombre puro del establishment Javier Gonz\u00e1lez Fraga.<\/p>\n<p>La clara apetencia de mostrarse distinto al gobierno y tras la ca\u00edda del Mauricio Macri de su intento presidencial llev\u00f3 a que Ricardo Alfons\u00edn torciera la mano a los opositores e indecisos internos y gestara la tan anunciada y a la vez sorpresiva alianza con el peronismo no oficialista. Es una alianza versi\u00f3n 2011 entre radicales y peronistas que no van desde puntos en comunes a favor de una mirada de sociedad sino s\u00f3lo en contra de alguien buscando sumar los votos de la derecha hu\u00e9rfana.<\/p>\n<p>Esta alianza que busca votos de abajo hacia arriba, es decir, que De Narv\u00e1ez le sume a Alfons\u00edn m\u00e1s que los que recibir\u00e1 el diputado m\u00e1s silencioso del recinto. Compararla, como dice Sebasti\u00e1n Varcel\u00f3 en su art\u00edculo semanal con la realizada en el 98 es un error. Aquella ten\u00eda un perfil absolutamente progresista en los papeles por m\u00e1s conservadora y asesina que haya terminado siendo. La actual es ya desde su base misma conservadora y posicionada en pro del mercado con lo cual el resultado es anunciado. Antes al menos la duda estaba, ahora, ni eso.<\/p>\n<p>El candidato a vicepresidente se opuso a la reestatizaci\u00f3n de las AFJP, se anuncia contrario a las retenciones, cuestiona los subsidios al consumo de gas, transporte y energ\u00eda y sostiene la necesidad de recuperar el empr\u00e9stito como fuente de financiamiento para reemplazar el dinero entrante a las arcas estatales v\u00eda impuesto a la renta extraordinaria de la exportaci\u00f3n de materia prima. En otras palabras lo contrario al Estado de Bienestar y acoplado al Estado en su faceta neoliberal.<\/p>\n<p>A todo esto Javier Torres, integrante de la UCR local, anuncia su benepl\u00e1cito al acuerdo. Sostiene que unos son de centro izquierda y los otros de centro derecha, pero pueden convivir. Se da el lujo de citar a  Lula como ejemplo de convivencia con la derecha tratando de gestar una de validaci\u00f3n a lo construido y anuncia que no existe un \u201cprogres\u00f3metro\u201d. Lamentablemente no es necesario tal instrumento pues basta con ver las medidas solicitadas hist\u00f3ricamente  tanto por De Narv\u00e1ez como por Fraga para sostener y afirmar que no est\u00e1n ni en la centro izquierda ni cerca del campo popular y si del campo en t\u00e9rminos de acumulaci\u00f3n de riquezas posados claramente en la derecha.<\/p>\n<p>Por mucho que les pese y quieran disimular la decisi\u00f3n tomada es puramente electoral, ajena a los patrones hist\u00f3ricos del partido y ejemplo de especulaci\u00f3n. No se unen en pos de algo sino en contra de un estado de situaci\u00f3n. En si no est\u00e1 mal estar en contra o cr\u00edticamente posados, sin embargo, cuando eso es la totalidad del asunto el resultado puede ser nefasto para la poblaci\u00f3n.<\/p>\n<p>Lo que se ve son acciones que no dejan de continuar con el camino de decadencia que ha iniciado en la \u00faltima d\u00e9cada el partido centenario.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Luciano Demergasso ldemer@educ.ar La Uni\u00f3n C\u00edvica Radical dio su m\u00e1ximo giro hist\u00f3rico a la derecha a partir de tres &#8230; <a title=\"Un radical a la derecha\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2011\/06\/06\/un-radical-a-la-derecha\/\" aria-label=\"Leer m\u00e1s sobre Un radical a la derecha\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-4798","post","type-post","status-publish","format-standard","hentry","category-opinion","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","wps_subtitle":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/4798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=4798"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/4798\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=4798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=4798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=4798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}