{"id":48374,"date":"2016-03-31T17:05:58","date_gmt":"2016-03-31T20:05:58","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=48374"},"modified":"2016-03-31T17:05:58","modified_gmt":"2016-03-31T20:05:58","slug":"denuncian-usurpaciones-en-terrenos-ferroviarios","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2016\/03\/31\/denuncian-usurpaciones-en-terrenos-ferroviarios\/","title":{"rendered":"Denuncian usurpaciones en terrenos ferroviarios"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"48381\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2016\/03\/31\/denuncian-usurpaciones-en-terrenos-ferroviarios\/31-terreno-la-colina-1\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/03\/31-terreno-La-Colina-1.jpg\" data-orig-size=\"448,336\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"31 terreno La Colina 1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/03\/31-terreno-La-Colina-1.jpg\" class=\"aligncenter size-full wp-image-48381\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/03\/31-terreno-La-Colina-1.jpg\" alt=\"31 terreno La Colina 1\" width=\"448\" height=\"336\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/03\/31-terreno-La-Colina-1.jpg 448w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/03\/31-terreno-La-Colina-1-150x113.jpg 150w\" sizes=\"auto, (max-width: 448px) 100vw, 448px\" \/>Vecinos del Barrio La Colina denunciaron que un sector del barrio, m\u00e1s espec\u00edficamente, un tri\u00e1ngulo correspondiente a los terrenos del Ferrocarril Sarmientos, un grupo de vecinos habr\u00edan comenzado a limpiar los terrenos y en algunos casos hasta se inici\u00f3 una construcci\u00f3n de cemento incluyendo el pilar para la bajada de luz.<\/p>\n<p>El lugar que estar\u00edan apropiando es en la calle 110 y 61 bis sobre calle 110, donde forma un tri\u00e1ngulo con las v\u00edas. Incluso, uno de los \u00abocupas\u00bb advierte con un cartel destacando que es de su propiedad y proh\u00edbe el paso, mientras otro habr\u00eda utilizado veh\u00edculos municipales para limpiar el terreno de acacios negros, e incluso en la ocupaci\u00f3n de los terrenos ferroviarios estar\u00eda involucrado un alba\u00f1il que vive cerca. Lo llamativo es que las personas que estar\u00edan ocupando estos terrenos, son vecinos de barrios linderos a La Colina que tienen sus propias casas.<\/p>\n<p>Alertados, un grupo de vecinos dio conocimiento a funcionarios nacionales responsables del \u00e1rea de ferrocarriles as\u00ed como a concejales de la ciudad mostrando fotos del lugar. Esperan respuestas.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"48377\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2016\/03\/31\/denuncian-usurpaciones-en-terrenos-ferroviarios\/31-terreno-la-colina-3\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/03\/31-terreno-La-Colina-3.jpg\" data-orig-size=\"448,336\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"31 terreno La Colina 3\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/03\/31-terreno-La-Colina-3.jpg\" class=\"aligncenter size-full wp-image-48377\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/03\/31-terreno-La-Colina-3.jpg\" alt=\"31 terreno La Colina 3\" width=\"448\" height=\"336\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/03\/31-terreno-La-Colina-3.jpg 448w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/03\/31-terreno-La-Colina-3-150x113.jpg 150w\" sizes=\"auto, (max-width: 448px) 100vw, 448px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vecinos del Barrio La Colina denunciaron que un sector del barrio, m\u00e1s espec\u00edficamente, un tri\u00e1ngulo correspondiente a los terrenos del &#8230; <a title=\"Denuncian usurpaciones en terrenos ferroviarios\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2016\/03\/31\/denuncian-usurpaciones-en-terrenos-ferroviarios\/\" aria-label=\"Leer m\u00e1s sobre Denuncian usurpaciones en terrenos ferroviarios\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":48382,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[8],"tags":[8850,7033,8852,8853,8851],"class_list":["post-48374","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociedad","tag-barrio-la-colina","tag-denuncia","tag-ocupas","tag-terrenos-ferroviarios","tag-usurpaciones","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/03\/31-terreno-La-Colina-2.jpg","wps_subtitle":"Barrio La Colina","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/48374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=48374"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/48374\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/48382"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=48374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=48374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=48374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}