{"id":49925,"date":"2016-05-14T10:08:38","date_gmt":"2016-05-14T13:08:38","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=49925"},"modified":"2016-05-14T10:08:38","modified_gmt":"2016-05-14T13:08:38","slug":"el-colegio-de-abogados-eligio-nuevos-miembros-en-su-consejo-directivo","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2016\/05\/14\/el-colegio-de-abogados-eligio-nuevos-miembros-en-su-consejo-directivo\/","title":{"rendered":"El Colegio de Abogados eligi\u00f3 nuevos miembros en su Consejo Directivo"},"content":{"rendered":"<p>En la jornada del viernes 13 de mayo, el Colegio de Abogados del Departamento Judicial Mercedes tuvo sus elecciones de autoridades.para cambiar la mitad de su Consejo Directivo. Una sola lista fue la presentada y oficializada, no obstante, en todo el departamento judicial fue importante la cantidad de abogados que se acercaron a las mesas de votaciones.<\/p>\n<p>&nbsp;<\/p>\n<p>La lista oficializada y que se suma al Consejo est\u00e1 integrada por los doctores Lucas G\u00f3mez, Daniel Giuliano, Jorge Ludovico, Gustavo Giampieri, Jorge Caramanico, y Mar\u00eda Bernarda Ormaechea.<\/p>\n<p>Entre los Consejeros Suplentes por cuatro a\u00f1os est\u00e1n los doctores Pablo Guidi, Javier Menay, Pedro Cattaneo y Felipe Sario.<\/p>\n<p>En tanto, para el Tribunal de Disciplina, los nuevo miembros titulares son los doctores Atilio Rossello, Isolina Tezano y Sebasti\u00e1n Ricca. Mientras que los miembros suplentes son los doctores Jorge Juancorena y Laura Cusin. Miembro suplente por dos a\u00f1os es la doctora Mariela Demarco.<\/p>\n<p>Para la Caja de Previsi\u00f3n Social\u00a0el Director Titular por cuatro a\u00f1os ser\u00e1 nuevamente el doctor Ariel Fusco, mientras que el suplente ser\u00e1 el doctor Fernando Florella. En tanto, como Revisor de Cuentas Titular por cuatro a\u00f1os qued\u00f3 el doctor Hern\u00e1n Salaverri y como suplente el doctor Luis Mar\u00eda Laborde.<\/p>\n<p>Cabe destacar que la Presidencia, actualmente a cargo del doctor Mateo Laborde, se mantiene por dos a\u00f1os m\u00e1s.<\/p>\n<p>&nbsp;<\/p>\n<p>Fuente: CADJM<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la jornada del viernes 13 de mayo, el Colegio de Abogados del Departamento Judicial Mercedes tuvo sus elecciones de &#8230; <a title=\"El Colegio de Abogados eligi\u00f3 nuevos miembros en su Consejo Directivo\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2016\/05\/14\/el-colegio-de-abogados-eligio-nuevos-miembros-en-su-consejo-directivo\/\" aria-label=\"Leer m\u00e1s sobre El Colegio de Abogados eligi\u00f3 nuevos miembros en su Consejo Directivo\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[11],"tags":[928,9142],"class_list":["post-49925","post","type-post","status-publish","format-standard","hentry","category-ciudad","tag-colegio-de-abogados","tag-elecciones","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"wps_subtitle":"","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/49925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=49925"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/49925\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=49925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=49925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=49925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}