{"id":51280,"date":"2016-06-14T16:44:04","date_gmt":"2016-06-14T19:44:04","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=51280"},"modified":"2016-06-21T15:02:33","modified_gmt":"2016-06-21T18:02:33","slug":"comunicado-del-arzobispado-mercedes-lujan","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2016\/06\/14\/comunicado-del-arzobispado-mercedes-lujan\/","title":{"rendered":"Monasterio de F\u00e1tima: Comunicado del Arzobispado Mercedes &#8211; Luj\u00e1n"},"content":{"rendered":"<p>A trav\u00e9s de una comunicaci\u00f3n enviada a los medios y firmado por\u00a0Monse\u00f1or Agust\u00edn Radrizzani,\u00a0Arzobispo de Mercedes &#8211; Luj\u00e1n, la Arquidi\u00f3scesis\u00a0expresa:<\/p>\n<p>\u00abAnte los acontecimientos sucedidos en el d\u00eda de la fecha\u00a0en el Monasterio de Nuestra Se\u00f1ora del Rosario de F\u00e1tima en General Rodr\u00edguez, queremos manifestar nuestra perplejidad y sorpresa ante esta situaci\u00f3n.<\/p>\n<p>Informamos a la opini\u00f3n p\u00fablica que la comunidad conocida como \u201cMonjas Misioneras Orantes y Penitentes de Ntra. del Rosario\u201d es, en realidad, una asociaci\u00f3n privada de fieles que se rige de acuerdo a los c\u00e1nones 321-326 del C\u00f3digo de Derecho Can\u00f3nico y que ha permanecido bajo la autoridad de su fundador, Mons. Rub\u00e9n Di Monte, recientemente fallecido.<\/p>\n<p>Deseamos que la Justicia pueda actuar con plena libertad para llegar a la verdad de lo acontecido y manifestamos nuestra disponibilidad a colaborar con lo que ella requiera\u00bb<\/p>\n<p>.\u00bb<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A trav\u00e9s de una comunicaci\u00f3n enviada a los medios y firmado por\u00a0Monse\u00f1or Agust\u00edn Radrizzani,\u00a0Arzobispo de Mercedes &#8211; Luj\u00e1n, la Arquidi\u00f3scesis\u00a0expresa: &#8230; <a title=\"Monasterio de F\u00e1tima: Comunicado del Arzobispado Mercedes &#8211; Luj\u00e1n\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2016\/06\/14\/comunicado-del-arzobispado-mercedes-lujan\/\" aria-label=\"Leer m\u00e1s sobre Monasterio de F\u00e1tima: Comunicado del Arzobispado Mercedes &#8211; Luj\u00e1n\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[8],"tags":[9482,9483,8312,290],"class_list":["post-51280","post","type-post","status-publish","format-standard","hentry","category-sociedad","tag-arzobispo","tag-di-monte","tag-lopez","tag-radrizzani","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","wps_subtitle":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/51280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=51280"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/51280\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=51280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=51280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=51280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}